{"id":122747,"date":"2020-11-24T08:35:10","date_gmt":"2020-11-24T11:35:10","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=122747"},"modified":"2020-11-24T16:21:10","modified_gmt":"2020-11-24T19:21:10","slug":"la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/","title":{"rendered":"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto"},"content":{"rendered":"<h3>Por Norberto G. Asquini<\/h3>\n<p><strong>Dispersos en sus adhesiones pol\u00edticas, pero unidos con la camiseta celeste.<\/strong> Ese es el panorama de la pol\u00edtica del sector<strong> evang\u00e9lico en La Pampa<\/strong>, en el que encontramos distintos grupos protestantes, pentecostales y pospentecostales, si bien las dos \u00faltimos son los m\u00e1s activos en la arena p\u00fablica.<\/p>\n<p>En las \u00faltimas semanas <strong>los evang\u00e9licos comenzaron a movilizarse nuevamente en oposici\u00f3n del proyecto del gobierno nacional para legalizar el aborto que ingres\u00f3 al Congreso<\/strong>. En eso <strong>hay unanimidad<\/strong>.<\/p>\n<p>Donde el bloque se fragmenta y pierde peso espec\u00edfico es cuando se habla de pol\u00edtica. Si bien los medios pampeanos dieron a conocer este a\u00f1o que una de las expresiones pol\u00edticas actuales de los evang\u00e9licos es <strong>UNO (Una Nueva Oportunidad)<\/strong> con pastores de nueve provincias y vinculado a Cambiemos, tambi\u00e9n tenemos a otros partidos de ra\u00edz confesional en marcha. Por mencionar, est\u00e1n<strong> Valores para mi Pa\u00eds<\/strong> y <strong>Gobernar Bien<\/strong>, al que parece acercarse el pampeano <strong>Pueblo Nuevo<\/strong>. Desde la Alianza Cristina de Iglesias Evang\u00e9licas de la Rep\u00fablica Argentina (ACIERA), su presidente Rub\u00e9n Proietti, aclar\u00f3 que son varias las expresiones pol\u00edtico partidarias dentro del sector. Aciera ha tendido a proponer una posici\u00f3n pol\u00edtica apartidaria.<\/p>\n<p>En La Pampa, como reflejo de lo que ocurri\u00f3 en el pa\u00eds, <strong>los evang\u00e9licos se convirtieron en un actor pol\u00edtico en los \u00faltimos a\u00f1os<\/strong>. El n\u00famero de iglesias evang\u00e9licas ha ido en aumento: creci\u00f3 un 18% en diez a\u00f1os, pasando de 241 en 2011 a 284 en 2020, seg\u00fan el Registro Nacional de Cultos. Varias con redes en muchos lugares de la provincia: la Iglesia Evang\u00e9lica Pentecostal Argentina tiene 22 filiares repartidas en el territorio provincial, la Asociaci\u00f3n Evang\u00e9lica Asamblea de Dios 18; la Iglesia Biblia Abierta Misi\u00f3n Sudamericana 18; la Uni\u00f3n de las Asambleas de Dios 18; la Federaci\u00f3n Asamblea Cristiana 15; y la Asociaci\u00f3n de los Testigos de Jehova 14, por nombrar las m\u00e1s populosas.<\/p>\n<p><strong>Qu\u00e9 pasa en La Pampa<\/strong><\/p>\n<p>El despliegue p\u00fablico de las iglesias evang\u00e9licas, mayormente pentecostales, se observ\u00f3 en la pol\u00edtica directa en las manifestaciones en contra de proyectos de ley que ampl\u00eden derechos en materia de g\u00e9nero, como la Ley de Educaci\u00f3n Sexual Integral (ESI), el matrimonio igualitario o el debate por la legalizaci\u00f3n del aborto. En estos temas <strong>han establecido alianzas con sectores cat\u00f3licos<\/strong>. Esto visibiliz\u00f3 fuertemente su presencia como sector social con<strong> capacidad de presi\u00f3n<\/strong> en las calles.<\/p>\n<p>Hay un peso creciente de los evang\u00e9licos en la pol\u00edtica argentina, aunque sus intentos partidarios-confesionales se han visto frustrados. En nuestra provincia, por ejemplo, luego de la movilizaci\u00f3n de 2018 el \u201cvoto celeste\u201d trat\u00f3 de ser capitalizado por el partido evang\u00e9lico Pueblo Nuevo y el derechista Comunidad Organizada. Ambos hicieron campa\u00f1a expl\u00edcita contra el \u201cverde\u201d Frejupa, cuyos legisladores hab\u00edan apoyado la ley de despenalizaci\u00f3n del aborto que finalmente no sali\u00f3. De hecho,<strong> en varios sectores de la oposici\u00f3n el an\u00e1lisis electoral pas\u00f3 por tratar de incluir alg\u00fan sector evang\u00e9lico, porque consideraban que eran votos cautivos de los pastores. Pero en las elecciones de 2019 los n\u00fameros mostraron que el electorado le dio la espalda a estas opciones partidarias<\/strong>. De hecho, se vot\u00f3 al Frejupa con la misma o m\u00e1s intensidad que en otras elecciones, en los tres comicios de 2019 tanto provinciales como nacionales. Y as\u00ed como el ex concejal santarrose\u00f1o Roberto Torres pas\u00f3 a Juntos por el Cambio, y luego a UNO; el ex diputado Daniel Robledo se alej\u00f3 de su alianza con el PJ para presentarse con Pueblo Nuevo y se lo ha visto este a\u00f1o cerca de Gobernar Bien; en el gobierno provincial contin\u00faa Ram\u00f3n G\u00f3mez como subsecretario de Culto.<\/p>\n<p><strong>Meterse en pol\u00edtica<\/strong><\/p>\n<p>La soci\u00f3loga Mar\u00eda Pilar Garc\u00eda Bossio indica que hay una intenci\u00f3n mayor que en el pasado de \u201cmeterse en pol\u00edtica\u201d o a manifestarse p\u00fablicamente para defender posiciones, pero esto no quiere decir que sus fieles act\u00faen de forma monol\u00edtica en t\u00e9rminos de participaci\u00f3n pol\u00edtica, ni que se pueda identificar a las iglesias pentecostales con una \u00fanica opci\u00f3n partidaria.<\/p>\n<p>El antrop\u00f3logo y soci\u00f3logo Pablo Sem\u00e1n completa: \u201cEs imposible afirmar la existencia de un voto confesional en el caso de los evang\u00e9licos. No solo se trata de que la identidad religiosa no genere autom\u00e1ticamente una identidad pol\u00edtica. El hecho de que no haya instancias de unificaci\u00f3n institucional y la propia din\u00e1mica de los grupos evang\u00e9licos, competitiva y sometida a m\u00faltiples posibilidades de fraccionamiento, hacen que algunos emprendimientos pol\u00edticos que apelan a la identidad religiosa tengan efectos muy distantes del buscado\u201d.<\/p>\n<p><strong>Por ahora, el celeste moviliza, pero hasta por ah\u00ed nom\u00e1s.<\/strong> En La Pampa no hay lugar para partidos confesionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Norberto G. Asquini Dispersos en sus adhesiones pol\u00edticas, pero unidos con la camiseta celeste. Ese es el panorama de la pol\u00edtica del sector evang\u00e9lico en La Pampa, en el&hellip;<\/p>\n","protected":false},"author":3,"featured_media":122560,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[319,12],"tags":[2976],"class_list":["post-122747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-temporales","category-sociedad","tag-evangelicos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Por Norberto G. Asquini Dispersos en sus adhesiones pol\u00edticas, pero unidos con la camiseta celeste. Ese es el panorama de la pol\u00edtica del sector evang\u00e9lico en La Pampa, en el&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-24T11:35:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-24T19:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/11\/abortocelestestelam334.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1004\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto\",\"datePublished\":\"2020-11-24T11:35:10+00:00\",\"dateModified\":\"2020-11-24T19:21:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/\"},\"wordCount\":842,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/abortocelestestelam334.jpg\",\"keywords\":[\"evangelicos\"],\"articleSection\":[\"A - TEMPORALES\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/\",\"name\":\"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/abortocelestestelam334.jpg\",\"datePublished\":\"2020-11-24T11:35:10+00:00\",\"dateModified\":\"2020-11-24T19:21:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/abortocelestestelam334.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/abortocelestestelam334.jpg\",\"width\":1004,\"height\":565},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/11\\\/24\\\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/","og_locale":"es_ES","og_type":"article","og_title":"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto - Diario Textual","og_description":"Por Norberto G. Asquini Dispersos en sus adhesiones pol\u00edticas, pero unidos con la camiseta celeste. Ese es el panorama de la pol\u00edtica del sector evang\u00e9lico en La Pampa, en el&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2020-11-24T11:35:10+00:00","article_modified_time":"2020-11-24T19:21:10+00:00","og_image":[{"width":1004,"height":565,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/11\/abortocelestestelam334.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto","datePublished":"2020-11-24T11:35:10+00:00","dateModified":"2020-11-24T19:21:10+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/"},"wordCount":842,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/11\/abortocelestestelam334.jpg","keywords":["evangelicos"],"articleSection":["A - TEMPORALES","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/","name":"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/11\/abortocelestestelam334.jpg","datePublished":"2020-11-24T11:35:10+00:00","dateModified":"2020-11-24T19:21:10+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/11\/abortocelestestelam334.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/11\/abortocelestestelam334.jpg","width":1004,"height":565},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/11\/24\/la-politica-evangelica-dispersos-en-lo-partidario-unidos-en-el-antiaborto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La pol\u00edtica evang\u00e9lica: dispersos en lo partidario, unidos en el antiaborto"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/122747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=122747"}],"version-history":[{"count":3,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/122747\/revisions"}],"predecessor-version":[{"id":122757,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/122747\/revisions\/122757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/122560"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=122747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=122747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=122747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}