{"id":138186,"date":"2021-03-18T14:41:36","date_gmt":"2021-03-18T17:41:36","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=138186"},"modified":"2021-03-19T09:57:02","modified_gmt":"2021-03-19T12:57:02","slug":"la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/","title":{"rendered":"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres"},"content":{"rendered":"\n<p>El secretario de Recursos H\u00eddricos, N\u00e9stor Lastiri, present\u00f3 ante el Ministerio P\u00fablico Fiscal de Victorica <strong>una denuncia penal contra un productor rural de la zona de La Humada, luego de que se constataran alteraciones en el manantial de Agua de Torres<\/strong>, que suministra agua a la poblaci\u00f3n de La Humada. &nbsp;<\/p>\n\n\n\n<p>Integrantes de la Secretar\u00eda inspecci\u00f3n en el manantial con el fin de constatar una serie de intervenciones e irregularidades que alteran el curso de agua y afectan el suministro de agua a la poblaci\u00f3n de La Humada.<\/p>\n\n\n\n<p>Concurrieron el ingeniero Juan Greco, la Asesora Letrada, Luisina Grand\u00f3n, y la secretaria privada Florencia Gonzalez Leyton, junto al intendente de La Humada, Leonardo Oscar Pereyra; las concejalas Carina Centeno y Felipa Lucero, el titular del CD, Jorge Lucero; Carlos Cerant , jefe de Acueducto Oeste en representaci\u00f3n de Aguas del Colorado; y la jueza Regional de Faltas, Mar\u00eda Natalia Sequeira.<\/p>\n\n\n\n<p>All\u00ed, la Secretar\u00eda constat\u00f3 que<strong> due\u00f1os de campos particulares efectuaron desv\u00edos y alteraciones en el curso del agua<\/strong>, mediante la colocaci\u00f3n de tierra en el margen izquierdo del nacimiento del manantial a lo largo de 250 metros por 2,5 metros de altura, y tambi\u00e9n en otras zonas con una longitud de 150 metros por 3,10 metros de alto, alterando el normal cauce del manantial.&nbsp;<\/p>\n\n\n\n<p>Por otro lado se pudieron confirmar indicios de <strong>la misma acci\u00f3n pero sobre el margen derecho del manantial.<\/strong><\/p>\n\n\n\n<p>Tambi\u00e9n se observ\u00f3 la presencia de animales vacunos sobre el recurso, alterando org\u00e1nicamente la superficie de la fuente y <strong>generando as\u00ed un alto grado de contaminaci\u00f3n.<\/strong> Adem\u00e1s se visualiz\u00f3 la colocaci\u00f3n de nuevos alambrados en zonas fuera de las establecidas y la alteraci\u00f3n de la escala de medici\u00f3n de calidad y cantidad de agua.&nbsp;<\/p>\n\n\n\n<p>Luego de la inspecci\u00f3n realizada, la Secretar\u00eda de Recursos H\u00eddricos, como autoridad de aplicaci\u00f3n del C\u00f3digo Provincial de Aguas y en su deber de conservaci\u00f3n y protecci\u00f3n de los recursos h\u00eddricos provinciales, labr\u00f3 un acta dejando constancia de lo actuado. <\/p>\n\n\n\n<p>La Secretar\u00eda <strong>repudi\u00f3 estas actividades irregulares y solicit\u00f3 el cese inmediato de las mismas&nbsp;<\/strong> teniendo en cuenta la importancia del recurso h\u00eddrico como prioridad de uso especial -consumo humano y dom\u00e9stico- conforme el art\u00edculo 67 inciso 1\u00b0 de la Ley 2581\/10.<\/p>\n\n\n\n<p>Asimismo la jueza Regional de Faltas, Mar\u00eda Natalia Sequeira, resolvi\u00f3 ordenar \u201cla prohibici\u00f3n inmediata de efectuar trabajos, movimientos y cualquier otra obra sobre los m\u00e1rgenes del manantial Agua de Torres\u201d, de acuerdo a lo establecido por el art\u00edculo 3 del C\u00f3digo de Aguas y art\u00edculo 72 del C\u00f3digo Municipal de Faltas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Recursos H\u00eddricos, N\u00e9stor Lastiri, present\u00f3 ante el Ministerio P\u00fablico Fiscal de Victorica una denuncia penal contra un productor rural de la zona de La Humada, luego de&hellip;<\/p>\n","protected":false},"author":4,"featured_media":138187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,12],"tags":[],"class_list":["post-138186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Humada: denuncian a un productor por alterar el manantial de Agua de Torres - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El secretario de Recursos H\u00eddricos, N\u00e9stor Lastiri, present\u00f3 ante el Ministerio P\u00fablico Fiscal de Victorica una denuncia penal contra un productor rural de la zona de La Humada, luego de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-18T17:41:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-19T12:57:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/03\/manantialaguadetorres33.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/\"},\"author\":{\"name\":\"diario2\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\"},\"headline\":\"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres\",\"datePublished\":\"2021-03-18T17:41:36+00:00\",\"dateModified\":\"2021-03-19T12:57:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/\"},\"wordCount\":466,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/manantialaguadetorres33.jpg\",\"articleSection\":[\"A - QUE PASA (al costado)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/\",\"name\":\"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/manantialaguadetorres33.jpg\",\"datePublished\":\"2021-03-18T17:41:36+00:00\",\"dateModified\":\"2021-03-19T12:57:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/manantialaguadetorres33.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/manantialaguadetorres33.jpg\",\"width\":900,\"height\":507},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/03\\\/18\\\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\",\"name\":\"diario2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"caption\":\"diario2\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/","og_locale":"es_ES","og_type":"article","og_title":"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres - Diario Textual","og_description":"El secretario de Recursos H\u00eddricos, N\u00e9stor Lastiri, present\u00f3 ante el Ministerio P\u00fablico Fiscal de Victorica una denuncia penal contra un productor rural de la zona de La Humada, luego de&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2021-03-18T17:41:36+00:00","article_modified_time":"2021-03-19T12:57:02+00:00","og_image":[{"width":900,"height":507,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/03\/manantialaguadetorres33.jpg","type":"image\/jpeg"}],"author":"diario2","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario2","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/"},"author":{"name":"diario2","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768"},"headline":"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres","datePublished":"2021-03-18T17:41:36+00:00","dateModified":"2021-03-19T12:57:02+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/"},"wordCount":466,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/03\/manantialaguadetorres33.jpg","articleSection":["A - QUE PASA (al costado)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/","name":"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/03\/manantialaguadetorres33.jpg","datePublished":"2021-03-18T17:41:36+00:00","dateModified":"2021-03-19T12:57:02+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/03\/manantialaguadetorres33.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/03\/manantialaguadetorres33.jpg","width":900,"height":507},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/03\/18\/la-humada-denuncian-a-productor-por-alterar-manantial-de-agua-de-torres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La Humada: denuncian a un productor por alterar el manantial de Agua de Torres"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768","name":"diario2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","caption":"diario2"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario2\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/138186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=138186"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/138186\/revisions"}],"predecessor-version":[{"id":138220,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/138186\/revisions\/138220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/138187"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=138186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=138186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=138186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}