{"id":141603,"date":"2021-04-16T08:32:30","date_gmt":"2021-04-16T11:32:30","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=141603"},"modified":"2021-04-16T08:36:10","modified_gmt":"2021-04-16T11:36:10","slug":"la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/","title":{"rendered":"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo"},"content":{"rendered":"\n<p>La banda del <strong>Indio Solari, \u201cLos Fundamentalistas del Aire Acondicionado\u201d<\/strong> dio a conocer a trav\u00e9s de las redes las recomendaciones para su pr\u00f3ximo show del 17 de abril.<br><br>El recital, que ser\u00e1 v\u00eda streaming desde la ciudad de Epecu\u00e9n, en la provincia de Buenos Aires, no ser\u00e1 transmitido en directo y por eso los organizadores pidieron a los simpatizantes no vayan a la ciudad.<br><br><strong>\u201cProvocar un evento que podr\u00eda convertirse en masivo, va en contra de la idea misma de esta convocatoria\u201d,<\/strong> asegur\u00f3 la banda.<\/p>\n\n\n\n<p>Indicaron tambi\u00e9n que el recital podr\u00e1 verse desde el exterior y tambi\u00e9n en diferido, durante las 12 horas posteriores al mismo.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">Comparto esta info de <a href=\"https:\/\/twitter.com\/LosFundaok?ref_src=twsrc%5Etfw\">@LosFundaok<\/a> <br><br>Prueba de luces y sonido. <a href=\"https:\/\/twitter.com\/hashtag\/ALosP%C3%A1jaros?src=hash&amp;ref_src=twsrc%5Etfw\">#ALosP\u00e1jaros<\/a>. <br><br>Entradas a la venta por <a href=\"https:\/\/twitter.com\/TicketekAr?ref_src=twsrc%5Etfw\">@ticketekar<\/a> -Capacidad limitada-<br><br>Hola a tod@s. Algunas aclaraciones en relaci\u00f3n al show. <a href=\"https:\/\/t.co\/90dLyxBeZe\">pic.twitter.com\/90dLyxBeZe<\/a><\/p>&mdash; Indio Solari Oficial (@Indio_Solari_ok) <a href=\"https:\/\/twitter.com\/Indio_Solari_ok\/status\/1382415618914316293?ref_src=twsrc%5Etfw\">April 14, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p><br>El grupo, integrado por Gaspar Benegas y Baltasar Comotto, en guitarras y voces; Pablo Sbaraglia, en teclados, guitarra y voz; Fernando Nal\u00e9, en bajo y voz; Deborah Dixon y Luciana Palacios, en coros; Sergio Colombo, en saxo y voz; Miguel \u00c1ngel Tallarita, en trompeta; y Ramiro L\u00f3pez Naguil, en bater\u00eda,\u00a0pidi\u00f3 a sus simpatizantes disfrutar del show en sus casas y continuar con los cuidados sanitarios frente al recrudecimiento de los casos de coronavirus.<br><br><strong>\u201cLas cosas no est\u00e1n f\u00e1ciles. C\u00f3mo siempre, cuid\u00e9monos entre todos\u201d,<\/strong> pidieron desde un hilo de Twitter, que fue compartido tambi\u00e9n desde la cuenta oficial del Indio Solari.<br><br>\u201cA los p\u00e1jaros\u201d es el t\u00edtulo del nuevo espect\u00e1culo que podr\u00e1 verse ese d\u00eda desde las 21 por la plataforma\u00a0<a href=\"http:\/\/ticketek%20live\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ticketek Live<\/a>\u00a0y que suceder\u00e1 a \u201cDesde los sat\u00e9lites\u201d, el concierto presentado en septiembre pasado desde el estadio Malvinas Argentinas, en donde se grab\u00f3 un disco en vivo de pr\u00f3xima edici\u00f3n.<br><br>Se trata del segundo recital que la banda hace bajo el formato streaming desde que comenz\u00f3 la pandemia.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">Siete d\u00edas <br>A los p\u00e1jaros<br>S\u00e1bado 17 de abril 21 hs<br><br>Entradas a la venta en <a href=\"https:\/\/twitter.com\/TicketekAr?ref_src=twsrc%5Etfw\">@TicketekAr<\/a> <a href=\"https:\/\/twitter.com\/LosFundaok?ref_src=twsrc%5Etfw\">@LosFundaok<\/a> <a href=\"https:\/\/t.co\/uAH7Ar8dzd\">pic.twitter.com\/uAH7Ar8dzd<\/a><\/p>&mdash; Indio Solari Oficial (@Indio_Solari_ok) <a href=\"https:\/\/twitter.com\/Indio_Solari_ok\/status\/1381311239742238728?ref_src=twsrc%5Etfw\">April 11, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n","protected":false},"excerpt":{"rendered":"<p>La banda del Indio Solari, \u201cLos Fundamentalistas del Aire Acondicionado\u201d dio a conocer a trav\u00e9s de las redes las recomendaciones para su pr\u00f3ximo show del 17 de abril. El recital,&hellip;<\/p>\n","protected":false},"author":4,"featured_media":141605,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[5063],"class_list":["post-141603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad","tag-indio-solari"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"La banda del Indio Solari, \u201cLos Fundamentalistas del Aire Acondicionado\u201d dio a conocer a trav\u00e9s de las redes las recomendaciones para su pr\u00f3ximo show del 17 de abril. El recital,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-16T11:32:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-16T11:36:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/04\/indiosolariylosfundamentalistas2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"935\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/\"},\"author\":{\"name\":\"diario2\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\"},\"headline\":\"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo\",\"datePublished\":\"2021-04-16T11:32:30+00:00\",\"dateModified\":\"2021-04-16T11:36:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/\"},\"wordCount\":390,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/indiosolariylosfundamentalistas2.jpg\",\"keywords\":[\"indio solari\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/\",\"name\":\"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/indiosolariylosfundamentalistas2.jpg\",\"datePublished\":\"2021-04-16T11:32:30+00:00\",\"dateModified\":\"2021-04-16T11:36:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/indiosolariylosfundamentalistas2.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/indiosolariylosfundamentalistas2.jpg\",\"width\":935,\"height\":522},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/04\\\/16\\\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\",\"name\":\"diario2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"caption\":\"diario2\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/","og_locale":"es_ES","og_type":"article","og_title":"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo - Diario Textual","og_description":"La banda del Indio Solari, \u201cLos Fundamentalistas del Aire Acondicionado\u201d dio a conocer a trav\u00e9s de las redes las recomendaciones para su pr\u00f3ximo show del 17 de abril. El recital,&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2021-04-16T11:32:30+00:00","article_modified_time":"2021-04-16T11:36:10+00:00","og_image":[{"width":935,"height":522,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/04\/indiosolariylosfundamentalistas2.jpg","type":"image\/jpeg"}],"author":"diario2","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario2","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/"},"author":{"name":"diario2","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768"},"headline":"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo","datePublished":"2021-04-16T11:32:30+00:00","dateModified":"2021-04-16T11:36:10+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/"},"wordCount":390,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/04\/indiosolariylosfundamentalistas2.jpg","keywords":["indio solari"],"articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/","name":"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/04\/indiosolariylosfundamentalistas2.jpg","datePublished":"2021-04-16T11:32:30+00:00","dateModified":"2021-04-16T11:36:10+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/04\/indiosolariylosfundamentalistas2.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/04\/indiosolariylosfundamentalistas2.jpg","width":935,"height":522},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/04\/16\/la-banda-del-indio-pidio-a-los-fans-que-no-vayan-a-epecuen-porque-el-show-no-sera-en-directo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La banda del Indio pidi\u00f3 a los fans que no vayan a Epecu\u00e9n porque el show no ser\u00e1 en directo"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768","name":"diario2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","caption":"diario2"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario2\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/141603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=141603"}],"version-history":[{"count":4,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/141603\/revisions"}],"predecessor-version":[{"id":141610,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/141603\/revisions\/141610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/141605"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=141603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=141603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=141603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}