{"id":165299,"date":"2021-10-15T13:16:29","date_gmt":"2021-10-15T16:16:29","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=165299"},"modified":"2021-10-15T13:16:32","modified_gmt":"2021-10-15T16:16:32","slug":"la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/","title":{"rendered":"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo"},"content":{"rendered":"\n<p>El proyecto social, cultural y educativo de la <strong>Biblioteca Digital Pampeana <\/strong>fue declarado este jueves de inter\u00e9s legislativo por la C\u00e1mara de Diputados de la Provincia.<\/p>\n\n\n\n<p>Se trata de una iniciativa de promoci\u00f3n de la lectura y difusi\u00f3n de obras literarias de la provincia de La Pampa; que surge de quienes conforman la Biblioteca Popular Miguel \u00c1ngel G\u00f3mez Drumell que se encuentra en la Comisi\u00f3n Vecinal del barrio de Villa Elisa, en Santa Rosa.<\/p>\n\n\n\n<p>La actividad de la Biblioteca se financia con el aporte de cofundadores como Conabip, el Fondo Nacional de Las Artes, la Secretar\u00eda de Mujeres, G\u00e9neros y Disidencias de La Pampa, Secretaria de Cultura y Educaci\u00f3n y concejo deliberante de Santa Rosa,&nbsp; Liliana Robledo, Graciela B\u00e1ez, Diana Rodr\u00edguez Palchevich, los diputados Mar\u00edn Balsa, Oscar Zanoli y Leonardo Avenda\u00f1o y la C\u00e1mara de Diputados de La Provincia de La Pampa y el acompa\u00f1amiento de Radio Kerm\u00e9s.<\/p>\n\n\n\n<p>La <a href=\"https:\/\/www.facebook.com\/bibliotecadigitalpampeana\" target=\"_blank\" rel=\"noreferrer noopener\">Biblioteca Digital Pampeana<\/a> es un espacio de difusi\u00f3n de la cultura pampeana que adapt\u00f3 su oferta al contexto de pandemia e inclinaci\u00f3n hacia la virtualidad con su formato digital, lo que permiti\u00f3 una m\u00e1s \u00e1gil comunicaci\u00f3n con sus asociados y seguidores.<\/p>\n\n\n\n<p>La <strong>presentaci\u00f3n de esta biblioteca se realiza una vez por mes en instituciones de Santa Rosa como escuelas, comisiones vecinales y centros de jubilados. En cada uno de estos encuentros est\u00e1 prevista la presentaci\u00f3n de un libro de autor\u00eda pampeana.<\/strong><\/p>\n\n\n\n<p>La publicidad de las obras de autoras y autores pampeanos es realizada por un community manager para Facebook, Instagram; un social media manager para la creaci\u00f3n de contenidos, y una dise\u00f1adora de publicidad multiformato para web y en televisi\u00f3n. Se financia por el aporte de los cofundadores y cofundadoras de la Biblioteca Digital.<\/p>\n\n\n\n<p>La Biblioteca Digital Pampeana tiene un formato \u00fanico ya que est\u00e1 acompa\u00f1ada con un plan de marketing para que los autores y autoras tengan publicidad y difusi\u00f3n de obras de calidad.<\/p>\n\n\n\n<p><strong>Es una realizaci\u00f3n inclusiva<\/strong>, ya que es la primea vez que personas con su visi\u00f3n disminuida y ciegas, pueden acceder a bibliograf\u00eda pampeana para leer de forma digital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto social, cultural y educativo de la Biblioteca Digital Pampeana fue declarado este jueves de inter\u00e9s legislativo por la C\u00e1mara de Diputados de la Provincia. Se trata de una&hellip;<\/p>\n","protected":false},"author":4,"featured_media":165300,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,2],"tags":[],"class_list":["post-165299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-cultura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El proyecto social, cultural y educativo de la Biblioteca Digital Pampeana fue declarado este jueves de inter\u00e9s legislativo por la C\u00e1mara de Diputados de la Provincia. Se trata de una&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T16:16:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-15T16:16:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/bibliotecadigitalpampeana5326.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/\"},\"author\":{\"name\":\"diario2\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\"},\"headline\":\"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo\",\"datePublished\":\"2021-10-15T16:16:29+00:00\",\"dateModified\":\"2021-10-15T16:16:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/\"},\"wordCount\":384,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bibliotecadigitalpampeana5326.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"CULTURA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/\",\"name\":\"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bibliotecadigitalpampeana5326.jpg\",\"datePublished\":\"2021-10-15T16:16:29+00:00\",\"dateModified\":\"2021-10-15T16:16:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bibliotecadigitalpampeana5326.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bibliotecadigitalpampeana5326.jpg\",\"width\":758,\"height\":453},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/15\\\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\",\"name\":\"diario2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"caption\":\"diario2\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/","og_locale":"es_ES","og_type":"article","og_title":"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo - Diario Textual","og_description":"El proyecto social, cultural y educativo de la Biblioteca Digital Pampeana fue declarado este jueves de inter\u00e9s legislativo por la C\u00e1mara de Diputados de la Provincia. Se trata de una&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2021-10-15T16:16:29+00:00","article_modified_time":"2021-10-15T16:16:32+00:00","og_image":[{"width":758,"height":453,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/bibliotecadigitalpampeana5326.jpg","type":"image\/jpeg"}],"author":"diario2","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario2","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/"},"author":{"name":"diario2","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768"},"headline":"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo","datePublished":"2021-10-15T16:16:29+00:00","dateModified":"2021-10-15T16:16:32+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/"},"wordCount":384,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/bibliotecadigitalpampeana5326.jpg","articleSection":["A - ES NOTICIA (van abajo)","CULTURA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/","name":"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/bibliotecadigitalpampeana5326.jpg","datePublished":"2021-10-15T16:16:29+00:00","dateModified":"2021-10-15T16:16:32+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/bibliotecadigitalpampeana5326.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/bibliotecadigitalpampeana5326.jpg","width":758,"height":453},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/15\/la-biblioteca-digital-pampeana-fue-declarada-de-interes-legislativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La Biblioteca Digital Pampeana fue declarada de inter\u00e9s legislativo"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768","name":"diario2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","caption":"diario2"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario2\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/165299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=165299"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/165299\/revisions"}],"predecessor-version":[{"id":165301,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/165299\/revisions\/165301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/165300"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=165299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=165299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=165299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}