{"id":167017,"date":"2021-10-29T15:26:54","date_gmt":"2021-10-29T18:26:54","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=167017"},"modified":"2021-10-30T10:32:11","modified_gmt":"2021-10-30T13:32:11","slug":"en-lonquimay-arranco-la-v-feria-provincial-del-libro","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/","title":{"rendered":"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro"},"content":{"rendered":"\n<p>El intendente de Lonquimay, Manuel Feito y la secretaria de Cultura del Gobierno de La Pampa, Adriana Maggio, recibieron esta ma\u00f1ana a m\u00e1s de un centenar de ni\u00f1os y p\u00fablico adulto que se acerc\u00f3 al Sal\u00f3n Comunitario de la localidad, para compartir el acto de apertura de la 5ta. Feria Provincial del Libro.<\/p>\n\n\n\n<p>Acompa\u00f1aron este acto, todos los funcionarios de la Secretar\u00eda de Cultura, Dini Calder\u00f3n, subsecretaria de Coordinaci\u00f3n Cultural, Malva Rold\u00e1n, directora de art\u00edstica; Daniel Pinc\u00e9n, director del Museo de Historia Natural; Elina Saez, directora de Patrimonio Cultural; Gabriel Ledesma, coordinador del Consejo Provincial Aborigen, y Muchi Gerez que protagoniz\u00f3 el cierre del acto junto a lo m\u00fasicos de Banda Sinf\u00f3nica de La Pampa.<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-1-1024x683.jpg\" alt=\"\" class=\"wp-image-167022\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-1-1024x683.jpg 1024w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-1-300x200.jpg 300w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-1-768x512.jpg 768w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-1-1536x1024.jpg 1536w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-1-1170x780.jpg 1170w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-1-585x390.jpg 585w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-1-263x175.jpg 263w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Tambi\u00e9n se acercaron autoridades y concejales de la localidad; el intendente de Uriburu, Pascual Fern\u00e1ndez; directoras de Cultura de localidades vecinas, autoridades del Ministerio de Educaci\u00f3n y de la Secretar\u00eda de Cultura y Extensi\u00f3n de la Universidad Nacional de La Pampa; y alumnos y alumnas de la Escuela N\u00ba 35 de Lonquimay del Instituto \u201cJulio Neri Rubio\u201d de Lonquimay.<\/p>\n\n\n\n<p>El intendente de Lonquimay agradeci\u00f3 especialmente a la Secretar\u00eda de Cultura por haber elegido a Lonquimay como sede, y manifest\u00f3 su alegr\u00eda por haber podido concretarla de manera presencial luego de haber pasado un duro a\u00f1o por la pandemia.<\/p>\n\n\n\n<p>Luego fue el turno de Maggio.  \u00abAgradecer para nosotros tambi\u00e9n es poco, le ponemos mucho compromiso, mucho amor, desde todos los grupos que conforman la Secretar\u00eda de Cultura y en esta ocasi\u00f3n conformando un solo equipo junto a las personas de la Municipalidad de Lonquimay que tanto ayudaron\u00bb, dijo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"TAUc2AUZYk\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/editorial-voces-en-la-feria-del-libro-se-presenta-tiempo-y-desvelo-de-juan-ricardo-nervi\/\">Editorial Voces, en la Feria del Libro: se presenta \u201cTiempo y Desvelo\u201d de Juan Ricardo Nervi<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abEditorial Voces, en la Feria del Libro: se presenta \u201cTiempo y Desvelo\u201d de Juan Ricardo Nervi\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/editorial-voces-en-la-feria-del-libro-se-presenta-tiempo-y-desvelo-de-juan-ricardo-nervi\/embed\/#?secret=TAUc2AUZYk\" data-secret=\"TAUc2AUZYk\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de Lonquimay, Manuel Feito y la secretaria de Cultura del Gobierno de La Pampa, Adriana Maggio, recibieron esta ma\u00f1ana a m\u00e1s de un centenar de ni\u00f1os y p\u00fablico&hellip;<\/p>\n","protected":false},"author":3,"featured_media":167020,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,11,2],"tags":[933],"class_list":["post-167017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-que-pasa","category-cultura","tag-feria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En Lonquimay arranc\u00f3 la V Feria Provincial del Libro - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El intendente de Lonquimay, Manuel Feito y la secretaria de Cultura del Gobierno de La Pampa, Adriana Maggio, recibieron esta ma\u00f1ana a m\u00e1s de un centenar de ni\u00f1os y p\u00fablico&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-29T18:26:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-30T13:32:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1858\" \/>\n\t<meta property=\"og:image:height\" content=\"1133\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro\",\"datePublished\":\"2021-10-29T18:26:54+00:00\",\"dateModified\":\"2021-10-30T13:32:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/\"},\"wordCount\":302,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/feriaprovincialibrolonquimay2021-2.jpg\",\"keywords\":[\"feria\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"A - QUE PASA (al costado)\",\"CULTURA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/\",\"name\":\"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/feriaprovincialibrolonquimay2021-2.jpg\",\"datePublished\":\"2021-10-29T18:26:54+00:00\",\"dateModified\":\"2021-10-30T13:32:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/feriaprovincialibrolonquimay2021-2.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/feriaprovincialibrolonquimay2021-2.jpg\",\"width\":1858,\"height\":1133},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/10\\\/29\\\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/","og_locale":"es_ES","og_type":"article","og_title":"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro - Diario Textual","og_description":"El intendente de Lonquimay, Manuel Feito y la secretaria de Cultura del Gobierno de La Pampa, Adriana Maggio, recibieron esta ma\u00f1ana a m\u00e1s de un centenar de ni\u00f1os y p\u00fablico&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2021-10-29T18:26:54+00:00","article_modified_time":"2021-10-30T13:32:11+00:00","og_image":[{"width":1858,"height":1133,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-2.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro","datePublished":"2021-10-29T18:26:54+00:00","dateModified":"2021-10-30T13:32:11+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/"},"wordCount":302,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-2.jpg","keywords":["feria"],"articleSection":["A - ES NOTICIA (van abajo)","A - QUE PASA (al costado)","CULTURA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/","name":"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-2.jpg","datePublished":"2021-10-29T18:26:54+00:00","dateModified":"2021-10-30T13:32:11+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-2.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/10\/feriaprovincialibrolonquimay2021-2.jpg","width":1858,"height":1133},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/10\/29\/en-lonquimay-arranco-la-v-feria-provincial-del-libro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"En Lonquimay arranc\u00f3 la V Feria Provincial del Libro"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/167017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=167017"}],"version-history":[{"count":3,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/167017\/revisions"}],"predecessor-version":[{"id":167023,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/167017\/revisions\/167023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/167020"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=167017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=167017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=167017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}