{"id":167808,"date":"2021-11-05T09:02:08","date_gmt":"2021-11-05T12:02:08","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=167808"},"modified":"2021-11-05T09:02:10","modified_gmt":"2021-11-05T12:02:10","slug":"hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/","title":{"rendered":"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima"},"content":{"rendered":"\n<p>Obreros que hac\u00edan una excavaci\u00f3n para tender redes de gas natural hallaron bajo una calle de Lima restos de un <strong>cementerio prehisp\u00e1nico, con vasijas de cer\u00e1mica de 2.000 a\u00f1os de antig\u00fcedad<\/strong>, inform\u00f3 hoy la arque\u00f3loga que hizo el hallazgo.<\/p>\n\n\n\n<p>\u00abEste cementerio tiene una antig\u00fcedad de 2.000 a\u00f1os, <strong>hasta el momento son seis cuerpos humanos que hemos recuperado, entre ni\u00f1os y adultos, acompa\u00f1ados de un ajuar de vasijas de cer\u00e1mica que fueron hechas exprofesamente para enterrarlas\u00bb,<\/strong> dijo a la agencia AFP en el lugar la arque\u00f3loga Cecilia Camargo.<\/p>\n\n\n\n<p>Seg\u00fan los expertos, este cementerio prehisp\u00e1nico encontrado bajo una calle del distrito lime\u00f1o de La Victoria estar\u00eda ligado al desarrollo cultural \u00abBlanco sobre Rojo\u00bb, asentado en la costa central de Per\u00fa en los valles de Chill\u00f3n, R\u00edmac y Lur\u00edn, los tres r\u00edos que atraviesan Lima.<\/p>\n\n\n\n<p>\u00abHasta el momento estamos recuperando cerca de 40 vasijas de diferentes formas relacionadas con el estilo Blanco sobre Rojo\u00bb, indic\u00f3 Camargo, responsable de patrimonio cultural de la empresa de gas natural C\u00e1lidda.<\/p>\n\n\n\n<p>\u00abAlgunas botellas muy diagn\u00f3sticas de esta \u00e9poca y de este estilo que son botellas con doble pico y asa puente, y tambi\u00e9n en el momento estamos descubriendo una que tiene como una carita dentro de su cuerpo\u00bb, explic\u00f3 Camargo.<\/p>\n\n\n\n<p>Los hallazgos de restos arqueol\u00f3gicos ocurren con frecuencia en Per\u00fa. Por ello tienen arque\u00f3logos todas las empresas de servicios p\u00fablicos que hacen excavaciones, entre ellas C\u00e1lidda, una compa\u00f1\u00eda de capitales colombianos que distribuye gas natural en Lima y en el vecino puerto del Callao.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obreros que hac\u00edan una excavaci\u00f3n para tender redes de gas natural hallaron bajo una calle de Lima restos de un cementerio prehisp\u00e1nico, con vasijas de cer\u00e1mica de 2.000 a\u00f1os de&hellip;<\/p>\n","protected":false},"author":4,"featured_media":167809,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,2],"tags":[2122,6232],"class_list":["post-167808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-cultura","tag-lima","tag-prehispanico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Obreros que hac\u00edan una excavaci\u00f3n para tender redes de gas natural hallaron bajo una calle de Lima restos de un cementerio prehisp\u00e1nico, con vasijas de cer\u00e1mica de 2.000 a\u00f1os de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-05T12:02:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-05T12:02:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/11\/cementerioprehistoricolima44.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"726\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/\"},\"author\":{\"name\":\"diario2\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\"},\"headline\":\"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima\",\"datePublished\":\"2021-11-05T12:02:08+00:00\",\"dateModified\":\"2021-11-05T12:02:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/\"},\"wordCount\":285,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cementerioprehistoricolima44.jpg\",\"keywords\":[\"lima\",\"prehisp\u00e1nico\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"CULTURA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/\",\"name\":\"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cementerioprehistoricolima44.jpg\",\"datePublished\":\"2021-11-05T12:02:08+00:00\",\"dateModified\":\"2021-11-05T12:02:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cementerioprehistoricolima44.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cementerioprehistoricolima44.jpg\",\"width\":726,\"height\":484},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/11\\\/05\\\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\",\"name\":\"diario2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"caption\":\"diario2\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/","og_locale":"es_ES","og_type":"article","og_title":"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima - Diario Textual","og_description":"Obreros que hac\u00edan una excavaci\u00f3n para tender redes de gas natural hallaron bajo una calle de Lima restos de un cementerio prehisp\u00e1nico, con vasijas de cer\u00e1mica de 2.000 a\u00f1os de&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2021-11-05T12:02:08+00:00","article_modified_time":"2021-11-05T12:02:10+00:00","og_image":[{"width":726,"height":484,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/11\/cementerioprehistoricolima44.jpg","type":"image\/jpeg"}],"author":"diario2","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario2","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/"},"author":{"name":"diario2","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768"},"headline":"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima","datePublished":"2021-11-05T12:02:08+00:00","dateModified":"2021-11-05T12:02:10+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/"},"wordCount":285,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/11\/cementerioprehistoricolima44.jpg","keywords":["lima","prehisp\u00e1nico"],"articleSection":["A - ES NOTICIA (van abajo)","CULTURA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/","name":"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/11\/cementerioprehistoricolima44.jpg","datePublished":"2021-11-05T12:02:08+00:00","dateModified":"2021-11-05T12:02:10+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/11\/cementerioprehistoricolima44.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/11\/cementerioprehistoricolima44.jpg","width":726,"height":484},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/11\/05\/hallan-restos-de-un-cementerio-prehispanico-bajo-una-calle-de-lima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Hallan restos de un cementerio prehisp\u00e1nico bajo una calle de Lima"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768","name":"diario2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","caption":"diario2"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario2\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/167808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=167808"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/167808\/revisions"}],"predecessor-version":[{"id":167810,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/167808\/revisions\/167810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/167809"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=167808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=167808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=167808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}