{"id":171162,"date":"2021-12-02T09:31:24","date_gmt":"2021-12-02T12:31:24","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=171162"},"modified":"2021-12-03T19:32:04","modified_gmt":"2021-12-03T22:32:04","slug":"trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/","title":{"rendered":"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes"},"content":{"rendered":"\n<p>El pueblo de Trenel y del centro del pa\u00eds ya palpita la Fiesta Provincial de Reyes. La edici\u00f3n 69 se desarrollar\u00e1 el s\u00e1bado 8 enero 2022, al aire libre, con la actuaci\u00f3n de la Academia Guarda Pampa, el Grupo Amancay, Junta Brava, Iv\u00e1n Caporaletti y DJ Timo.<\/p>\n\n\n\n<p>El cierre estar\u00e1 a cargo del reconocido grupo cuartetero Trulal\u00e1.<\/p>\n\n\n\n<p>La fiesta contar\u00e1 con un espacio de artesanos y un patio de comidas. Adem\u00e1s, estar\u00e1n los reyes magos, con regalos y sorteos para los ni\u00f1os y las ni\u00f1as.<\/p>\n\n\n\n<p>La fiesta es organizada por el Club Social y Deportivo Trenel, con el acompa\u00f1amiento de la Secretar\u00eda de Cultura de La Pampa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/bannerfiestadereyes2022-1-1024x1024.jpeg\" alt=\"\" class=\"wp-image-171164\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/bannerfiestadereyes2022-1-1024x1024.jpeg 1024w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/bannerfiestadereyes2022-1-300x300.jpeg 300w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/bannerfiestadereyes2022-1-150x150.jpeg 150w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/bannerfiestadereyes2022-1-768x768.jpeg 768w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/bannerfiestadereyes2022-1-585x585.jpeg 585w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/bannerfiestadereyes2022-1.jpeg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pueblo de Trenel y del centro del pa\u00eds ya palpita la Fiesta Provincial de Reyes. La edici\u00f3n 69 se desarrollar\u00e1 el s\u00e1bado 8 enero 2022, al aire libre, con&hellip;<\/p>\n","protected":false},"author":3,"featured_media":171169,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,319,2],"tags":[6350],"class_list":["post-171162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-a-temporales","category-cultura","tag-trulala"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El pueblo de Trenel y del centro del pa\u00eds ya palpita la Fiesta Provincial de Reyes. La edici\u00f3n 69 se desarrollar\u00e1 el s\u00e1bado 8 enero 2022, al aire libre, con&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-02T12:31:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-03T22:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/trulala2021-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1073\" \/>\n\t<meta property=\"og:image:height\" content=\"636\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes\",\"datePublished\":\"2021-12-02T12:31:24+00:00\",\"dateModified\":\"2021-12-03T22:32:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/\"},\"wordCount\":124,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/trulala2021-2.jpg\",\"keywords\":[\"trulala\"],\"articleSection\":[\"A - QUE PASA (al costado)\",\"A - TEMPORALES\",\"CULTURA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/\",\"name\":\"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/trulala2021-2.jpg\",\"datePublished\":\"2021-12-02T12:31:24+00:00\",\"dateModified\":\"2021-12-03T22:32:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/trulala2021-2.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/trulala2021-2.jpg\",\"width\":1073,\"height\":636},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2021\\\/12\\\/02\\\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/","og_locale":"es_ES","og_type":"article","og_title":"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes - Diario Textual","og_description":"El pueblo de Trenel y del centro del pa\u00eds ya palpita la Fiesta Provincial de Reyes. La edici\u00f3n 69 se desarrollar\u00e1 el s\u00e1bado 8 enero 2022, al aire libre, con&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2021-12-02T12:31:24+00:00","article_modified_time":"2021-12-03T22:32:04+00:00","og_image":[{"width":1073,"height":636,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/trulala2021-2.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes","datePublished":"2021-12-02T12:31:24+00:00","dateModified":"2021-12-03T22:32:04+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/"},"wordCount":124,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/trulala2021-2.jpg","keywords":["trulala"],"articleSection":["A - QUE PASA (al costado)","A - TEMPORALES","CULTURA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/","name":"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/trulala2021-2.jpg","datePublished":"2021-12-02T12:31:24+00:00","dateModified":"2021-12-03T22:32:04+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/trulala2021-2.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/trulala2021-2.jpg","width":1073,"height":636},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/12\/02\/trenel-trulala-actuara-en-la-fiesta-provincial-de-reyes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Trenel: Trulal\u00e1 actuar\u00e1 en la Fiesta Provincial de Reyes"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/171162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=171162"}],"version-history":[{"count":4,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/171162\/revisions"}],"predecessor-version":[{"id":171168,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/171162\/revisions\/171168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/171169"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=171162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=171162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=171162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}