{"id":188087,"date":"2022-05-09T09:59:56","date_gmt":"2022-05-09T12:59:56","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=188087"},"modified":"2022-05-09T20:54:30","modified_gmt":"2022-05-09T23:54:30","slug":"gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/","title":{"rendered":"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d"},"content":{"rendered":"\n<p>El presidente de la <strong>Asociaci\u00f3n Agr\u00edcola Ganadera de La Pampa<\/strong> Marcelo Rodr\u00edguez revel\u00f3 a <strong>Diario Textual<\/strong> que los productores siguen con problemas para abastecerse de <strong>gasoil<\/strong>. Pero dijo que lo que m\u00e1s les preocupa es el cobro de <strong>sobreprecios<\/strong>. \u201cAnte la necesidad y la urgencia de algunos productores se consigue (gasoil), pero con un sobreprecio. Se est\u00e1 creando un <strong>mercado alternativo<\/strong>\u201d, denunci\u00f3. Y asegur\u00f3 que el litro de Diesel 500 al campo en algunas estaciones se vende <strong>\u201centre 160 y 180 pesos el litro, cuando en el surtidor est\u00e1 a 116 pesos\u201d. <\/strong><\/p>\n\n\n\n<p>Rodr\u00edguez asegur\u00f3 que contin\u00faan las \u201crestricciones\u201d en las estaciones de servicio y en los agroservice de bandera oficial. \u201cLo que m\u00e1s nos preocupa es que se est\u00e1n pagando sobreprecios, seg\u00fan la zona de la provincia\u201d.<\/p>\n\n\n\n<p>\u201cAnte la necesidad que tienen los productores para distintas labores, se est\u00e1 creando un mercado alternativo con cobros de sobreprecios. Eso es preocupante\u201d, advirti\u00f3.<\/p>\n\n\n\n<p>Las dificultades en el abastecimiento de gasoil comenzaron hace un par de meses. Sucede que la producci\u00f3n local no alcanza a satisfacer el mercado interno y las petroleras entregan -en promedio- un diez por ciento menos del producto en las estaciones de servicio. Consecuencia de ello, es que muchas estaciones operan desde hace tiempo con cupos de venta.<\/p>\n\n\n\n<p>En las \u00faltimas horas, el presidente de la Sociedad Rural Argentina,&nbsp;Nicol\u00e1s Pino, se refiri\u00f3 al tema: \u201cA los que cosechan soja les est\u00e1 faltando. Desde el Gobierno deben solucionar este tema. La gente que est\u00e1 necesitando el gasoil para trabajar no lo consigue o lo obtiene a precios desorbitantes\u201d.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Asociaci\u00f3n Agr\u00edcola Ganadera de La Pampa Marcelo Rodr\u00edguez revel\u00f3 a Diario Textual que los productores siguen con problemas para abastecerse de gasoil. Pero dijo que lo&hellip;<\/p>\n","protected":false},"author":7,"featured_media":188095,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,11,20],"tags":[1409],"class_list":["post-188087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-que-pasa","category-campo","tag-gasoil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El presidente de la Asociaci\u00f3n Agr\u00edcola Ganadera de La Pampa Marcelo Rodr\u00edguez revel\u00f3 a Diario Textual que los productores siguen con problemas para abastecerse de gasoil. Pero dijo que lo&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T12:59:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T23:54:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/cosechacampo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/\"},\"author\":{\"name\":\"diario5\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\"},\"headline\":\"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d\",\"datePublished\":\"2022-05-09T12:59:56+00:00\",\"dateModified\":\"2022-05-09T23:54:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/\"},\"wordCount\":276,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cosechacampo.jpg\",\"keywords\":[\"gasoil\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"A - QUE PASA (al costado)\",\"CAMPO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/\",\"name\":\"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cosechacampo.jpg\",\"datePublished\":\"2022-05-09T12:59:56+00:00\",\"dateModified\":\"2022-05-09T23:54:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cosechacampo.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cosechacampo.jpg\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/09\\\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\",\"name\":\"diario5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"caption\":\"diario5\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/","og_locale":"es_ES","og_type":"article","og_title":"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d - Diario Textual","og_description":"El presidente de la Asociaci\u00f3n Agr\u00edcola Ganadera de La Pampa Marcelo Rodr\u00edguez revel\u00f3 a Diario Textual que los productores siguen con problemas para abastecerse de gasoil. Pero dijo que lo&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-05-09T12:59:56+00:00","article_modified_time":"2022-05-09T23:54:30+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/cosechacampo.jpg","type":"image\/jpeg"}],"author":"diario5","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario5","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/"},"author":{"name":"diario5","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067"},"headline":"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d","datePublished":"2022-05-09T12:59:56+00:00","dateModified":"2022-05-09T23:54:30+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/"},"wordCount":276,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/cosechacampo.jpg","keywords":["gasoil"],"articleSection":["A - ES NOTICIA (van abajo)","A - QUE PASA (al costado)","CAMPO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/","name":"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/cosechacampo.jpg","datePublished":"2022-05-09T12:59:56+00:00","dateModified":"2022-05-09T23:54:30+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/cosechacampo.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/cosechacampo.jpg","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/09\/gasoil-ruralistas-pampeanos-denuncian-sobreprecios-y-un-mercado-alternativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Gasoil: ruralistas pampeanos denuncian sobreprecios y un \u201cmercado alternativo\u201d"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067","name":"diario5","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","caption":"diario5"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario5\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/188087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=188087"}],"version-history":[{"count":4,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/188087\/revisions"}],"predecessor-version":[{"id":188100,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/188087\/revisions\/188100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/188095"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=188087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=188087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=188087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}