{"id":188434,"date":"2022-05-12T08:36:42","date_gmt":"2022-05-12T11:36:42","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=188434"},"modified":"2022-05-12T19:03:09","modified_gmt":"2022-05-12T22:03:09","slug":"provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/","title":{"rendered":"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico"},"content":{"rendered":"\n<p>El Gobierno provincial financiar\u00e1 obras de pavimentaci\u00f3n y repavimentaci\u00f3n en General Pico y Santa Rosa por $2.892 millones. En la capital provincial se invertir\u00e1n $1.507 millones, &nbsp;en tanto que en la ciudad norte\u00f1a se destinar\u00e1n $1.385 para estos trabajos. En ambos casos las obras tienen un a\u00f1o y seis meses de plazo para su ejecuci\u00f3n.<\/p>\n\n\n\n<p>En Santa Rosa se realizar\u00e1n trabajos de rehabilitaci\u00f3n y pavimentaci\u00f3n de cuadras con microaglomerado asf\u00e1ltico en fr\u00edo y concreto asf\u00e1ltico en caliente y ejecuci\u00f3n de pavimento en cuadras completamente nuevas de la ciudad.<\/p>\n\n\n\n<p>Se ejecutar\u00e1\u00a0 el fresado de la capa de rodamiento existente, logrando una superficie apta para desde all\u00ed construir la nueva capa de rodamiento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/dinapolirojoalonsoconvenioasfalto-1024x649.jpg\" alt=\"\" class=\"wp-image-188438\" width=\"756\" height=\"479\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/dinapolirojoalonsoconvenioasfalto-1024x649.jpg 1024w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/dinapolirojoalonsoconvenioasfalto-300x190.jpg 300w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/dinapolirojoalonsoconvenioasfalto-768x487.jpg 768w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/dinapolirojoalonsoconvenioasfalto-1536x973.jpg 1536w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/dinapolirojoalonsoconvenioasfalto-2048x1298.jpg 2048w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/dinapolirojoalonsoconvenioasfalto-1170x741.jpg 1170w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/05\/dinapolirojoalonsoconvenioasfalto-585x371.jpg 585w\" sizes=\"(max-width: 756px) 100vw, 756px\" \/><figcaption><em>El convenio se firm\u00f3 en Casa de Gobierno<\/em>.<\/figcaption><\/figure>\n\n\n\n<p>En las calles que presentan mayor grado de deterioro o deformaciones tanto transversales como longitudinales, se prev\u00e9 el fresado y reciclado de la estructura existente previo a la construcci\u00f3n de la nueva capa de rodamiento.<\/p>\n\n\n\n<p>En las calles nuevas a pavimentar los trabajos implicar\u00e1n preparaci\u00f3n de subrasante, ejecuci\u00f3n de cordones y badenes, construcci\u00f3n de base granular, imprimaci\u00f3n, riego de liga y carpeta asf\u00e1ltica en caliente de 4 cm.<\/p>\n\n\n\n<p>En Pico, en tanto, se reconstruir\u00e1 el casco hist\u00f3rico en un total de 342 cuadras.&nbsp;Se repavimentar\u00e1 con concreto asf\u00e1ltico en caliente distintas arterias, ya determinadas de esta ciudad. Se prev\u00e9 la realizaci\u00f3n del fresado de capa de rodamiento existente y el reciclado de estructura existente. Posteriormente se avanzar\u00e1 en el riego de Imprimaci\u00f3n de la base; riego de liga, para concluir con la ejecuci\u00f3n de carpeta de concreto asf\u00e1ltico en caliente de espesores variables.<\/p>\n\n\n\n<p>Del mismo modo que se har\u00e1 en Santa Rosa, se prev\u00e9 que en las calles m\u00e1s deterioradas o deformadas, se har\u00e1 el fresado y reciclado de la estructura existente previo a la construcci\u00f3n de la nueva capa de rodamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno provincial financiar\u00e1 obras de pavimentaci\u00f3n y repavimentaci\u00f3n en General Pico y Santa Rosa por $2.892 millones. En la capital provincial se invertir\u00e1n $1.507 millones, &nbsp;en tanto que en&hellip;<\/p>\n","protected":false},"author":7,"featured_media":174173,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,12],"tags":[6932],"class_list":["post-188434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-sociedad","tag-pavimento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El Gobierno provincial financiar\u00e1 obras de pavimentaci\u00f3n y repavimentaci\u00f3n en General Pico y Santa Rosa por $2.892 millones. En la capital provincial se invertir\u00e1n $1.507 millones, &nbsp;en tanto que en&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-12T11:36:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-12T22:03:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/asfaltosantarosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"956\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/\"},\"author\":{\"name\":\"diario5\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\"},\"headline\":\"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico\",\"datePublished\":\"2022-05-12T11:36:42+00:00\",\"dateModified\":\"2022-05-12T22:03:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/\"},\"wordCount\":338,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/asfaltosantarosa.jpg\",\"keywords\":[\"pavimento\"],\"articleSection\":[\"A - QUE PASA (al costado)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/\",\"name\":\"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/asfaltosantarosa.jpg\",\"datePublished\":\"2022-05-12T11:36:42+00:00\",\"dateModified\":\"2022-05-12T22:03:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/asfaltosantarosa.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/asfaltosantarosa.jpg\",\"width\":1440,\"height\":956},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/05\\\/12\\\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\",\"name\":\"diario5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"caption\":\"diario5\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/","og_locale":"es_ES","og_type":"article","og_title":"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico - Diario Textual","og_description":"El Gobierno provincial financiar\u00e1 obras de pavimentaci\u00f3n y repavimentaci\u00f3n en General Pico y Santa Rosa por $2.892 millones. En la capital provincial se invertir\u00e1n $1.507 millones, &nbsp;en tanto que en&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-05-12T11:36:42+00:00","article_modified_time":"2022-05-12T22:03:09+00:00","og_image":[{"width":1440,"height":956,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/asfaltosantarosa.jpg","type":"image\/jpeg"}],"author":"diario5","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario5","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/"},"author":{"name":"diario5","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067"},"headline":"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico","datePublished":"2022-05-12T11:36:42+00:00","dateModified":"2022-05-12T22:03:09+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/"},"wordCount":338,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/asfaltosantarosa.jpg","keywords":["pavimento"],"articleSection":["A - QUE PASA (al costado)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/","name":"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/asfaltosantarosa.jpg","datePublished":"2022-05-12T11:36:42+00:00","dateModified":"2022-05-12T22:03:09+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/asfaltosantarosa.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2021\/12\/asfaltosantarosa.jpg","width":1440,"height":956},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/05\/12\/provincia-invertira-2-892-millones-en-pavimento-para-santa-rosa-y-general-pico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Provincia invertir\u00e1 $2.892 millones en pavimento para Santa Rosa y General Pico"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067","name":"diario5","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","caption":"diario5"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario5\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/188434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=188434"}],"version-history":[{"count":3,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/188434\/revisions"}],"predecessor-version":[{"id":188440,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/188434\/revisions\/188440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/174173"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=188434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=188434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=188434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}