{"id":191195,"date":"2022-06-10T21:32:28","date_gmt":"2022-06-11T00:32:28","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=191195"},"modified":"2022-06-12T07:51:56","modified_gmt":"2022-06-12T10:51:56","slug":"ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/","title":{"rendered":"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial"},"content":{"rendered":"\n<p>Los <strong>gobernadores del peronismo <\/strong>quieren <strong>meterse en la pelea presidencial del 2023<\/strong>: este viernes, por la noche, anunciaron la conformaci\u00f3n de la <strong>Liga de los Gobernadores<\/strong>.<\/p>\n\n\n\n<p>Uno de los que hizo el anuncio fue el pampeano <strong>Sergio Ziliotto<\/strong>, el primero en firmar la proclama de lanzamiento. \u201cGobernadoras y gobernadores impulsamos el debate, la consulta y los acuerdos a trav\u00e9s de una liga que nos une detr\u00e1s de una Argentina justa, federal y en unidad nacional\u201d, tuite\u00f3.<\/p>\n\n\n\n<p>De esta manera, la idea de construir un eje pol\u00edtico de los gobernadores busca meterse en la discusi\u00f3n q<strong>ue seguramente concentrar\u00e1n en 2023 el kircherismo duro, el massismo y el albertismo.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"568\" height=\"855\" src=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/06\/ligadegobernadoresactafundacional2022-1.jpg\" alt=\"\" class=\"wp-image-191198\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/06\/ligadegobernadoresactafundacional2022-1.jpg 568w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/06\/ligadegobernadoresactafundacional2022-1-199x300.jpg 199w\" sizes=\"(max-width: 568px) 100vw, 568px\" \/><\/figure>\n\n\n\n<p>\u201cDespojados de intereses partidarios, representamos a nuestras provincias en la defensa de un pa\u00eds justo y equitativo, en el que los recursos se asignen promoviendo en desarrollo arm\u00f3nico y equilibrado\u201d, expres\u00f3 Ziliotto.<\/p>\n\n\n\n<p>\u201cAsumimos un debate hist\u00f3rico frente a las asimetr\u00edas que imponen la infraestructura p\u00fablica disponible; la competitividad de las econom\u00edas regionales;&nbsp; la inequidad en el precio del combustible; las asimetr\u00edas de las tarifas energ\u00e9ticas y en los subsidios la transporte\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>\u201cEs hora de gestar consensos estructurales y pol\u00edticas para el desarrollo que permitan generar nuevos empleos de calidad. Con este objetivo analizamos alternativas para federalizar pol\u00edticas tendientes a transformar los planes sociales en trabajo genuino y digno\u201d, dijo.<\/p>\n\n\n\n<p>\u201cQueremos representar a nuestras provincias m\u00e1s all\u00e1 del partido o la coalici\u00f3n que las gobierne. Nuestra convocatoria es amplia y plural para fortalecer la democracia con la participaci\u00f3n de todos y todas. \u00a1Ese es el desaf\u00edo!\u201d, finaliz\u00f3 el mandatario.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/ziliottosergio\/status\/1535416625477955584?s=21&#038;t=mxkzgKJN_9mOafodDD1Uzg\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los gobernadores del peronismo quieren meterse en la pelea presidencial del 2023: este viernes, por la noche, anunciaron la conformaci\u00f3n de la Liga de los Gobernadores. Uno de los que&hellip;<\/p>\n","protected":false},"author":3,"featured_media":190377,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,8],"tags":[6895],"class_list":["post-191195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-politica","tag-en-campana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Los gobernadores del peronismo quieren meterse en la pelea presidencial del 2023: este viernes, por la noche, anunciaron la conformaci\u00f3n de la Liga de los Gobernadores. Uno de los que&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-11T00:32:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-12T10:51:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/06\/ziliottosergiogobernadores2022-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial\",\"datePublished\":\"2022-06-11T00:32:28+00:00\",\"dateModified\":\"2022-06-12T10:51:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/\"},\"wordCount\":302,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ziliottosergiogobernadores2022-11.jpg\",\"keywords\":[\"en campa\u00f1a\"],\"articleSection\":[\"A - QUE PASA (al costado)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/\",\"name\":\"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ziliottosergiogobernadores2022-11.jpg\",\"datePublished\":\"2022-06-11T00:32:28+00:00\",\"dateModified\":\"2022-06-12T10:51:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ziliottosergiogobernadores2022-11.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ziliottosergiogobernadores2022-11.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/10\\\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/","og_locale":"es_ES","og_type":"article","og_title":"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial - Diario Textual","og_description":"Los gobernadores del peronismo quieren meterse en la pelea presidencial del 2023: este viernes, por la noche, anunciaron la conformaci\u00f3n de la Liga de los Gobernadores. Uno de los que&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-06-11T00:32:28+00:00","article_modified_time":"2022-06-12T10:51:56+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/06\/ziliottosergiogobernadores2022-11.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial","datePublished":"2022-06-11T00:32:28+00:00","dateModified":"2022-06-12T10:51:56+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/"},"wordCount":302,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/06\/ziliottosergiogobernadores2022-11.jpg","keywords":["en campa\u00f1a"],"articleSection":["A - QUE PASA (al costado)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/","name":"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/06\/ziliottosergiogobernadores2022-11.jpg","datePublished":"2022-06-11T00:32:28+00:00","dateModified":"2022-06-12T10:51:56+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/06\/ziliottosergiogobernadores2022-11.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/06\/ziliottosergiogobernadores2022-11.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/10\/ziliotto-y-otros-mandatarios-lanza-la-liga-de-los-gobernadores-para-terciar-en-la-carrera-presidencial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Ziliotto y otros mandatarios lanzan la Liga de los Gobernadores para terciar en la carrera presidencial"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/191195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=191195"}],"version-history":[{"count":9,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/191195\/revisions"}],"predecessor-version":[{"id":191207,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/191195\/revisions\/191207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/190377"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=191195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=191195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=191195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}