{"id":191426,"date":"2022-06-14T16:00:00","date_gmt":"2022-06-14T19:00:00","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=191426"},"modified":"2022-06-15T09:30:49","modified_gmt":"2022-06-15T12:30:49","slug":"el-indec-informa-la-inflacion-de-mayo","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/","title":{"rendered":"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o"},"content":{"rendered":"\n<p>La inflaci\u00f3n mostr\u00f3 una leve desaceleraci\u00f3n en mayo, pese a mantenerse a\u00fan en niveles muy elevados. El Indec inform\u00f3 hoy que&nbsp;<strong>la suba de precios del mes pasado fue de 5,1%<\/strong>&nbsp;y que en s\u00f3lo cinco meses ya acumula una variaci\u00f3n de 29,3%. El organismo asegur\u00f3 que el \u00edndice de precios al consumidor (IPC) muestra&nbsp;<strong>un avance de 60,7% en los \u00faltimos doce meses.<\/strong><\/p>\n\n\n\n<p>El aumento de la inflaci\u00f3n n\u00facleo -que elimina precios estacionales y regulados- fue de 5,2%. Los Alimentos y bebidas, el cap\u00edtulo que m\u00e1s pesa en el IPC y que m\u00e1s afecta a los segmentos carenciados, tuvo un incremento de 4,4%.<\/p>\n\n\n\n<p>Seg\u00fan detall\u00f3 el ministerio de Econom\u00eda, \u201cdentro de la divisi\u00f3n Alimentos y Bebidas no alcoh\u00f3licas, la mayor\u00eda de los rubros redujo sus tasas de aumento respecto a los meses previos. Las mayores subas volvieron a darse en Aceites (11% y 6% seg\u00fan regi\u00f3n) y Carnes y derivados (entre 5% y 6,5%), as\u00ed como tambi\u00e9n en Bebidas no alcoh\u00f3licas (aumentos de hasta casi 8% en algunas partes del pa\u00eds). Por otro lado, Frutas sigue con aumentos moderados mientras que las Verduras contin\u00faan con bajas en la mayor\u00eda de las regiones.<\/p>\n\n\n\n<p>\u201cPor su parte, la inflaci\u00f3n del mes fue liderada por Salud, que tuvo un incremento de 6,2% mensual (vs. 6,4% en abril), por incrementos en medicamentos y prepagas. Le sigui\u00f3 la divisi\u00f3n Transporte que subi\u00f3 6,1% mensual (vs. 5,3% abril) al nivel general, con impacto de la suba de combustibles y de transporte p\u00fablico\u201d, agregaron.<\/p>\n\n\n\n<p>En los pr\u00f3ximos d\u00edas el Ministerio de Econom\u00eda actualizar\u00e1 la proyecci\u00f3n de inflaci\u00f3n anual que hab\u00eda acordado con el FMI. Como tope, hab\u00edan calculado un 48% anual, pero esa pauta qued\u00f3 completamente vetusta tras la variaci\u00f3n de los \u00edndices del primer cuatrimestre. El Gobierno ahora no espera una tasa menor al 60% anual para el cierre de 2022 en un escenario optimista y un rec\u00e1lculo de esa cifra deber\u00e1 estar m\u00e1s cerca de ese nivel.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La inflaci\u00f3n mostr\u00f3 una leve desaceleraci\u00f3n en mayo, pese a mantenerse a\u00fan en niveles muy elevados. El Indec inform\u00f3 hoy que&nbsp;la suba de precios del mes pasado fue de 5,1%&nbsp;y&hellip;<\/p>\n","protected":false},"author":3,"featured_media":89894,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,5],"tags":[1943],"class_list":["post-191426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-economia","tag-precios"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"La inflaci\u00f3n mostr\u00f3 una leve desaceleraci\u00f3n en mayo, pese a mantenerse a\u00fan en niveles muy elevados. El Indec inform\u00f3 hoy que&nbsp;la suba de precios del mes pasado fue de 5,1%&nbsp;y&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-14T19:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-15T12:30:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o\",\"datePublished\":\"2022-06-14T19:00:00+00:00\",\"dateModified\":\"2022-06-15T12:30:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/\"},\"wordCount\":361,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg\",\"keywords\":[\"precios\"],\"articleSection\":[\"A - QUE PASA (al costado)\",\"ECONOMIA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/\",\"name\":\"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg\",\"datePublished\":\"2022-06-14T19:00:00+00:00\",\"dateModified\":\"2022-06-15T12:30:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/14\\\/el-indec-informa-la-inflacion-de-mayo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/","og_locale":"es_ES","og_type":"article","og_title":"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o - Diario Textual","og_description":"La inflaci\u00f3n mostr\u00f3 una leve desaceleraci\u00f3n en mayo, pese a mantenerse a\u00fan en niveles muy elevados. El Indec inform\u00f3 hoy que&nbsp;la suba de precios del mes pasado fue de 5,1%&nbsp;y&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-06-14T19:00:00+00:00","article_modified_time":"2022-06-15T12:30:49+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o","datePublished":"2022-06-14T19:00:00+00:00","dateModified":"2022-06-15T12:30:49+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/"},"wordCount":361,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg","keywords":["precios"],"articleSection":["A - QUE PASA (al costado)","ECONOMIA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/","name":"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg","datePublished":"2022-06-14T19:00:00+00:00","dateModified":"2022-06-15T12:30:49+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/cuarentenacoronaviruscontrolprecios2020-000001.jpeg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/14\/el-indec-informa-la-inflacion-de-mayo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La inflaci\u00f3n de mayo fue de 5,1% y el aumento ya supera el 60% en un a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/191426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=191426"}],"version-history":[{"count":6,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/191426\/revisions"}],"predecessor-version":[{"id":191512,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/191426\/revisions\/191512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/89894"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=191426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=191426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=191426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}