{"id":191550,"date":"2022-06-15T11:30:57","date_gmt":"2022-06-15T14:30:57","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=191550"},"modified":"2022-06-16T10:36:14","modified_gmt":"2022-06-16T13:36:14","slug":"el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/","title":{"rendered":"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones"},"content":{"rendered":"\n<p>A una semana del lanzamiento de la nueva l\u00ednea de <strong>cr\u00e9ditos personales<\/strong> el <strong>Banco de La Pampa<\/strong> ya otorg\u00f3 <strong>7.200 pr\u00e9stamos por $722 millones<\/strong>, inform\u00f3 a Diario Textual el presidente de la entidad bancaria Alexis Iviglia. <strong>\u201cEl funcionamiento de la l\u00ednea es excelente\u201d<\/strong>, evalu\u00f3 el banquero.<\/p>\n\n\n\n<p>La cartera inicial que dispuso el BLP para estos cr\u00e9ditos es de 2.000 millones de pesos y una tasa fija del 29% a 24 meses. <\/p>\n\n\n\n<p>Los pr\u00e9stamos son hasta 100 mil pesos, con una cuota mensual de $6.200.<\/p>\n\n\n\n<p>Los clientes del Banco de La Pampa pueden acceder por Home Banking o Pampa M\u00f3vil, a este nuevo beneficio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A una semana del lanzamiento de la nueva l\u00ednea de cr\u00e9ditos personales el Banco de La Pampa ya otorg\u00f3 7.200 pr\u00e9stamos por $722 millones, inform\u00f3 a Diario Textual el presidente&hellip;<\/p>\n","protected":false},"author":7,"featured_media":87817,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,12],"tags":[1153],"class_list":["post-191550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-sociedad","tag-creditos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"A una semana del lanzamiento de la nueva l\u00ednea de cr\u00e9ditos personales el Banco de La Pampa ya otorg\u00f3 7.200 pr\u00e9stamos por $722 millones, inform\u00f3 a Diario Textual el presidente&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-15T14:30:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-16T13:36:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/bancodelapampa375291.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/\"},\"author\":{\"name\":\"diario5\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\"},\"headline\":\"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones\",\"datePublished\":\"2022-06-15T14:30:57+00:00\",\"dateModified\":\"2022-06-16T13:36:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/\"},\"wordCount\":114,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/bancodelapampa375291.jpg\",\"keywords\":[\"cr\u00e9ditos\"],\"articleSection\":[\"A - QUE PASA (al costado)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/\",\"name\":\"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/bancodelapampa375291.jpg\",\"datePublished\":\"2022-06-15T14:30:57+00:00\",\"dateModified\":\"2022-06-16T13:36:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/bancodelapampa375291.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/bancodelapampa375291.jpg\",\"width\":900,\"height\":507},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/06\\\/15\\\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\",\"name\":\"diario5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"caption\":\"diario5\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/","og_locale":"es_ES","og_type":"article","og_title":"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones - Diario Textual","og_description":"A una semana del lanzamiento de la nueva l\u00ednea de cr\u00e9ditos personales el Banco de La Pampa ya otorg\u00f3 7.200 pr\u00e9stamos por $722 millones, inform\u00f3 a Diario Textual el presidente&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-06-15T14:30:57+00:00","article_modified_time":"2022-06-16T13:36:14+00:00","og_image":[{"width":900,"height":507,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/bancodelapampa375291.jpg","type":"image\/jpeg"}],"author":"diario5","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario5","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/"},"author":{"name":"diario5","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067"},"headline":"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones","datePublished":"2022-06-15T14:30:57+00:00","dateModified":"2022-06-16T13:36:14+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/"},"wordCount":114,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/bancodelapampa375291.jpg","keywords":["cr\u00e9ditos"],"articleSection":["A - QUE PASA (al costado)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/","name":"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/bancodelapampa375291.jpg","datePublished":"2022-06-15T14:30:57+00:00","dateModified":"2022-06-16T13:36:14+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/bancodelapampa375291.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/04\/bancodelapampa375291.jpg","width":900,"height":507},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/06\/15\/el-blp-en-una-semana-otorgo-7-200-prestamos-personales-por-722-millones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"El BLP en una semana otorg\u00f3 7.200 pr\u00e9stamos personales por $722 millones"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067","name":"diario5","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","caption":"diario5"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario5\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/191550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=191550"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/191550\/revisions"}],"predecessor-version":[{"id":191552,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/191550\/revisions\/191552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/87817"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=191550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=191550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=191550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}