{"id":194893,"date":"2022-07-21T20:03:43","date_gmt":"2022-07-21T23:03:43","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=194893"},"modified":"2022-07-21T20:03:46","modified_gmt":"2022-07-21T23:03:46","slug":"empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/","title":{"rendered":"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3"},"content":{"rendered":"\n<p>La <strong>Empresa Pampeana de Telecomunicaciones (Empatel) inici\u00f3 el tendido de fibra \u00f3ptica domiciliaria en Cuchillo C\u00f3<\/strong>. El presidente de la empresa estatal, Andr\u00e9s Zulueta, y el gerente general, Ricardo Fuch, visitaron la localidad y se reunieron con el intendente Horacio Ledesma para revisar la puesta en marcha y coordinar algunos aspectos de su implementaci\u00f3n.<\/p>\n\n\n\n<p>\u201cEstimamos que va a ser un despliegue muy r\u00e1pido, despu\u00e9s tendremos que hacer pruebas junto a la Fundaci\u00f3n para la Sanidad Animal (Funsadu) para lanzar el servicio que va a manejar esa entidad. <strong>La llegada de la fibra \u00f3ptica va a permitir acceder a servicios de mayor velocidad y evitar los incidentes que son caracter\u00edsticos del radioenlace<\/strong>\u201d, expres\u00f3 Zulueta a la Agencia Provincial de Noticias.<\/p>\n\n\n\n<p>Y a\u00f1adi\u00f3: \u201cEs una gran satisfacci\u00f3n para Empatel como para el Ministerio de Conectividad y Modernizaci\u00f3n, que conduce Antonio Curciarello, llevar este tipo de servicios a lugares como Cuchillo C\u00f3, igualando en t\u00e9rminos de calidad a lo que recibe un pampeano de otra localidad de m\u00e1s habitantes\u201d.<\/p>\n\n\n\n<p>El funcionario, con relaci\u00f3n a la obra, afirm\u00f3 que <strong>se cubrir\u00e1n aproximadamente 15 manzanas donde hay unos 60 hogares. \u201cDespu\u00e9s de montar la red, vamos a realizar una etapa de prueba con una cantidad de conexiones muy limitadas <\/strong>para asegurarnos que no haya ning\u00fan inconveniente antes de escalar en cantidad de conexiones. Este procedimiento ya lo venimos haciendo en otras localidades con muy buen resultado. Una vez cumplida esa etapa el proveedor, con el acompa\u00f1amiento t\u00e9cnico de Empatel, ira realizando las correspondientes conexiones en cada uno de los hogares\u201d, explic\u00f3.<\/p>\n\n\n\n<p>El tendido de fibra \u00f3ptica domiciliaria en Cuchillo C\u00f3 es parte del plan de obras que incluye la <strong>conexi\u00f3n de diecisiete localidades con el servicio de \u00faltima milla, y cinco localidades a la fibra \u00f3ptica troncal de la Provincia, financiado por el Gobierno provincial y el Ente Nacional de Comunicaciones<\/strong> (ENACOM) y proyectado por el Ministerio de Conectividad y Modernizaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Empresa Pampeana de Telecomunicaciones (Empatel) inici\u00f3 el tendido de fibra \u00f3ptica domiciliaria en Cuchillo C\u00f3. El presidente de la empresa estatal, Andr\u00e9s Zulueta, y el gerente general, Ricardo Fuch,&hellip;<\/p>\n","protected":false},"author":5,"featured_media":194894,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[1857,2027,6479],"class_list":["post-194893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad","tag-cuchillo-co","tag-empatel","tag-fibra-optica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3 - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3 - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"La Empresa Pampeana de Telecomunicaciones (Empatel) inici\u00f3 el tendido de fibra \u00f3ptica domiciliaria en Cuchillo C\u00f3. El presidente de la empresa estatal, Andr\u00e9s Zulueta, y el gerente general, Ricardo Fuch,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-21T23:03:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-21T23:03:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/07\/empatelcuchilloco.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/\"},\"author\":{\"name\":\"diario3\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\"},\"headline\":\"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3\",\"datePublished\":\"2022-07-21T23:03:43+00:00\",\"dateModified\":\"2022-07-21T23:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/\"},\"wordCount\":344,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/empatelcuchilloco.jpeg\",\"keywords\":[\"cuchillo co\",\"Empatel\",\"fibra optica\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/\",\"name\":\"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3 - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/empatelcuchilloco.jpeg\",\"datePublished\":\"2022-07-21T23:03:43+00:00\",\"dateModified\":\"2022-07-21T23:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/empatelcuchilloco.jpeg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/empatelcuchilloco.jpeg\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/07\\\/21\\\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\",\"name\":\"diario3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"caption\":\"diario3\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3 - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/","og_locale":"es_ES","og_type":"article","og_title":"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3 - Diario Textual","og_description":"La Empresa Pampeana de Telecomunicaciones (Empatel) inici\u00f3 el tendido de fibra \u00f3ptica domiciliaria en Cuchillo C\u00f3. El presidente de la empresa estatal, Andr\u00e9s Zulueta, y el gerente general, Ricardo Fuch,&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-07-21T23:03:43+00:00","article_modified_time":"2022-07-21T23:03:46+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/07\/empatelcuchilloco.jpeg","type":"image\/jpeg"}],"author":"diario3","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario3","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/"},"author":{"name":"diario3","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f"},"headline":"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3","datePublished":"2022-07-21T23:03:43+00:00","dateModified":"2022-07-21T23:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/"},"wordCount":344,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/07\/empatelcuchilloco.jpeg","keywords":["cuchillo co","Empatel","fibra optica"],"articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/","name":"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3 - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/07\/empatelcuchilloco.jpeg","datePublished":"2022-07-21T23:03:43+00:00","dateModified":"2022-07-21T23:03:46+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/07\/empatelcuchilloco.jpeg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/07\/empatelcuchilloco.jpeg","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/07\/21\/empatel-comenzo-trabajos-para-llevar-la-fibra-optica-a-cuchillo-co\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Empatel comenz\u00f3 trabajos para llevar la fibra \u00f3ptica a Cuchillo C\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f","name":"diario3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","caption":"diario3"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario3\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/194893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=194893"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/194893\/revisions"}],"predecessor-version":[{"id":194895,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/194893\/revisions\/194895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/194894"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=194893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=194893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=194893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}