{"id":199270,"date":"2022-09-05T19:36:41","date_gmt":"2022-09-05T22:36:41","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=199270"},"modified":"2022-09-05T19:36:44","modified_gmt":"2022-09-05T22:36:44","slug":"metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/","title":{"rendered":"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos"},"content":{"rendered":"\n<p>El ministro de Educaci\u00f3n de La Pampa, Pablo Maccione, visit\u00f3 la localidad de Metileo, donde recorri\u00f3 las obras de refacci\u00f3n que se llevan adelante en la Escuela N\u00b0 53 y cuya inversi\u00f3n provincial ronda los 11 millones de pesos.<\/p>\n\n\n\n<p>El funcionario provincial estuvo acompa\u00f1ado por el intendente, Juan Carlos Pavoni y la concejala Adriana Maturana, quienes fueron recibidos por la directora del establecimiento educativo, Mar\u00eda Bel\u00e9n Gallini.<\/p>\n\n\n\n<p>\u201cSon refacciones necesarias, en esta primera etapa se trabaja en el recambio de chapas en el techo que ten\u00eda filtraciones, m\u00e1s una ampliaci\u00f3n que consta de una galer\u00eda que permitir\u00e1 acceder a los sanitarios de manera interna\u201d, coment\u00f3 el ministro a la Agencia Provincial de Noticias.<\/p>\n\n\n\n<p>Posteriormente se trabajar\u00e1 en una segunda etapa en reparaciones generales de mamposter\u00eda y pintura general del edificio. \u201cSiempre tenemos contacto con los intendentes, Juan Carlos (Pavoni) siempre estuvo preocupado y ocupado por esta situaci\u00f3n, hab\u00edamos acordado algunas definiciones hace un tiempo y hoy estamos concretando la primera etapa, con una inversi\u00f3n que ronda los 11 millones de pesos\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>El jefe comunal agradeci\u00f3 la visita del ministro: \u201cAdem\u00e1s sumamos la buena noticia de nuevas obras que se har\u00e1n por etapas, son muy importantes y con una gran inversi\u00f3n del Gobierno provincial. Nosotros siempre destacamos que el trabajo conjunto con Provincia para los pueblos chicos es muy importante\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Educaci\u00f3n de La Pampa, Pablo Maccione, visit\u00f3 la localidad de Metileo, donde recorri\u00f3 las obras de refacci\u00f3n que se llevan adelante en la Escuela N\u00b0 53 y&hellip;<\/p>\n","protected":false},"author":5,"featured_media":199273,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[3728,2394],"class_list":["post-199270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad","tag-educacion-2","tag-maccione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El ministro de Educaci\u00f3n de La Pampa, Pablo Maccione, visit\u00f3 la localidad de Metileo, donde recorri\u00f3 las obras de refacci\u00f3n que se llevan adelante en la Escuela N\u00b0 53 y&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-05T22:36:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-05T22:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/maccionemetileo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/\"},\"author\":{\"name\":\"diario3\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\"},\"headline\":\"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos\",\"datePublished\":\"2022-09-05T22:36:41+00:00\",\"dateModified\":\"2022-09-05T22:36:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/\"},\"wordCount\":246,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/maccionemetileo.jpg\",\"keywords\":[\"educacion\",\"maccione\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/\",\"name\":\"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/maccionemetileo.jpg\",\"datePublished\":\"2022-09-05T22:36:41+00:00\",\"dateModified\":\"2022-09-05T22:36:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/maccionemetileo.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/maccionemetileo.jpg\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/05\\\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\",\"name\":\"diario3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"caption\":\"diario3\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/","og_locale":"es_ES","og_type":"article","og_title":"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos - Diario Textual","og_description":"El ministro de Educaci\u00f3n de La Pampa, Pablo Maccione, visit\u00f3 la localidad de Metileo, donde recorri\u00f3 las obras de refacci\u00f3n que se llevan adelante en la Escuela N\u00b0 53 y&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-09-05T22:36:41+00:00","article_modified_time":"2022-09-05T22:36:44+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/maccionemetileo.jpg","type":"image\/jpeg"}],"author":"diario3","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario3","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/"},"author":{"name":"diario3","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f"},"headline":"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos","datePublished":"2022-09-05T22:36:41+00:00","dateModified":"2022-09-05T22:36:44+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/"},"wordCount":246,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/maccionemetileo.jpg","keywords":["educacion","maccione"],"articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/","name":"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/maccionemetileo.jpg","datePublished":"2022-09-05T22:36:41+00:00","dateModified":"2022-09-05T22:36:44+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/maccionemetileo.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/maccionemetileo.jpg","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/05\/metileo-obras-de-refaccion-en-la-escuela-53-por-11-millones-de-pesos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Metileo: obras de refacci\u00f3n en la escuela 53 por 11 millones de pesos"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f","name":"diario3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","caption":"diario3"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario3\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/199270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=199270"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/199270\/revisions"}],"predecessor-version":[{"id":199274,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/199270\/revisions\/199274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/199273"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=199270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=199270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=199270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}