{"id":200173,"date":"2022-09-13T21:35:01","date_gmt":"2022-09-14T00:35:01","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=200173"},"modified":"2022-09-14T10:09:54","modified_gmt":"2022-09-14T13:09:54","slug":"como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/","title":{"rendered":"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio"},"content":{"rendered":"\n<p>Este martes 13, mientras prosigue la investigaci\u00f3n del intento de magnicidio de <strong>Cristina Kirchner<\/strong>, se detectaron mensajes comprometedores de <strong>Agustina D\u00edaz<\/strong>, la tercera detenida luego del atentado fallido.<\/p>\n\n\n\n<p>La joven detenida recientemente luego de un operativo en San Miguel ordenado por la jueza Mar\u00eda Eugenia Capuchetti, le habr\u00eda indicado a su amiga de confianza <strong>Brenda Uliarte <\/strong>que elimine el contenido de su tel\u00e9fono celular luego del intento de asesinato de la titular del Senado. Tambi\u00e9n le recrimin\u00f3 las fallas en la ejecuci\u00f3n del ataque. <strong>\u201c\u00bfPor qu\u00e9 fall\u00f3 el tiro? \u00bfC\u00f3mo mandaste a este tarado? \u00bfSe puso nervioso?\u201d, le pregunt\u00f3.<\/strong><\/p>\n\n\n\n<p>\u201cBorr\u00e1 todo\u201d, sugiri\u00f3 D\u00edaz a la imputada Uliarte en comunicaciones posteriores al 1 de septiembre, despu\u00e9s de la detenci\u00f3n de Sabag Montiel tras la tentativa de homicidio. Las pruebas contra D\u00edaz, que le ser\u00e1n exhibidas antes de la declaraci\u00f3n indagatoria que tendr\u00e1 lugar este mi\u00e9rcoles, la comprometen todav\u00eda m\u00e1s porque habr\u00eda intercambiado ideas con Uliarte sobre c\u00f3mo llevar adelante un ataque contra Cristina Kirchner.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"YkTz332vCJ\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/cristina-fernandez-pidio-ser-parte-querellante-en-la-causa-por-el-atentado-en-su-contra\/\">Cristina Fern\u00e1ndez pidi\u00f3 ser parte querellante en la causa por el atentado en su contra<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abCristina Fern\u00e1ndez pidi\u00f3 ser parte querellante en la causa por el atentado en su contra\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/cristina-fernandez-pidio-ser-parte-querellante-en-la-causa-por-el-atentado-en-su-contra\/embed\/#?secret=G088JJ57dU#?secret=YkTz332vCJ\" data-secret=\"YkTz332vCJ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Seg\u00fan la agencia de noticias T\u00e9lam, de los intercambios extra\u00eddos del tel\u00e9fono celular de Uliarte surgi\u00f3 tambi\u00e9n que D\u00edaz le reproch\u00f3 con insultos que el atentado hubiera fracasado. \u201c\u00bfPor qu\u00e9 fall\u00f3 el tiro? \u00bfC\u00f3mo mandaste a este tarado? \u00bfSe puso nervioso?\u201d, le recrimin\u00f3 con vehemencia a su compa\u00f1era.<\/p>\n\n\n\n<p>Los hallazgos alteran considerablemente el curso de la investigaci\u00f3n ya que ubicar\u00edan a Brenda Uliarte en un lugar distinto al que ella declar\u00f3 cuando en su primera indagatoria asegur\u00f3 que solo hab\u00eda acompa\u00f1ado a su novio hasta la esquina de Juncal y Uruguay y que lo que hizo le parec\u00eda \u201caberrante\u201d.<\/p>\n\n\n\n<p>Luego de la detenci\u00f3n de D\u00edaz este lunes en San Miguel<strong>, se le secuestraron tres tel\u00e9fonos celulares, de los cuales solo uno estaba activo, y un chip que ser\u00eda el que contiene las conversaciones que provocaron su arresto.<\/strong><\/p>\n\n\n\n<p>Agustina D\u00edaz es una amiga de Brenda Uliarte que se comunic\u00f3 la novia del agresor luego del intento de magnicidio llevado a cabo por Fernando Sabag Montiel la noche del jueves 1\u00b0 de septiembre pasado.<\/p>\n\n\n\n<p>Su detenci\u00f3n se produjo en el contexto de tres allanamientos que se registraron en la madrugada de este martes, dos en la provincia de Buenos Aires y uno en la Capital Federal, ejecutados por efectivos de la Polic\u00eda de Seguridad Aeroportuaria (PSA).<\/p>\n\n\n\n<p>Seg\u00fan datos extra\u00eddos de los tel\u00e9fonos de los detenidos Sabag Montiel y Uliarte, ambos hablaron de alquilar un departamento frente a la casa de Cristina en Recoleta, antes de que el imputado le gatillara desde corta distancia a la ex mandataria.<\/p>\n\n\n\n<p>Si bien la mujer ser\u00eda una amiga muy cercana de Uliarte, ciertas fuentes con acceso al expediente consideran no tiene vinculaci\u00f3n con el grupo conocido como \u201cLos Copitos\u201d, dado que vend\u00edan en la v\u00eda p\u00fablica algodones de az\u00facar.<\/p>\n\n\n\n<p>Durante los allanamientos realizados en las \u00faltimas horas fueron secuestrados \u201ccelulares, dispositivos electr\u00f3nicos, y elementos de inter\u00e9s para la causa\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 13, mientras prosigue la investigaci\u00f3n del intento de magnicidio de Cristina Kirchner, se detectaron mensajes comprometedores de Agustina D\u00edaz, la tercera detenida luego del atentado fallido. La joven&hellip;<\/p>\n","protected":false},"author":3,"featured_media":200178,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,8],"tags":[],"class_list":["post-200173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Este martes 13, mientras prosigue la investigaci\u00f3n del intento de magnicidio de Cristina Kirchner, se detectaron mensajes comprometedores de Agustina D\u00edaz, la tercera detenida luego del atentado fallido. La joven&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-14T00:35:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-14T13:09:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1023\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio\",\"datePublished\":\"2022-09-14T00:35:01+00:00\",\"dateModified\":\"2022-09-14T13:09:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/\"},\"wordCount\":546,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/\",\"name\":\"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg\",\"datePublished\":\"2022-09-14T00:35:01+00:00\",\"dateModified\":\"2022-09-14T13:09:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg\",\"width\":1023,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/13\\\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/","og_locale":"es_ES","og_type":"article","og_title":"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio - Diario Textual","og_description":"Este martes 13, mientras prosigue la investigaci\u00f3n del intento de magnicidio de Cristina Kirchner, se detectaron mensajes comprometedores de Agustina D\u00edaz, la tercera detenida luego del atentado fallido. La joven&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-09-14T00:35:01+00:00","article_modified_time":"2022-09-14T13:09:54+00:00","og_image":[{"width":1023,"height":682,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio","datePublished":"2022-09-14T00:35:01+00:00","dateModified":"2022-09-14T13:09:54+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/"},"wordCount":546,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/","name":"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg","datePublished":"2022-09-14T00:35:01+00:00","dateModified":"2022-09-14T13:09:54+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/sabagmontielpistolaatenteadocristinafernandez2022-1.jpg","width":1023,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/13\/como-mandaste-a-este-tarado-el-reproche-de-agustina-diaz-luego-del-fallido-magnicidio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"\u201c\u00bfC\u00f3mo mandaste a este tarado?\u201d, el reproche de Agustina D\u00edaz luego del fallido magnicidio"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/200173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=200173"}],"version-history":[{"count":4,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/200173\/revisions"}],"predecessor-version":[{"id":200177,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/200173\/revisions\/200177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/200178"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=200173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=200173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=200173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}