{"id":201065,"date":"2022-09-21T20:48:34","date_gmt":"2022-09-21T23:48:34","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=201065"},"modified":"2022-09-21T20:48:36","modified_gmt":"2022-09-21T23:48:36","slug":"diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/","title":{"rendered":"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria"},"content":{"rendered":"\n<p>Legisladores provinciales de la comisi\u00f3n de Legislaci\u00f3n General emitieron un dictamen favorable al proyecto de Ariel Rojas y Valeria Luj\u00e1n (FreJuPa), por el que<strong> se modifican los art\u00edculos 69 y 71, de la Ley 2699, para que el reclamo de pago de la cuota alimentaria sea gratuito.<\/strong><\/p>\n\n\n\n<p>\u201c<strong>Durante el 2021 el 90% por ciento de las madres tuvieron que reclamar en la justicia para obtener la cuota alimentaria<\/strong>. El no pago constituye actos violentos contra las mujeres. Todo lo que no contribuye una parte lo solventa la otra. Los altos \u00edndices de mora son los que obligan a garantizar las cuotas alimentarias\u201d, argument\u00f3 Rojas.<\/p>\n\n\n\n<p>Y agreg\u00f3: \u201cLa<strong> intenci\u00f3n es facilitar el acceso a la justicia, para que la situaci\u00f3n econ\u00f3mica no determine las posibilidades de poder reclamar<\/strong>, con el fin de no incurrir en un doble gasto: tener que solventar el no pago de la cuota y el gasto de la justicia\u201d.<\/p>\n\n\n\n<p>La ley 2699 es por la que se cre\u00f3 en nuestra provincia la normativa de mediaci\u00f3n integral y que permite la resoluci\u00f3n alternativa de conflictos dirigido por uno o m\u00e1s mediadores con t\u00edtulo habilitante, quienes promover\u00e1n la comunicaci\u00f3n directa entre las partes. La mediaci\u00f3n puede ser voluntaria extrajudicial, voluntaria escolar u obligatoria judicial.<\/p>\n\n\n\n<p>Tambi\u00e9n sali\u00f3 por unanimidad la iniciativa por la que se crea el Perfil de Ciudadan\u00eda Pampeana Digital (CIPADI), con el objeto de centralizar y facilitar a la ciudadan\u00eda el acceso a los servicios digitales que brinda la Administraci\u00f3n P\u00fablica Provincial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Legisladores provinciales de la comisi\u00f3n de Legislaci\u00f3n General emitieron un dictamen favorable al proyecto de Ariel Rojas y Valeria Luj\u00e1n (FreJuPa), por el que se modifican los art\u00edculos 69 y&hellip;<\/p>\n","protected":false},"author":5,"featured_media":201066,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[3697],"class_list":["post-201065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad","tag-cuota-alimentaria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Legisladores provinciales de la comisi\u00f3n de Legislaci\u00f3n General emitieron un dictamen favorable al proyecto de Ariel Rojas y Valeria Luj\u00e1n (FreJuPa), por el que se modifican los art\u00edculos 69 y&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-21T23:48:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-21T23:48:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/comisioneslegislaciongeneral2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/\"},\"author\":{\"name\":\"diario3\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\"},\"headline\":\"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria\",\"datePublished\":\"2022-09-21T23:48:34+00:00\",\"dateModified\":\"2022-09-21T23:48:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/\"},\"wordCount\":271,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/comisioneslegislaciongeneral2022.jpg\",\"keywords\":[\"cuota alimentaria\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/\",\"name\":\"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/comisioneslegislaciongeneral2022.jpg\",\"datePublished\":\"2022-09-21T23:48:34+00:00\",\"dateModified\":\"2022-09-21T23:48:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/comisioneslegislaciongeneral2022.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/comisioneslegislaciongeneral2022.jpg\",\"width\":900,\"height\":535},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/09\\\/21\\\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\",\"name\":\"diario3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"caption\":\"diario3\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/","og_locale":"es_ES","og_type":"article","og_title":"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria - Diario Textual","og_description":"Legisladores provinciales de la comisi\u00f3n de Legislaci\u00f3n General emitieron un dictamen favorable al proyecto de Ariel Rojas y Valeria Luj\u00e1n (FreJuPa), por el que se modifican los art\u00edculos 69 y&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-09-21T23:48:34+00:00","article_modified_time":"2022-09-21T23:48:36+00:00","og_image":[{"width":900,"height":535,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/comisioneslegislaciongeneral2022.jpg","type":"image\/jpeg"}],"author":"diario3","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario3","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/"},"author":{"name":"diario3","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f"},"headline":"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria","datePublished":"2022-09-21T23:48:34+00:00","dateModified":"2022-09-21T23:48:36+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/"},"wordCount":271,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/comisioneslegislaciongeneral2022.jpg","keywords":["cuota alimentaria"],"articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/","name":"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/comisioneslegislaciongeneral2022.jpg","datePublished":"2022-09-21T23:48:34+00:00","dateModified":"2022-09-21T23:48:36+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/comisioneslegislaciongeneral2022.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/09\/comisioneslegislaciongeneral2022.jpg","width":900,"height":535},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/09\/21\/diputados-proponen-la-gratuidad-en-el-reclamo-del-pago-de-la-cuota-alimentaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Diputados proponen la gratuidad en el reclamo del pago de la cuota alimentaria"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f","name":"diario3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","caption":"diario3"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario3\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/201065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=201065"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/201065\/revisions"}],"predecessor-version":[{"id":201067,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/201065\/revisions\/201067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/201066"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=201065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=201065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=201065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}