{"id":204748,"date":"2022-10-25T18:31:59","date_gmt":"2022-10-25T21:31:59","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=204748"},"modified":"2022-10-25T18:32:01","modified_gmt":"2022-10-25T21:32:01","slug":"elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/","title":{"rendered":"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa"},"content":{"rendered":"\n<p>El <strong>pr\u00f3ximo mi\u00e9rcoles 9 de noviembre se realizar\u00e1 en todo el pa\u00eds las elecciones de la Central de Trabajadores y Trabajadoras de la Argentina (CTA)<\/strong>, para la renovaci\u00f3n de sus autoridades. En <strong>La Pampa la lista es encabezada por Lilia L\u00f3pez; Silvia Su\u00e1rez y Susana Pedernera.<\/strong><\/p>\n\n\n\n<p>\u201cEl acto eleccionario contar\u00e1 con la participaci\u00f3n y compromiso de un n\u00famero significativo de compa\u00f1erxs de distintos sindicatos, agrupaciones sociales, barriales que le dan forma a una Central que tiene como objetivo principal defender la Unidad Nacional y trabajar por una Justicia Social\u201d, expres\u00f3 la organizaci\u00f3n sindical en nuestra provincia y agreg\u00f3 que <strong>en La Pampa integran la CTA, los gremios de ATE, SUTEPA, UTEDYC, SITEND, UTELPa, Frente Barrial CTA, APINTA, Movimiento Enfermer\u00eda Pampeana y afiliados directos.<\/strong><\/p>\n\n\n\n<p>Los prop\u00f3sitos de la CTA para estas elecciones son:<\/p>\n\n\n\n<p>-\u201c<strong>Exigir al Estado el control y planificaci\u00f3n de la econom\u00eda<\/strong>, para dar respuestas a los m\u00e1s necesitados, que nadie en la Argentina est\u00e9 en situaci\u00f3n de pobreza, para dar respuesta al pueblo trabajador.<\/p>\n\n\n\n<p>&#8211;<strong>Terminar con las pr\u00e1cticas monop\u00f3licas y oligop\u00f3licas de los grupos concentrados de la econom\u00eda <\/strong>que provocan inflaci\u00f3n deteriorando el poder adquisitivo de toda la poblaci\u00f3n.<\/p>\n\n\n\n<p>&#8211;<strong>Impulsar una reforma tributaria integral progresiva<\/strong>, incrementando los grav\u00e1menes sobre los sectores de mayores ingresos, para una justa distribuci\u00f3n de las riquezas.<\/p>\n\n\n\n<p><strong>-Implementar de manera efectiva la Ley de Medios oportunamente sancionada por el Congreso <\/strong>de la Naci\u00f3n y avanzar en una Reforma Judicial y de la Corte Suprema de Justicia.<\/p>\n\n\n\n<p>-Promover las pol\u00edticas del cuidado, en clave de derechos humanos, y desde una perspectiva de g\u00e9nero.<\/p>\n\n\n\n<p>-En defensa de los r\u00edos interprovinciales, y de la soberan\u00eda popular sobre los recursos naturales, y en defensa de las pol\u00edticas p\u00fablicas de crecimiento sostenible.<\/p>\n\n\n\n<p>-Retomar con fuerza la unidad entre los pueblos hermanos de la Patria Grande.<\/p>\n\n\n\n<p>-Construimos una Central comprometida en defender los derechos de todxs lxs trabajadores de este pa\u00eds, en defender las pol\u00edticas p\u00fablicas inclusivas.<\/p>\n\n\n\n<p>-Es un momento clave para que todo el movimiento sindical, las organizaciones sociales y pol\u00edticas pensemos juntos el camino de la solidaridad, para lograr una soberan\u00eda plena, y nuestra independencia Real. Sin ellas no hay Naci\u00f3n, Democracia, ni Justicia Social\u201d.<\/p>\n\n\n\n<p>La<strong> lista 10 a nivel Nacional estar\u00e1 encabezada por Hugo Yasky, Daniel Catalano y Edgardo Llano<\/strong> y tendr\u00e1 enfrente a la <strong>lista Multicolor, quien llevar\u00e1 como candidata a secretaria general a Patricia Jur\u00e9 de Aten, a Daniela Vergara de Amsafe y Andrea Lanzette de Suteba<\/strong>, como secretarias adjuntas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo mi\u00e9rcoles 9 de noviembre se realizar\u00e1 en todo el pa\u00eds las elecciones de la Central de Trabajadores y Trabajadoras de la Argentina (CTA), para la renovaci\u00f3n de sus&hellip;<\/p>\n","protected":false},"author":5,"featured_media":204749,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[449,125],"class_list":["post-204748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad","tag-cta","tag-elecciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo mi\u00e9rcoles 9 de noviembre se realizar\u00e1 en todo el pa\u00eds las elecciones de la Central de Trabajadores y Trabajadoras de la Argentina (CTA), para la renovaci\u00f3n de sus&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T21:31:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-25T21:32:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/CTAlista2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"547\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/\"},\"author\":{\"name\":\"diario3\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\"},\"headline\":\"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa\",\"datePublished\":\"2022-10-25T21:31:59+00:00\",\"dateModified\":\"2022-10-25T21:32:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/\"},\"wordCount\":452,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/CTAlista2022.jpg\",\"keywords\":[\"CTA\",\"elecciones\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/\",\"name\":\"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/CTAlista2022.jpg\",\"datePublished\":\"2022-10-25T21:31:59+00:00\",\"dateModified\":\"2022-10-25T21:32:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/CTAlista2022.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/CTAlista2022.jpg\",\"width\":900,\"height\":547},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\",\"name\":\"diario3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"caption\":\"diario3\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/","og_locale":"es_ES","og_type":"article","og_title":"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa - Diario Textual","og_description":"El pr\u00f3ximo mi\u00e9rcoles 9 de noviembre se realizar\u00e1 en todo el pa\u00eds las elecciones de la Central de Trabajadores y Trabajadoras de la Argentina (CTA), para la renovaci\u00f3n de sus&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-10-25T21:31:59+00:00","article_modified_time":"2022-10-25T21:32:01+00:00","og_image":[{"width":900,"height":547,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/CTAlista2022.jpg","type":"image\/jpeg"}],"author":"diario3","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario3","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/"},"author":{"name":"diario3","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f"},"headline":"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa","datePublished":"2022-10-25T21:31:59+00:00","dateModified":"2022-10-25T21:32:01+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/"},"wordCount":452,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/CTAlista2022.jpg","keywords":["CTA","elecciones"],"articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/","name":"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/CTAlista2022.jpg","datePublished":"2022-10-25T21:31:59+00:00","dateModified":"2022-10-25T21:32:01+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/CTAlista2022.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/CTAlista2022.jpg","width":900,"height":547},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/elecciones-en-la-cta-lilia-lopez-encabeza-lista-en-la-pampa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Elecciones en la CTA: Lilia L\u00f3pez encabeza lista en La Pampa"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f","name":"diario3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","caption":"diario3"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario3\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/204748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=204748"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/204748\/revisions"}],"predecessor-version":[{"id":204750,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/204748\/revisions\/204750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/204749"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=204748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=204748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=204748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}