{"id":204757,"date":"2022-10-25T19:00:31","date_gmt":"2022-10-25T22:00:31","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=204757"},"modified":"2022-10-25T19:00:32","modified_gmt":"2022-10-25T22:00:32","slug":"lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/","title":{"rendered":"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza"},"content":{"rendered":"\n<p>Este mi\u00e9rcoles se present\u00f3 <strong>una nueva edici\u00f3n de la Fiesta Pampeana de la Cerveza<\/strong> y que en este caso ser\u00e1 en Lonquimay, el <strong>pr\u00f3ximo s\u00e1bado 5 de noviembre<\/strong>. <strong>La entrada costar\u00e1 1500 pesos y habr\u00e1 transporte gratuito.<\/strong><\/p>\n\n\n\n<p>En el auditorio del CC Medasur, la secretaria de Cultura Adriana Maggio acompa\u00f1\u00f3 a integrantes de la Asociaci\u00f3n Descendientes de Alemanes de La Pampa; a Silvia Canulli, directora de Cultura de la Municipalidad de Lonquimay y a Mario D\u00edaz, vicepresidente del Lonquimay Club, en la presentaci\u00f3n de la 18\u00b0 edici\u00f3n.<\/p>\n\n\n\n<p>Melina Weiman, presidenta de la Asociaci\u00f3n, cont\u00f3 que esta fiesta es \u00fanica en La Pampa con esta caracter\u00edstica: \u201c<strong>Tiene la particularidad de tener una sede distinta en cada edici\u00f3n<\/strong>. Este a\u00f1o se hace en el Club Lonquimay, donde vamos a <strong>disfrutar de la m\u00fasica a cargo del Grupo Austral, el Ballet de Danzas \u2018Edelweiss\u2019 que viene desde la ciudad de La Plata<\/strong>, distintos tipos de cervezas artesanales y el tradicional espiche del barril. Adem\u00e1s de ofertas gastron\u00f3micas de la colectividad y el desfile tradicional con vestimenta t\u00edpica, entre otras sorpresas. Van a estar disponibles distintas cervezas que se producen en La Pampa y se presentar\u00e1 una variedad de uno de los integrante del Comisi\u00f3n\u201d.<\/p>\n\n\n\n<p>La entrada tendr\u00e1 un valor de $1.500 y <strong>los menores de 8 a\u00f1os no pagan. Para la fiesta se pondr\u00e1 a disposici\u00f3n transporte gratis para que las personas puedan asistir, consumir cerveza y regresar<\/strong> de manera segura.<\/p>\n\n\n\n<p>Aquellos interesados podr\u00e1n encontrar todos los <strong>detalles e informaci\u00f3n en la p\u00e1gina de la Asociaci\u00f3n Descendientes de Alemanes de La Pampa.<\/strong><\/p>\n\n\n\n<p>Acerca de la fiesta, Adriana Maggio dijo: \u201cEstamos en un clima de alegr\u00eda, ya que esta fiesta se suma a otras, marcando la temporada de fiestas populares que empiezan a desarrollarse en toda la Provincia\u201d.<\/p>\n\n\n\n<p>\u201cUna felicidad plena porque significa trabajo para los artistas, significa movimiento econ\u00f3mico y fundamentalmente significa el encuentro de la gente y para entender que solamente de manera colectiva y desde y con todas las colectividades de todos los or\u00edgenes, podemos hacer una provincia donde vivamos m\u00e1s felices y mejor. La cerveza artesanal se ha convertido en un producto de la industrial cultural que est\u00e1 dando mucho trabajo, impulsando a muchos emprendedores en este rubro, y esto da cuenta de que la cultura no es un gasto, sino que tambi\u00e9n aporta a la econom\u00eda de las regiones\u201d, agreg\u00f3 la funcionaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles se present\u00f3 una nueva edici\u00f3n de la Fiesta Pampeana de la Cerveza y que en este caso ser\u00e1 en Lonquimay, el pr\u00f3ximo s\u00e1bado 5 de noviembre. La entrada&hellip;<\/p>\n","protected":false},"author":5,"featured_media":204759,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,2],"tags":[7310,798],"class_list":["post-204757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-cultura","tag-fiesta-de-la-cerveza","tag-lonquimay"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Este mi\u00e9rcoles se present\u00f3 una nueva edici\u00f3n de la Fiesta Pampeana de la Cerveza y que en este caso ser\u00e1 en Lonquimay, el pr\u00f3ximo s\u00e1bado 5 de noviembre. La entrada&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T22:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-25T22:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/fiestadelacervezalonquimay.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"844\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/\"},\"author\":{\"name\":\"diario3\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\"},\"headline\":\"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza\",\"datePublished\":\"2022-10-25T22:00:31+00:00\",\"dateModified\":\"2022-10-25T22:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/\"},\"wordCount\":430,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/fiestadelacervezalonquimay.jpg\",\"keywords\":[\"fiesta de la cerveza\",\"lonquimay\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"CULTURA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/\",\"name\":\"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/fiestadelacervezalonquimay.jpg\",\"datePublished\":\"2022-10-25T22:00:31+00:00\",\"dateModified\":\"2022-10-25T22:00:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/fiestadelacervezalonquimay.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/fiestadelacervezalonquimay.jpg\",\"width\":844,\"height\":507},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/10\\\/25\\\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/a1b6f563e0ee944c60f98119389a4d9f\",\"name\":\"diario3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g\",\"caption\":\"diario3\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/","og_locale":"es_ES","og_type":"article","og_title":"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza - Diario Textual","og_description":"Este mi\u00e9rcoles se present\u00f3 una nueva edici\u00f3n de la Fiesta Pampeana de la Cerveza y que en este caso ser\u00e1 en Lonquimay, el pr\u00f3ximo s\u00e1bado 5 de noviembre. La entrada&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-10-25T22:00:31+00:00","article_modified_time":"2022-10-25T22:00:32+00:00","og_image":[{"width":844,"height":507,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/fiestadelacervezalonquimay.jpg","type":"image\/jpeg"}],"author":"diario3","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario3","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/"},"author":{"name":"diario3","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f"},"headline":"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza","datePublished":"2022-10-25T22:00:31+00:00","dateModified":"2022-10-25T22:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/"},"wordCount":430,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/fiestadelacervezalonquimay.jpg","keywords":["fiesta de la cerveza","lonquimay"],"articleSection":["A - ES NOTICIA (van abajo)","CULTURA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/","name":"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/fiestadelacervezalonquimay.jpg","datePublished":"2022-10-25T22:00:31+00:00","dateModified":"2022-10-25T22:00:32+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/fiestadelacervezalonquimay.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/10\/fiestadelacervezalonquimay.jpg","width":844,"height":507},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/10\/25\/lonquimay-sede-de-la-18-edicion-de-la-fiesta-pampeana-de-la-cerveza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Lonquimay, sede de la 18\u00b0 edici\u00f3n de la Fiesta Pampeana de la Cerveza"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/a1b6f563e0ee944c60f98119389a4d9f","name":"diario3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e7ee62c82fc04d9dd79d746a390d93c69c43223e5faeeb3ea9461ef752bfc5d?s=96&d=mm&r=g","caption":"diario3"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario3\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/204757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=204757"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/204757\/revisions"}],"predecessor-version":[{"id":204760,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/204757\/revisions\/204760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/204759"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=204757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=204757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=204757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}