{"id":208800,"date":"2022-11-30T11:45:52","date_gmt":"2022-11-30T14:45:52","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=208800"},"modified":"2022-11-30T17:03:15","modified_gmt":"2022-11-30T20:03:15","slug":"una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/","title":{"rendered":"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre"},"content":{"rendered":"\n<p><strong>Micaela Cuta <\/strong>dice que tiene miedo. \u201cEl 8 de diciembre mi ex ya cumple la condena por haber incendiado mi casa, con nosotros adentro, y la Justicia no me ha dado ninguna orden de restricci\u00f3n\u201d, dice a Diario Textual. <strong>\u201cMis hijos y yo estamos en riesgo\u201d<\/strong>, agrega.<\/p>\n\n\n\n<p>\u201cYa me reun\u00ed con la gente de la Fiscal\u00eda para pedirles que le pongan una orden de restricci\u00f3n o tener algo para que podamos estar tranquilos en nuestra casa o salir a la calle normalmente. Pero me dicen que no pueden hacer nada\u201d, sostiene.<\/p>\n\n\n\n<p>El atentado ocurri\u00f3 en diciembre de 2017 en una vivienda de Villa Santill\u00e1n, en Pestalozzi, entre P\u00edo XII y Chile. Es la casa de Mar\u00eda Alfonso, la madre de Micaela Cuta, ex de Carra.<\/p>\n\n\n\n<p>El exmilitar <strong>Brian Ezequiel Carra<\/strong> fue condenado a 5 a\u00f1os de c\u00e1rcel por haber quemado la casa donde se encontraban familiares de su expareja e incluso sus propios hijos. Hoy tiene salidas transitorias y reside en Villa Gesell, en la casa de una t\u00eda. Pero la intenci\u00f3n de Carra, seg\u00fan Cuta, es radicarse a seis cuadras de la casa que destruy\u00f3. \u201cYa me informaron desde la Justicia que va a fijar domicilio en la casa de su padre\u201d, sostiene.<\/p>\n\n\n\n<p>Cuta y Carra tienen tres hijos, de 8, 10 y 11 a\u00f1os de edad. Por uno de ellos, incluso, Cuta denunci\u00f3 situaciones de violencia contra el exmilitar. Pero esa causa no ha avanzado: es que, para los peritos, el peque\u00f1o -que incluso sufre de disdrofia, por lo que ya ve muy poco- no est\u00e1 a\u00fan preparado para afrontar una C\u00e1mara Gesell.<\/p>\n\n\n\n<p>Cuta denunci\u00f3 en 32 oportunidades a su ex. La \u00faltima denuncia la hizo un d\u00eda antes de que le quemara la casa. \u201cYo estoy aterrorizada\u201d, asegura.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"U66J3TrJSQ\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/06\/23\/la-corte-confirmo-la-condena-al-exmilitar-que-incendio-la-casa-de-su-ex\/\">La Corte confirm\u00f3 la condena al exmilitar que incendi\u00f3 la casa de su ex<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abLa Corte confirm\u00f3 la condena al exmilitar que incendi\u00f3 la casa de su ex\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2021\/06\/23\/la-corte-confirmo-la-condena-al-exmilitar-que-incendio-la-casa-de-su-ex\/embed\/#?secret=RRi5nKgVPj#?secret=U66J3TrJSQ\" data-secret=\"U66J3TrJSQ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Micaela Cuta dice que tiene miedo. \u201cEl 8 de diciembre mi ex ya cumple la condena por haber incendiado mi casa, con nosotros adentro, y la Justicia no me ha&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-208800","post","type-post","status-publish","format-standard","hentry","category-es-noticia","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Micaela Cuta dice que tiene miedo. \u201cEl 8 de diciembre mi ex ya cumple la condena por haber incendiado mi casa, con nosotros adentro, y la Justicia no me ha&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-30T14:45:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-30T20:03:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/11\/cutamicaela002.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/11\\\/30\\\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/11\\\/30\\\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre\",\"datePublished\":\"2022-11-30T14:45:52+00:00\",\"dateModified\":\"2022-11-30T20:03:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/11\\\/30\\\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\\\/\"},\"wordCount\":324,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/11\\\/30\\\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/11\\\/30\\\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\\\/\",\"name\":\"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"datePublished\":\"2022-11-30T14:45:52+00:00\",\"dateModified\":\"2022-11-30T20:03:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/11\\\/30\\\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/11\\\/30\\\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/11\\\/30\\\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/","og_locale":"es_ES","og_type":"article","og_title":"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre - Diario Textual","og_description":"Micaela Cuta dice que tiene miedo. \u201cEl 8 de diciembre mi ex ya cumple la condena por haber incendiado mi casa, con nosotros adentro, y la Justicia no me ha&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-11-30T14:45:52+00:00","article_modified_time":"2022-11-30T20:03:15+00:00","og_image":[{"width":1080,"height":693,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/11\/cutamicaela002.png","type":"image\/png"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre","datePublished":"2022-11-30T14:45:52+00:00","dateModified":"2022-11-30T20:03:15+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/"},"wordCount":324,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/","name":"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"datePublished":"2022-11-30T14:45:52+00:00","dateModified":"2022-11-30T20:03:15+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/30\/una-mujer-pide-medidas-de-proteccion-su-ex-le-quemo-la-casa-y-ahora-queda-libre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Una mujer pide medidas de protecci\u00f3n: su ex le quem\u00f3 la casa y ahora queda libre"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/208800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=208800"}],"version-history":[{"count":3,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/208800\/revisions"}],"predecessor-version":[{"id":208803,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/208800\/revisions\/208803"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=208800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=208800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=208800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}