{"id":208907,"date":"2022-12-01T09:52:09","date_gmt":"2022-12-01T12:52:09","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=208907"},"modified":"2022-12-01T12:18:34","modified_gmt":"2022-12-01T15:18:34","slug":"aumentaron-un-4-las-naftas-y-el-gasoil","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/","title":{"rendered":"Shell y Axion aumentaron un 4% las naftas y el gasoil"},"content":{"rendered":"\n<p>Las petroleras Shell y Axion aumentaron un 4% sus combustibles desde la primera hora de este jueves. YPF por el momento no aplicar\u00e1 la suba. <\/p>\n\n\n\n<p>El 4% se trata del\u00a0tope m\u00e1ximo que estableci\u00f3 el Gobierno a partir de diciembre.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"og7s6DhDlg\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/27\/los-combustibles-se-suman-al-programa-de-precios-justos\/\">Los combustibles se suman al programa de Precios Justos<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abLos combustibles se suman al programa de Precios Justos\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/27\/los-combustibles-se-suman-al-programa-de-precios-justos\/embed\/#?secret=5LnjTavf8O#?secret=og7s6DhDlg\" data-secret=\"og7s6DhDlg\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Las empresas Shell y Axion ya anunciaron que se sumar\u00e1n al incremento de nafta y gasoil, mientras que YPF no lo har\u00e1 por el momento.&nbsp;El Gobierno hab\u00eda establecido un m\u00e1ximo de suba por cuatro meses. Despu\u00e9s de su medida, lleg\u00f3 la&nbsp;sexta actualizaci\u00f3n de los precios&nbsp;en lo que va de 2022.&nbsp;<\/p>\n\n\n\n<p>La decisi\u00f3n fue oficializada el lunes y cont\u00f3 con la firma del ministro de Econom\u00eda, Sergio Massa, y los referentes de las principales compa\u00f1\u00edas petroleras, quienes brindaron su compromiso a cambio de la promesa del Gobierno de que tendr\u00edan&nbsp;acceso a d\u00f3lares para conseguir insumos y aplazar los impuestos al combustible.<\/p>\n\n\n\n<p>Seg\u00fan se estipul\u00f3, con la idea en el plano de incorporar a los combustibles en el programa Precios Justos, la nafta y el gasoil podr\u00e1n subir hasta un 4% en diciembre, enero y febrero, pero en marzo est\u00e1 permitido hasta un 3,5%.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"GzlutqfIMr\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/28\/combustibles-en-precios-justos-una-medida-innecesaria-dicen-estacioneros-pampeanos\/\">Combustibles en Precios Justos: \u201cUna medida innecesaria\u201d, dicen estacioneros pampeanos<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abCombustibles en Precios Justos: \u201cUna medida innecesaria\u201d, dicen estacioneros pampeanos\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/11\/28\/combustibles-en-precios-justos-una-medida-innecesaria-dicen-estacioneros-pampeanos\/embed\/#?secret=rFG11kiIdK#?secret=GzlutqfIMr\" data-secret=\"GzlutqfIMr\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Las petroleras Shell y Axion aumentaron un 4% sus combustibles desde la primera hora de este jueves. YPF por el momento no aplicar\u00e1 la suba. El 4% se trata del\u00a0tope&hellip;<\/p>\n","protected":false},"author":7,"featured_media":116759,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-208907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shell y Axion aumentaron un 4% las naftas y el gasoil - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shell y Axion aumentaron un 4% las naftas y el gasoil - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Las petroleras Shell y Axion aumentaron un 4% sus combustibles desde la primera hora de este jueves. YPF por el momento no aplicar\u00e1 la suba. El 4% se trata del\u00a0tope&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-01T12:52:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-01T15:18:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/10\/naftascombustiblesgasoilestacionesypf2020-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"862\" \/>\n\t<meta property=\"og:image:height\" content=\"544\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/\"},\"author\":{\"name\":\"diario5\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\"},\"headline\":\"Shell y Axion aumentaron un 4% las naftas y el gasoil\",\"datePublished\":\"2022-12-01T12:52:09+00:00\",\"dateModified\":\"2022-12-01T15:18:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/\"},\"wordCount\":223,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/naftascombustiblesgasoilestacionesypf2020-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/\",\"name\":\"Shell y Axion aumentaron un 4% las naftas y el gasoil - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/naftascombustiblesgasoilestacionesypf2020-1.jpg\",\"datePublished\":\"2022-12-01T12:52:09+00:00\",\"dateModified\":\"2022-12-01T15:18:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/naftascombustiblesgasoilestacionesypf2020-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/naftascombustiblesgasoilestacionesypf2020-1.jpg\",\"width\":862,\"height\":544},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2022\\\/12\\\/01\\\/aumentaron-un-4-las-naftas-y-el-gasoil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shell y Axion aumentaron un 4% las naftas y el gasoil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\",\"name\":\"diario5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"caption\":\"diario5\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shell y Axion aumentaron un 4% las naftas y el gasoil - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/","og_locale":"es_ES","og_type":"article","og_title":"Shell y Axion aumentaron un 4% las naftas y el gasoil - Diario Textual","og_description":"Las petroleras Shell y Axion aumentaron un 4% sus combustibles desde la primera hora de este jueves. YPF por el momento no aplicar\u00e1 la suba. El 4% se trata del\u00a0tope&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2022-12-01T12:52:09+00:00","article_modified_time":"2022-12-01T15:18:34+00:00","og_image":[{"width":862,"height":544,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/10\/naftascombustiblesgasoilestacionesypf2020-1.jpg","type":"image\/jpeg"}],"author":"diario5","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario5","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/"},"author":{"name":"diario5","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067"},"headline":"Shell y Axion aumentaron un 4% las naftas y el gasoil","datePublished":"2022-12-01T12:52:09+00:00","dateModified":"2022-12-01T15:18:34+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/"},"wordCount":223,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/10\/naftascombustiblesgasoilestacionesypf2020-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/","name":"Shell y Axion aumentaron un 4% las naftas y el gasoil - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/10\/naftascombustiblesgasoilestacionesypf2020-1.jpg","datePublished":"2022-12-01T12:52:09+00:00","dateModified":"2022-12-01T15:18:34+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/10\/naftascombustiblesgasoilestacionesypf2020-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/10\/naftascombustiblesgasoilestacionesypf2020-1.jpg","width":862,"height":544},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2022\/12\/01\/aumentaron-un-4-las-naftas-y-el-gasoil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Shell y Axion aumentaron un 4% las naftas y el gasoil"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067","name":"diario5","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","caption":"diario5"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario5\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/208907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=208907"}],"version-history":[{"count":3,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/208907\/revisions"}],"predecessor-version":[{"id":208915,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/208907\/revisions\/208915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/116759"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=208907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=208907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=208907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}