{"id":213515,"date":"2023-01-18T17:15:21","date_gmt":"2023-01-18T20:15:21","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=213515"},"modified":"2023-01-18T17:15:23","modified_gmt":"2023-01-18T20:15:23","slug":"cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/","title":{"rendered":"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online"},"content":{"rendered":"\n<p>La Cooperativa Popular de Electricidad (CPE) record\u00f3 que vuelven a estar vigentes las alternativas de pago de facturas en locales de <strong>\u201cRapiPago\u201d y el \u201cbot\u00f3n de pago\u201d para operaciones online<\/strong> . Estas dos formas de pago hab\u00edan quedado suspendidas a mediados de diciembre por inconvenientes en el sistema de la empresa privada prestadora de estos servicios a nivel nacional.<\/p>\n\n\n\n<p>Hay varias maneras de abonar las facturas cooperativas online. Una es visitar el sitio web&nbsp;<a href=\"http:\/\/www.cpe.com.ar\/\" rel=\"noreferrer noopener\" target=\"_blank\">www.cpe.com.ar<\/a>&nbsp;y elegir el \u00edcono \u201cPagar\u201d, para acceder a \u201cMi Usuario CPE\u201d. Otra forma es desde los celulares, con la aplicaci\u00f3n \u201cCPE\u201d, que se descarga gratuitamente de las tiendas \u201cPlay Store\u201d o \u201cApple Store\u201d. Una vez instalada la aplicaci\u00f3n, hay que abrirla, registrarse y dirigirse al men\u00fa \u201cServicios y Facturaci\u00f3n\u201d, opci\u00f3n \u201cPagar facturas\u201d.<\/p>\n\n\n\n<p>Es posible adem\u00e1s abonar los servicios desde cajeros autom\u00e1ticos de la Red Link o el homebanking de entidades financieras adheridas a esa red; los cajeros autom\u00e1ticos de Red Banelco, Banelco M\u00f3vil o la plataforma PagoMisCuentas. Tambi\u00e9n se puede pagar a trav\u00e9s del d\u00e9bito autom\u00e1tico de la tarjeta de cr\u00e9dito Mastercard del Banco de La Pampa. Otros lugares son las sucursales de Banco de La Pampa, el Banco Naci\u00f3n y las agencias de PampaPagos o PagoF\u00e1cil.<\/p>\n\n\n\n<p>Como siempre, las facturas tambi\u00e9n se pueden abonar en las cajas de la misma CPE: en Santa Rosa en el sal\u00f3n La Usina (1\u00ba de Mayo casi Ra\u00fal B. D\u00edaz), en el Centro \u201cCarlos Lorenzo\u201d (Jos\u00e9 Luro y Per\u00fa), y en las oficinas de cada una de las localidades interconectadas (Anguil, Ataliva Roca, Uriburu, Lonquimay, Catril\u00f3, Mauricio Mayer y Toay).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cooperativa Popular de Electricidad (CPE) record\u00f3 que vuelven a estar vigentes las alternativas de pago de facturas en locales de \u201cRapiPago\u201d y el \u201cbot\u00f3n de pago\u201d para operaciones online&hellip;<\/p>\n","protected":false},"author":4,"featured_media":212993,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-213515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"La Cooperativa Popular de Electricidad (CPE) record\u00f3 que vuelven a estar vigentes las alternativas de pago de facturas en locales de \u201cRapiPago\u201d y el \u201cbot\u00f3n de pago\u201d para operaciones online&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-18T20:15:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-18T20:15:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/01\/cpeopcionesdepago.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/\"},\"author\":{\"name\":\"diario2\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\"},\"headline\":\"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online\",\"datePublished\":\"2023-01-18T20:15:21+00:00\",\"dateModified\":\"2023-01-18T20:15:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/\"},\"wordCount\":300,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cpeopcionesdepago.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/\",\"name\":\"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cpeopcionesdepago.jpg\",\"datePublished\":\"2023-01-18T20:15:21+00:00\",\"dateModified\":\"2023-01-18T20:15:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cpeopcionesdepago.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cpeopcionesdepago.jpg\",\"width\":700,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/01\\\/18\\\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\",\"name\":\"diario2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"caption\":\"diario2\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/","og_locale":"es_ES","og_type":"article","og_title":"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online - Diario Textual","og_description":"La Cooperativa Popular de Electricidad (CPE) record\u00f3 que vuelven a estar vigentes las alternativas de pago de facturas en locales de \u201cRapiPago\u201d y el \u201cbot\u00f3n de pago\u201d para operaciones online&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2023-01-18T20:15:21+00:00","article_modified_time":"2023-01-18T20:15:23+00:00","og_image":[{"width":700,"height":500,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/01\/cpeopcionesdepago.jpg","type":"image\/jpeg"}],"author":"diario2","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario2","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/"},"author":{"name":"diario2","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768"},"headline":"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online","datePublished":"2023-01-18T20:15:21+00:00","dateModified":"2023-01-18T20:15:23+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/"},"wordCount":300,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/01\/cpeopcionesdepago.jpg","articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/","name":"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/01\/cpeopcionesdepago.jpg","datePublished":"2023-01-18T20:15:21+00:00","dateModified":"2023-01-18T20:15:23+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/01\/cpeopcionesdepago.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/01\/cpeopcionesdepago.jpg","width":700,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/01\/18\/cpe-se-rehabilitaron-las-opciones-de-rapipago-y-el-boton-de-pago-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"CPE: se rehabilitaron las opciones de Rapipago y el bot\u00f3n de pago online"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768","name":"diario2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","caption":"diario2"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario2\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/213515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=213515"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/213515\/revisions"}],"predecessor-version":[{"id":213516,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/213515\/revisions\/213516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/212993"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=213515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=213515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=213515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}