{"id":21650,"date":"2018-09-27T16:36:33","date_gmt":"2018-09-27T19:36:33","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=21650"},"modified":"2018-09-27T20:52:35","modified_gmt":"2018-09-27T23:52:35","slug":"segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/","title":{"rendered":"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2%"},"content":{"rendered":"<p>El Instituto Nacional de Estad\u00edsticas y Censos revel\u00f3 esta tarde los n\u00fameros de la pobreza y la indigencia en el pa\u00eds en el primer semestre de 2018. En el aglomerado Santa Rosa-Toay la pobreza alcanz\u00f3 el 26,3% y la indigencia el 4,2%.<\/p>\n<p>Los resultados provienen de la informaci\u00f3n de la Encuesta Permanente de Hogares y la valorizaci\u00f3n de la canasta b\u00e1sica alimentaria y de la canasta b\u00e1sica total.<\/p>\n<p>A nivel pa\u00eds, la pobreza se ubic\u00f3 en el 27,3%, mientras que la indigencia fue del 4,9%.<\/p>\n<p>En Santa Rosa-Toay se registraron 38.818 personas pobres y 5.207 indigentes.<\/p>\n<p>Si se compara con igual per\u00edodo de 2017, hubo una disminuci\u00f3n de la pobreza: de 27,4% baj\u00f3 a 26,3%. Pero la indigencia subi\u00f3 de 4,1% a 4,2%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Nacional de Estad\u00edsticas y Censos revel\u00f3 esta tarde los n\u00fameros de la pobreza y la indigencia en el pa\u00eds en el primer semestre de 2018. En el aglomerado&hellip;<\/p>\n","protected":false},"author":7,"featured_media":3238,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[319,12],"tags":[],"class_list":["post-21650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-temporales","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2% - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2% - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El Instituto Nacional de Estad\u00edsticas y Censos revel\u00f3 esta tarde los n\u00fameros de la pobreza y la indigencia en el pa\u00eds en el primer semestre de 2018. En el aglomerado&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-27T19:36:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-27T23:52:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/pobrezasantarosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/\"},\"author\":{\"name\":\"diario5\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\"},\"headline\":\"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2%\",\"datePublished\":\"2018-09-27T19:36:33+00:00\",\"dateModified\":\"2018-09-27T23:52:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/\"},\"wordCount\":135,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/pobrezasantarosa.jpg\",\"articleSection\":[\"A - TEMPORALES\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/\",\"name\":\"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2% - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/pobrezasantarosa.jpg\",\"datePublished\":\"2018-09-27T19:36:33+00:00\",\"dateModified\":\"2018-09-27T23:52:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/pobrezasantarosa.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/pobrezasantarosa.jpg\",\"width\":675,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/27\\\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\",\"name\":\"diario5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"caption\":\"diario5\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2% - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/","og_locale":"es_ES","og_type":"article","og_title":"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2% - Diario Textual","og_description":"El Instituto Nacional de Estad\u00edsticas y Censos revel\u00f3 esta tarde los n\u00fameros de la pobreza y la indigencia en el pa\u00eds en el primer semestre de 2018. En el aglomerado&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2018-09-27T19:36:33+00:00","article_modified_time":"2018-09-27T23:52:35+00:00","og_image":[{"width":675,"height":450,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/pobrezasantarosa.jpg","type":"image\/jpeg"}],"author":"diario5","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario5","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/"},"author":{"name":"diario5","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067"},"headline":"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2%","datePublished":"2018-09-27T19:36:33+00:00","dateModified":"2018-09-27T23:52:35+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/"},"wordCount":135,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/pobrezasantarosa.jpg","articleSection":["A - TEMPORALES","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/","name":"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2% - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/pobrezasantarosa.jpg","datePublished":"2018-09-27T19:36:33+00:00","dateModified":"2018-09-27T23:52:35+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/pobrezasantarosa.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/pobrezasantarosa.jpg","width":675,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/27\/segun-indec-la-pobreza-santa-rosa-toay-del-263-la-indigencia-42\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Seg\u00fan el Indec, la pobreza en Santa Rosa-Toay es del 26,3% y la indigencia 4,2%"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067","name":"diario5","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","caption":"diario5"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario5\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/21650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=21650"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/21650\/revisions"}],"predecessor-version":[{"id":21669,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/21650\/revisions\/21669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/3238"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=21650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=21650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=21650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}