{"id":21702,"date":"2018-09-28T04:27:06","date_gmt":"2018-09-28T07:27:06","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=21702"},"modified":"2018-09-28T10:16:21","modified_gmt":"2018-09-28T13:16:21","slug":"archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/","title":{"rendered":"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA"},"content":{"rendered":"<p>El fiscal general de Santa Rosa,<strong> Guillermo Sancho<\/strong>, intervino en la causa penal por las presuntas irregularidades en la <strong>licitaci\u00f3n del Acueducto del Colorado Norte<\/strong> y<strong> desestim\u00f3 el planteo<\/strong> que hizo el fiscal de Investigaciones Administrativas,<strong> Juan Carlos Carola<\/strong>, para que <strong>la causa no sea archivada<\/strong>. Ahora, as\u00ed,<strong> solo resta la firma de un juez de control para que se concluya la investigaci\u00f3n contra el exgobernador Oscar Jorge y los exministros Jorge Varela y Sergio Violo<\/strong>.<\/p>\n<p>Sancho, al intervenir,<strong> sostuvo que el titular de la FIA, Juan Carlos Carola, \u201cno est\u00e1 legitimado\u00bb para oponerse a un archivo<\/strong>.<\/p>\n<p>La FIA hab\u00eda denunciado el 3 de octubre de 2016 la presunta comisi\u00f3n de los delitos de abuso de autoridad, incumplimiento de los deberes de funcionario p\u00fablico, administraci\u00f3n fraudulenta y falsedad ideol\u00f3gica por parte de Jorge, Violo y Varela, firmantes del Decreto 34\/2013.<\/p>\n<p>Esta fiscal\u00eda le apunt\u00f3 a los funcionarios provinciales por seguir con las negociaciones para la construcci\u00f3n de un acueducto a pesar de que la empresa ganadora, la UTE formada por las firmas Supercemento y la brasile\u00f1a OAS, no cumpli\u00f3 con el primer contrato que la obligaba a aportar el financiamiento.<\/p>\n<p>La obra, igual, nunca se hizo. Sin embargo,<strong> para la FIA hubo un \u201cardid\u201d y un perjuicio, el monto del 10% de adelanto financiero que aun reclama Supercemento.<\/strong><\/p>\n<p>La FIA asegur\u00f3 que se violaron las leyes de obras P\u00fablicas N\u00ba 38, la de Contabilidad N\u00ba 3, la del Tribunal de Cuentas N\u00ba 513\/69 y la Ley Org\u00e1nica de la Asesor\u00eda Letrada de Gobierno.<\/p>\n<p><strong>El fiscal M\u00e1ximo Paulucci recientemente pidi\u00f3 el archivo de la causa.<\/strong> Argument\u00f3 que las irregularidades en el expediente \u201cfueron manifiestas\u201d (\u201cteniendo la publicidad que se le ha dado al tr\u00e1mite de adjudicaci\u00f3n\u201d, dijo el fiscal) pero que no deben ser alcanzadas por el Derecho Penal.\u00a0\u00a0Es decir, consider\u00f3 que no hay configurados delitos porque, entre otros puntos, no hay dolo, es decir, intencionalidad.<\/p>\n<p>Paulucci sostuvo que tampoco se puede acusar a Jorge de incumplimiento de los deberes de funcionario p\u00fabico. La FIA hab\u00eda apuntado a Jorge porque no reinici\u00f3 todo el acto administrativo una vez que se cay\u00f3. Adem\u00e1s, la FIA sostuvo que Jorge, Varela y Violo no pod\u00edan desconocer que la preadjudicaci\u00f3n que firmaban no era la que conform\u00f3 el Tribunal de Cuentas y que se apartaban del pliego.<\/p>\n<p>Frente a ese pedido de archivo<strong>, la FIA reaccion\u00f3 y pidi\u00f3 que se siga investigando. Pero ahora Sancho le dijo que no tiene legitimidad para oponerse.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fiscal general de Santa Rosa, Guillermo Sancho, intervino en la causa penal por las presuntas irregularidades en la licitaci\u00f3n del Acueducto del Colorado Norte y desestim\u00f3 el planteo que&hellip;<\/p>\n","protected":false},"author":3,"featured_media":21703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,319,12],"tags":[],"class_list":["post-21702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-a-temporales","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El fiscal general de Santa Rosa, Guillermo Sancho, intervino en la causa penal por las presuntas irregularidades en la licitaci\u00f3n del Acueducto del Colorado Norte y desestim\u00f3 el planteo que&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-28T07:27:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-28T13:16:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/09\/acueductocolorado2016-1000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"638\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA\",\"datePublished\":\"2018-09-28T07:27:06+00:00\",\"dateModified\":\"2018-09-28T13:16:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/\"},\"wordCount\":441,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/acueductocolorado2016-1000.jpg\",\"articleSection\":[\"A - QUE PASA (al costado)\",\"A - TEMPORALES\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/\",\"name\":\"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/acueductocolorado2016-1000.jpg\",\"datePublished\":\"2018-09-28T07:27:06+00:00\",\"dateModified\":\"2018-09-28T13:16:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/acueductocolorado2016-1000.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/acueductocolorado2016-1000.jpg\",\"width\":638,\"height\":425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/28\\\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/","og_locale":"es_ES","og_type":"article","og_title":"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA - Diario Textual","og_description":"El fiscal general de Santa Rosa, Guillermo Sancho, intervino en la causa penal por las presuntas irregularidades en la licitaci\u00f3n del Acueducto del Colorado Norte y desestim\u00f3 el planteo que&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2018-09-28T07:27:06+00:00","article_modified_time":"2018-09-28T13:16:21+00:00","og_image":[{"width":638,"height":425,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/09\/acueductocolorado2016-1000.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA","datePublished":"2018-09-28T07:27:06+00:00","dateModified":"2018-09-28T13:16:21+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/"},"wordCount":441,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/09\/acueductocolorado2016-1000.jpg","articleSection":["A - QUE PASA (al costado)","A - TEMPORALES","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/","name":"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/09\/acueductocolorado2016-1000.jpg","datePublished":"2018-09-28T07:27:06+00:00","dateModified":"2018-09-28T13:16:21+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/09\/acueductocolorado2016-1000.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/09\/acueductocolorado2016-1000.jpg","width":638,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/28\/archivo-la-causa-del-acueducto-del-norte-fiscal-rechazo-la-oposicion-la-fia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Archivo de la causa del Acueducto del Norte: otro fiscal rechaz\u00f3 la oposici\u00f3n de la FIA"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/21702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=21702"}],"version-history":[{"count":5,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/21702\/revisions"}],"predecessor-version":[{"id":21708,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/21702\/revisions\/21708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/21703"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=21702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=21702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=21702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}