{"id":21862,"date":"2018-09-29T10:21:05","date_gmt":"2018-09-29T13:21:05","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=21862"},"modified":"2018-09-30T10:27:44","modified_gmt":"2018-09-30T13:27:44","slug":"tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/","title":{"rendered":"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ"},"content":{"rendered":"<p><strong>Eduardo Tindiglia<\/strong>, diputado provincial del Frente para la Victoria,<strong> dej\u00f3 abierta la posibilidad de sumarse a un eventual frente electoral que encabezar\u00e1 el PJ en la provincia en 2019<\/strong>.<\/p>\n<p>El PJ, en un congreso en Quem\u00fa, llam\u00f3 a conformar un frente electoral. \u00bfSe sumar\u00e1 Nuevo Encuentro? \u201cEs importante decir que hasta el momento no se han producido un di\u00e1logo. No ha habido al menos conversaciones formales, como deber\u00eda ser en caso de constituirse un frente, que por supuesto no nos vamos a negar al di\u00e1logo\u201d, dijo el legislador a Radio Textual (FM Sonar).<\/p>\n<p>Dijo que el pa\u00eds \u00abse hunde\u00bb si sigue en el camino del ajuste.\u00a0\u201cTodas las variables en estos tres a\u00f1os del Gobierno nacional han sido absolutamente negativas. En lo social, en lo econ\u00f3mico, en todo sentido\u2026 La verdad que nosotros, desde el kirchnerismo, tenemos una posici\u00f3n muy cr\u00edtica en cuanto al deterioro de la situaci\u00f3n social.<strong> Todos los d\u00edas hay personas que se quedan sin trabajo, en medio de un modelo de ricos para transferir recursos desde los sectores populares a una minor\u00eda, que representa Mauricio Macri y sus CEO\u2019s. Por este camino, el pa\u00eds se hunde<\/strong>\u201d, expres\u00f3.<\/p>\n<p>\u201cEste gobierno duplic\u00f3 los desocupados, dolariz\u00f3 los servicios p\u00fablicos y entreg\u00f3 la soberan\u00eda al Fondo Monetario Internacional\u201d, sostuvo.<\/p>\n<p>Dijo que el llamado por la prensa porte\u00f1a como el \u201cperonismo responsable\u201d va a votar el proyecto de Presupuesto 2019. \u201c<strong>Este peronismo fue hist\u00f3ricamente acomodaticio<\/strong>\u201d, sostuvo.<\/p>\n<p><strong>Consider\u00f3 que Cristina Fern\u00e1ndez se presentar\u00e1 a las elecciones.<\/strong> \u201cEs lo que anhelamos todos. Es la figura m\u00e1s importante de la pol\u00edtica nacional, claramente, a partir de su reincorporaci\u00f3n pol\u00edtica, en el Senado nacional\u201d, sostuvo.<\/p>\n<p>\u00bfY Carlos Verna? \u201cHoy est\u00e1 parado en un lugar distinto. <strong>No es el Verna del 2016<\/strong>. Es otro Verna y eso se refleja en el voto de los legisladores nacionales, que le responden. A pesar de haber votado a favor de los fondos buitres y la reforma previsional, ahora tiene otra posici\u00f3n\u201d, sostuvo.<\/p>\n<p>Tambi\u00e9n cuestion\u00f3 a Javier Mac Allister, el referente del PRO. \u00abEs <strong>un representante de un modelo de destrucci\u00f3n<\/strong>. \u00bfSe imaginan un Gobierno de Mac Allister? De por s\u00ed, habr\u00e1 cientos de despedidos en el Estado\u00bb, vaticin\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eduardo Tindiglia, diputado provincial del Frente para la Victoria, dej\u00f3 abierta la posibilidad de sumarse a un eventual frente electoral que encabezar\u00e1 el PJ en la provincia en 2019. El&hellip;<\/p>\n","protected":false},"author":3,"featured_media":7005,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[319,8],"tags":[43],"class_list":["post-21862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-temporales","category-politica","tag-tindiglia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Eduardo Tindiglia, diputado provincial del Frente para la Victoria, dej\u00f3 abierta la posibilidad de sumarse a un eventual frente electoral que encabezar\u00e1 el PJ en la provincia en 2019. El&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-29T13:21:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-30T13:27:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/tindigliaeduardosesion2018-011.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"529\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ\",\"datePublished\":\"2018-09-29T13:21:05+00:00\",\"dateModified\":\"2018-09-30T13:27:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/\"},\"wordCount\":399,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/tindigliaeduardosesion2018-011.jpg\",\"keywords\":[\"tindiglia\"],\"articleSection\":[\"A - TEMPORALES\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/\",\"name\":\"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/tindigliaeduardosesion2018-011.jpg\",\"datePublished\":\"2018-09-29T13:21:05+00:00\",\"dateModified\":\"2018-09-30T13:27:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/tindigliaeduardosesion2018-011.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/tindigliaeduardosesion2018-011.jpg\",\"width\":529,\"height\":341},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/09\\\/29\\\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/","og_locale":"es_ES","og_type":"article","og_title":"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ - Diario Textual","og_description":"Eduardo Tindiglia, diputado provincial del Frente para la Victoria, dej\u00f3 abierta la posibilidad de sumarse a un eventual frente electoral que encabezar\u00e1 el PJ en la provincia en 2019. El&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2018-09-29T13:21:05+00:00","article_modified_time":"2018-09-30T13:27:44+00:00","og_image":[{"width":529,"height":341,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/tindigliaeduardosesion2018-011.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ","datePublished":"2018-09-29T13:21:05+00:00","dateModified":"2018-09-30T13:27:44+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/"},"wordCount":399,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/tindigliaeduardosesion2018-011.jpg","keywords":["tindiglia"],"articleSection":["A - TEMPORALES","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/","name":"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/tindigliaeduardosesion2018-011.jpg","datePublished":"2018-09-29T13:21:05+00:00","dateModified":"2018-09-30T13:27:44+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/tindigliaeduardosesion2018-011.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/tindigliaeduardosesion2018-011.jpg","width":529,"height":341},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/09\/29\/tindiglia-deja-abierta-la-posibilidad-sumarse-al-frente-pj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Tindiglia deja abierta la posibilidad de sumarse a un frente con el PJ"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/21862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=21862"}],"version-history":[{"count":9,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/21862\/revisions"}],"predecessor-version":[{"id":21871,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/21862\/revisions\/21871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/7005"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=21862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=21862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=21862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}