{"id":233549,"date":"2023-08-11T09:22:15","date_gmt":"2023-08-11T12:22:15","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=233549"},"modified":"2023-08-11T09:22:18","modified_gmt":"2023-08-11T12:22:18","slug":"elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/","title":{"rendered":"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se celebraron las elecciones en la Asociaci\u00f3n Trabajadores del Estado en todo el pa\u00eds y en La Pampa la lista Celeste y Blanca, con Roxana Rechimont y N\u00e9stor Chazarreta, obtuvo un amplio respaldo. A nivel nacional gan\u00f3 la f\u00f3rmula Aguiar-Cabezas, de la lista verde Anusate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este 9 de agosto ATE tuvo sus elecciones en todo el pa\u00eds. Por primera vez hubo paridad de g\u00e9nero y alternancia en todas las listas producto de la \u00faltima reforma del estatuto de la asociaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En La Pampa la elecci\u00f3n se desarroll\u00f3 con total normalidad con una asistencia del 55% del padr\u00f3n repartidos en 40 urnas por toda la provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lista Celeste y Blanca encabezada por Roxana Rechimont y Jorge Chazarreta obtuvo un amplio respaldo a su pol\u00edtica sindical al ser ratificados en los cargos que ocupan actualmente con 1126 votos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la seccional \u201cPampa Norte\u201d se impuso Pedro Coria, acompa\u00f1ado por Roc\u00edo Santoro con 132 votos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En General Pico, la nueva secretaria general ser\u00e1 Nora Poblet y Fredy Romero ser\u00e1 el secretario general adjunto por la Celeste y Blanca. Cosecharon 259 votos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La disputa en la seccional 25 de Mayo qued\u00f3 en manos de la lista Verde Anusate qui\u00e9n llevaba como secretario general a Ana Andrada. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la seccional de General Acha, Norma Ojeda de la agrupaci\u00f3n Verde Anusate seguir\u00e1 al frente del gremio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se celebraron las elecciones en la Asociaci\u00f3n Trabajadores del Estado en todo el pa\u00eds y en La Pampa la lista Celeste y Blanca, con Roxana Rechimont y N\u00e9stor Chazarreta, obtuvo&hellip;<\/p>\n","protected":false},"author":7,"featured_media":233550,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-233549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Se celebraron las elecciones en la Asociaci\u00f3n Trabajadores del Estado en todo el pa\u00eds y en La Pampa la lista Celeste y Blanca, con Roxana Rechimont y N\u00e9stor Chazarreta, obtuvo&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-11T12:22:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-11T12:22:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/rechimontate.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/\"},\"author\":{\"name\":\"diario5\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\"},\"headline\":\"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados\",\"datePublished\":\"2023-08-11T12:22:15+00:00\",\"dateModified\":\"2023-08-11T12:22:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/\"},\"wordCount\":243,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/rechimontate.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/\",\"name\":\"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/rechimontate.jpg\",\"datePublished\":\"2023-08-11T12:22:15+00:00\",\"dateModified\":\"2023-08-11T12:22:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/rechimontate.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/rechimontate.jpg\",\"width\":850,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/11\\\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\",\"name\":\"diario5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"caption\":\"diario5\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/","og_locale":"es_ES","og_type":"article","og_title":"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados - Diario Textual","og_description":"Se celebraron las elecciones en la Asociaci\u00f3n Trabajadores del Estado en todo el pa\u00eds y en La Pampa la lista Celeste y Blanca, con Roxana Rechimont y N\u00e9stor Chazarreta, obtuvo&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2023-08-11T12:22:15+00:00","article_modified_time":"2023-08-11T12:22:18+00:00","og_image":[{"width":850,"height":666,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/rechimontate.jpg","type":"image\/jpeg"}],"author":"diario5","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario5","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/"},"author":{"name":"diario5","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067"},"headline":"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados","datePublished":"2023-08-11T12:22:15+00:00","dateModified":"2023-08-11T12:22:18+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/"},"wordCount":243,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/rechimontate.jpg","articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/","name":"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/rechimontate.jpg","datePublished":"2023-08-11T12:22:15+00:00","dateModified":"2023-08-11T12:22:18+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/rechimontate.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/rechimontate.jpg","width":850,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/11\/elecciones-en-ate-la-celeste-y-blanca-tuvo-el-respaldo-de-las-y-los-afiliados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Elecciones en ATE: La Celeste y Blanca tuvo el respaldo de las y los afiliados"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067","name":"diario5","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","caption":"diario5"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario5\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/233549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=233549"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/233549\/revisions"}],"predecessor-version":[{"id":233551,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/233549\/revisions\/233551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/233550"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=233549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=233549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=233549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}