{"id":233865,"date":"2023-08-13T13:06:58","date_gmt":"2023-08-13T16:06:58","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=233865"},"modified":"2023-08-13T19:35:59","modified_gmt":"2023-08-13T22:35:59","slug":"verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/","title":{"rendered":"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Carlos Verna<\/strong>, dos veces gobernador &nbsp;(2003-2007 y 2015-2019) y uno de los principales referentes de peronismo pampeano, reapareci\u00f3 este domingo cuando vot\u00f3 en la ciudad de General Pico. Dijo que en esta campa\u00f1a se ver\u00e1 si \u201cla gente est\u00e1 m\u00e1s enojada con las promesas incumplidas de Alberto Fern\u00e1ndez o con el Gobierno de Macri que destruy\u00f3 fuentes de trabajo\u201d, elogi\u00f3 a <strong>Sergio Ziliotto<\/strong> porque \u201csabe manejar la Provincia\u201d, destac\u00f3 a la intendenta piquense <strong>Fernanda Alonso<\/strong>, y aclar\u00f3 que \u201cnunca\u201d votar\u00eda a presidente a Juan Schiaretti. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-\u00bfCu\u00e1l es su an\u00e1lisis hacia esta campa\u00f1a?-le consult\u00f3 la prensa.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-En esta campa\u00f1a hay que ver si la gente est\u00e1 m\u00e1s enojada con las promesas incumplidas de Alberto Fern\u00e1ndez, del asado barato, de la heladera llena, de los sueldos que le ganan a la inflaci\u00f3n, o con el gobierno de Macri y las 22.000 pymes destruidas y que nos trajo el Fondo (Monetario Internacional). Si est\u00e1 m\u00e1s enojada con Macri porque destruy\u00f3 fuentes de trabajo y recibi\u00f3 a un pa\u00eds con el 25% de inflaci\u00f3n y lo llev\u00f3 al 50%. O si est\u00e1 m\u00e1s enojada con la administraci\u00f3n de Alberto Fern\u00e1ndez que recibi\u00f3 a un pa\u00eds con el 50% de inflaci\u00f3n y lo llev\u00f3 hasta ahora al 115%. Y si bien hay trabajo, hay trabajo de baja calidad. Por primera vez con un Gobierno peronista, y no lo dije yo, lo dijo alguien m\u00e1s importante que yo (NdeR: en referencia a Cristina Fern\u00e1ndez), en un gobierno peronista hay trabajadores que en blanco, o sea trabajadores registrados, cobran por debajo de la l\u00ednea de poder. Entonces hay que ver si est\u00e1n m\u00e1s enojados una administraci\u00f3n o la otra. Y los que est\u00e1n enojados con las dos administraciones van a terminar votando a (Javier) Milei o no viniendo a votar. Yo creo que Milei va a sacar votos y creo que el porcentaje de participaci\u00f3n en las elecciones va a ser menor al que nos tiene acostumbrada La Pampa y en el pa\u00eds. Y eso es malo. Es malo para la democracia porque la debilita y es malo para las instituciones porque le hace perder calidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8211; \u00bfC\u00f3mo es el futuro que te avizora para la provincia de La Pampa con este escenario?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-La Pampa siempre estuvo bien administrada, siempre tuvo recursos, (Sergio) Ziliotto ha mostrado que sabe manejar la provincia, Fernanda (Alonso) ha demostrado que sabe manejar la municipalidad, y las coparticipaciones de la provincia, o sea, no es un regalito, es lo que le toca a la provincia. El problema va a ser que a partir de ma\u00f1ana: nos enteraremos de cu\u00e1les son las condiciones que puso el Fondo para dar los 7.500 millones, que s\u00f3lo son para pagarle al fondo. Porque si ustedes miran las cuentas del pa\u00eds, la Argentina lleva pagado en lo que va del a\u00f1o 14.500 millones de d\u00f3lares de deuda externa. Y el Fondo nos dio 4.000. Nosotros hemos puesto 10.000 millones de d\u00f3lares en un a\u00f1o en el que perdimos 20.000 millones de recaudaci\u00f3n por la sequ\u00eda. Quiere decir que eso de que el prestamiento de \u00faltima instancia est\u00e1 para ayudar a los pa\u00edses es bastante poco cierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que m\u00e1s que la sociedad pampeano, m\u00e1s que al precandidato a diputado, mira a los postulantes a presidente. <strong>\u201cEs una elecci\u00f3n nacional, yo creo que la gente no mira el candidato a diputado, yo creo que la gente lo que mira es el candidato a presidente\u201d<\/strong>, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n cruz\u00f3 a un medio de prensa que sostuvo que Verna haya \u201carreglado\u201d con Juan Schiaretti. \u201cLe quiero aclarar a algunos que hicieron por ah\u00ed una operaci\u00f3n de prensa, de que yo iba a votar a (Juan) Schiaretti. Le quiero recordar, para los que tienen poca memoria, que una vez en el CFI, en una reuni\u00f3n de gobernadores, yo le dije a todos los periodistas que estaban que hab\u00eda gobernadores peronistas que estaban m\u00e1s cerca de Macri que de Per\u00f3n. Uno de ellos es Schiaretti. Lo pensaba y lo sigo pensando. As\u00ed que no cuenten conmigo. Yo soy peronista, voto peronismo\u201d, aclar\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-\u00bfSigue enojado con Sergio Massa por haber visitado y respaldado la represa de El Tambolar (NdeR: en San Juan, que provoca el corte del Salado en el oeste pampeano)?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Yo defiendo a La Pampa y a los pampeanos. Adem\u00e1s, yo present\u00e9 una demanda cuando era gobernador en el 2018 contra la provincia de San Juan por construir una represa sobre un r\u00edo que es compartido en la cuenta del Desag\u00fcadero &#8211; Salado &#8211; Chadileuv\u00fa &#8211; Curac\u00f3. Yo no reniego de la defensa de la defensa de los r\u00edos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-En las \u00faltimas horas entr\u00f3 algo de agua en el Atuel. \u00bfEs una esperanza?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-No, debe ser agua de lluvia. No creo que todav\u00eda haya un nivel importante porque es 0,2 metros c\u00fabicos (por segundo). Y lo que estableci\u00f3 la Corte es bastante m\u00e1s (3,2 m3\/S). Yo creo que habr\u00eda que exhortar a la Corte una vez m\u00e1s a que cumpla el fallo, que nos den el agua que nos toca. Porque lo que se olvida de contar es que es cierto que en Mendoza crearon un oasis de 50.000 hect\u00e1reas, pero a nosotros nos criaron un desierto de 500.000.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"KMa3198pPl\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-hay-que-exhortar-a-la-corte-para-que-nos-den-el-agua-del-atuel\/\">Verna: \u201cHay que exhortar a la Corte para que nos den el agua del Atuel\u201d<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abVerna: \u201cHay que exhortar a la Corte para que nos den el agua del Atuel\u201d\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-hay-que-exhortar-a-la-corte-para-que-nos-den-el-agua-del-atuel\/embed\/#?secret=h0gbJDAN6a#?secret=KMa3198pPl\" data-secret=\"KMa3198pPl\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carlos Verna, dos veces gobernador &nbsp;(2003-2007 y 2015-2019) y uno de los principales referentes de peronismo pampeano, reapareci\u00f3 este domingo cuando vot\u00f3 en la ciudad de General Pico. Dijo que&hellip;<\/p>\n","protected":false},"author":3,"featured_media":233873,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,8],"tags":[],"class_list":["post-233865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Carlos Verna, dos veces gobernador &nbsp;(2003-2007 y 2015-2019) y uno de los principales referentes de peronismo pampeano, reapareci\u00f3 este domingo cuando vot\u00f3 en la ciudad de General Pico. Dijo que&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-13T16:06:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-13T22:35:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vernacarlosvotando2023-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d\",\"datePublished\":\"2023-08-13T16:06:58+00:00\",\"dateModified\":\"2023-08-13T22:35:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/\"},\"wordCount\":935,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vernacarlosvotando2023-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/\",\"name\":\"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vernacarlosvotando2023-1.jpg\",\"datePublished\":\"2023-08-13T16:06:58+00:00\",\"dateModified\":\"2023-08-13T22:35:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vernacarlosvotando2023-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vernacarlosvotando2023-1.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/","og_locale":"es_ES","og_type":"article","og_title":"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d - Diario Textual","og_description":"Carlos Verna, dos veces gobernador &nbsp;(2003-2007 y 2015-2019) y uno de los principales referentes de peronismo pampeano, reapareci\u00f3 este domingo cuando vot\u00f3 en la ciudad de General Pico. Dijo que&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2023-08-13T16:06:58+00:00","article_modified_time":"2023-08-13T22:35:59+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vernacarlosvotando2023-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d","datePublished":"2023-08-13T16:06:58+00:00","dateModified":"2023-08-13T22:35:59+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/"},"wordCount":935,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vernacarlosvotando2023-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/","name":"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vernacarlosvotando2023-1.jpg","datePublished":"2023-08-13T16:06:58+00:00","dateModified":"2023-08-13T22:35:59+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vernacarlosvotando2023-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vernacarlosvotando2023-1.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/verna-y-las-paso-se-vera-si-la-gente-esta-mas-enojada-con-alberto-o-con-el-gobierno-de-macri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Verna y las PASO: \u201cSe ver\u00e1 si la gente est\u00e1 m\u00e1s enojada con Alberto o con el Gobierno de Macri\u201d"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/233865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=233865"}],"version-history":[{"count":6,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/233865\/revisions"}],"predecessor-version":[{"id":233875,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/233865\/revisions\/233875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/233873"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=233865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=233865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=233865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}