{"id":233942,"date":"2023-08-13T21:06:50","date_gmt":"2023-08-14T00:06:50","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=233942"},"modified":"2023-08-13T22:41:15","modified_gmt":"2023-08-14T01:41:15","slug":"fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/","title":{"rendered":"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un hombre de 53 a\u00f1os oriundo de Chacharramendi falleci\u00f3 el s\u00e1bado en un siniestro vial ocurrido en la ruta nacional 35 y el acceso a la localidad de Bernasconi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El hecho ocurri\u00f3 a las 15.30 horas cuando una Toyota Hilux circulaba de Oeste a Este. Desde la Unidad Regional III informaron que por motivos que se tratan de establecer, la camioneta se sali\u00f3 de la cinta asf\u00e1ltica produciendo el vuelco del rodado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El conductor, que iba solo, sali\u00f3 despedido y falleci\u00f3 en el lugar. Trabajo en el lugar la Agencia de Investigaci\u00f3n Cient\u00edfica. El cuerpo de la v\u00edctima fue trasladado a la morgue judicial de General Acha y posteriormente fue entregado a familiares<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre de 53 a\u00f1os oriundo de Chacharramendi falleci\u00f3 el s\u00e1bado en un siniestro vial ocurrido en la ruta nacional 35 y el acceso a la localidad de Bernasconi. El&hellip;<\/p>\n","protected":false},"author":3,"featured_media":233943,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-233942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35 - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35 - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Un hombre de 53 a\u00f1os oriundo de Chacharramendi falleci\u00f3 el s\u00e1bado en un siniestro vial ocurrido en la ruta nacional 35 y el acceso a la localidad de Bernasconi. El&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-14T00:06:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-14T01:41:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vuelcoruta35-011.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"843\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35\",\"datePublished\":\"2023-08-14T00:06:50+00:00\",\"dateModified\":\"2023-08-14T01:41:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/\"},\"wordCount\":126,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vuelcoruta35-011.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/\",\"name\":\"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35 - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vuelcoruta35-011.jpg\",\"datePublished\":\"2023-08-14T00:06:50+00:00\",\"dateModified\":\"2023-08-14T01:41:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vuelcoruta35-011.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vuelcoruta35-011.jpg\",\"width\":1500,\"height\":843},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2023\\\/08\\\/13\\\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35 - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/","og_locale":"es_ES","og_type":"article","og_title":"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35 - Diario Textual","og_description":"Un hombre de 53 a\u00f1os oriundo de Chacharramendi falleci\u00f3 el s\u00e1bado en un siniestro vial ocurrido en la ruta nacional 35 y el acceso a la localidad de Bernasconi. El&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2023-08-14T00:06:50+00:00","article_modified_time":"2023-08-14T01:41:15+00:00","og_image":[{"width":1500,"height":843,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vuelcoruta35-011.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35","datePublished":"2023-08-14T00:06:50+00:00","dateModified":"2023-08-14T01:41:15+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/"},"wordCount":126,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vuelcoruta35-011.jpg","articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/","name":"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35 - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vuelcoruta35-011.jpg","datePublished":"2023-08-14T00:06:50+00:00","dateModified":"2023-08-14T01:41:15+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vuelcoruta35-011.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/08\/vuelcoruta35-011.jpg","width":1500,"height":843},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2023\/08\/13\/fallecio-un-vecino-de-chacharramendi-en-un-vuelco-en-ruta-35\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Falleci\u00f3 un vecino de Chacharramendi en un vuelco en ruta 35"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/233942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=233942"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/233942\/revisions"}],"predecessor-version":[{"id":233944,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/233942\/revisions\/233944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/233943"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=233942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=233942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=233942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}