{"id":250335,"date":"2024-01-05T21:16:06","date_gmt":"2024-01-06T00:16:06","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=250335"},"modified":"2024-01-07T11:41:04","modified_gmt":"2024-01-07T14:41:04","slug":"patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/","title":{"rendered":"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar"},"content":{"rendered":"\n<p><strong>Patricia Matal\u00f3n<\/strong>, quien fuera dirigente del Partido Justicialista y luego se acercara al PRO y a la Libertad Avanza, celebr\u00f3 efusivamente que el Ej\u00e9rcito Argentino haya decidido <strong><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/gano-milei-y-hubo-un-giro-del-ejercito-rechazo-devolver-la-ex-escuela-hogar-de-santa-rosa\/\" target=\"_blank\" rel=\"noreferrer noopener\">no devolver el exedificio de la Escuela Hogar de Santa Rosa que ocup\u00f3 hace 40 a\u00f1os<\/a><\/strong>, en plena Dictadura militar, luego de encarcelar a sus autoridades.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"y0DHrhIdYH\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/gano-milei-y-hubo-un-giro-del-ejercito-rechazo-devolver-la-ex-escuela-hogar-de-santa-rosa\/\">Gan\u00f3 Milei y hubo un giro del Ej\u00e9rcito: rechaz\u00f3 devolver la ex Escuela Hogar de Santa Rosa<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abGan\u00f3 Milei y hubo un giro del Ej\u00e9rcito: rechaz\u00f3 devolver la ex Escuela Hogar de Santa Rosa\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/gano-milei-y-hubo-un-giro-del-ejercito-rechazo-devolver-la-ex-escuela-hogar-de-santa-rosa\/embed\/#?secret=vrCrmPu6qv#?secret=y0DHrhIdYH\" data-secret=\"y0DHrhIdYH\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong><em>\u201cEso pasa cuando todo lo politizan. Me encanta que el gobierno pampeano est\u00e9 comenzando a cosechar su siembra (esto es solo el comienzo). Bien por el Ej\u00e9rcito Argentino, nuestro Ej\u00e9rcito\u201d<\/em><\/strong>, escribi\u00f3 en respuesta a la nota de <strong>Diario Textual<\/strong>, que revel\u00f3 el cambio de postura del Ej\u00e9rcito, cuando gan\u00f3 las elecciones el libertario Javier Milei.<\/p>\n\n\n\n<p>Matal\u00f3n es una abogado especialista en recursos h\u00eddricos. Lleg\u00f3 a La Pampa de la mano de Carlos Verna, cuando era gobernador. Fue asesora tambi\u00e9n de Verna en el Senado nacional, entre otros cargos. Adem\u00e1s, fue presidenta de la Junta Electoral del PJ, hasta que en 2015, enojada por la alianza de Verna con los kirchnerista, decidi\u00f3 pegar el portazo. Unos d\u00edas despu\u00e9s se sum\u00f3 al PRO, en un sector vinculado a Patricia Bullrich.<\/p>\n\n\n\n<p>Con Bullrich como ministra de Seguridad, Matal\u00f3n aceler\u00f3 su acercamiento a La Libertad Avanza, el partido de Milei.<\/p>\n\n\n\n<p>Es \u201cpromilitar\u201d. Es hija de Carlos Matal\u00f3n, quien fuera jefe de la Compa\u00f1\u00eda de Ingenieros Mecanizada 10 -que es parte de la X Brigada Mecanizada, que ocupa la exescuela- en la Guerra de Malvinas. Adem\u00e1s, fue uno de los militares que en 1995 detect\u00f3 el tr\u00e1fico de armas de la Argentina a la Guerra de Balcanes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"715\" height=\"726\" src=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/matalonconbullrich.jpg\" alt=\"\" class=\"wp-image-250277\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/matalonconbullrich.jpg 715w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/matalonconbullrich-295x300.jpg 295w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/matalonconbullrich-585x594.jpg 585w\" sizes=\"(max-width: 715px) 100vw, 715px\" \/><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>El no del Ej\u00e9rcito<\/strong><\/p>\n\n\n\n<p>El&nbsp;<strong>Ej\u00e9rcito Argentino<\/strong>, a pocos d\u00edas de la victoria de&nbsp;<strong>Javier Milei<\/strong>, mostr\u00f3 un giro en su posici\u00f3n y, mediante una nota,<strong>&nbsp;rechaz\u00f3 la posibilidad de devolver<\/strong>&nbsp;el edificio de la&nbsp;<strong>Ex Escuela Hogar de Santa Rosa&nbsp;<\/strong>a la comunidad para que la utilice la<strong>&nbsp;Universidad Nacional de La Pampa (UNLPam).<\/strong><\/p>\n\n\n\n<p>El dato fue confirmado a&nbsp;<strong>Diario Textual&nbsp;<\/strong>por&nbsp;<strong>Oscar Alpa<\/strong>, rector de la UNLPam y quien era -hasta la asunci\u00f3n de Milei- el&nbsp;<strong>secretario de Pol\u00edticas Universitarias de la Naci\u00f3n<\/strong>, a cargo de las negociaciones.<\/p>\n\n\n\n<p>Poco despu\u00e9s del balotaje, el Ej\u00e9rcito expres\u00f3 en el expediente que se abri\u00f3 en la<strong>&nbsp;Administraci\u00f3n de Bienes del Estado (ABE<\/strong>) que&nbsp;<strong>no va a reintegrar el edificio&nbsp;<\/strong>que ocupa desde hace cuatro d\u00e9cadas. Actualmente hay unos&nbsp;<strong>400 oficiales, suboficiales y soldados que dependen de la X Brigada Mecanizada.<\/strong><\/p>\n\n\n\n<p>Claramente fue&nbsp;<strong>un giro&nbsp;<\/strong>en su posicionamiento.<strong>&nbsp;\u201cVen\u00edamos teniendo conversaciones para que se pudiera concretar (la entrega), pero inesperadamente luego de la segunda vuelta nos dijeron, por nota, que no devolver\u00e1n el edificio\u201d<\/strong>, cont\u00f3 Alpa a Diario Textual.<\/p>\n\n\n\n<p>En diciembre de 2020,&nbsp;<strong>el Gobierno nacional abri\u00f3, por primera vez, la posibilidad de devolver al Estado provincial el edificio<\/strong>&nbsp;de la ex Escuela Hogar de Santa Rosa:&nbsp;el entonces ministro Agust\u00edn Rossi<strong><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/12\/08\/rossi-pidio-ayuda-financiera-de-la-pampa-ampliar-una-guarnicion-militar-y-devolver-la-ex-escuela-hogar\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;dijo que \u201cel camino\u201d para que \u201cvuelva a manos de la provincia\u201d era que&nbsp;se ampliaran las instalaciones del Regimiento de Toay,&nbsp;<\/a><\/strong>para de esa forma trasladar la X Brigada Mecanizada.<\/p>\n\n\n\n<p><strong>La ex Escuela Hogar N\u00ba 141 est\u00e1 ubicada en la calle Ra\u00fal B. D\u00edaz al 1075.<\/strong>&nbsp;Fue una obra financiada por la Fundaci\u00f3n de Ayuda Social Eva Duarte de Per\u00f3n e inaugurada en el a\u00f1o 1955 bajo la denominaci\u00f3n&nbsp;<strong>Hogar Escuela General Juan D. Per\u00f3n<\/strong>.&nbsp;<strong>Lleg\u00f3 a albergar hasta 1.000 ni\u00f1os de Santa Rosa y de otros puntos de la provincia<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"960\" height=\"608\" src=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/escuelahogarvieja1.jpg\" alt=\"\" class=\"wp-image-7283\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/escuelahogarvieja1.jpg 960w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/escuelahogarvieja1-300x190.jpg 300w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/escuelahogarvieja1-768x486.jpg 768w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/escuelahogarvieja1-585x371.jpg 585w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p>En la dictadura militar, el lugar fue desalojado. <strong>Sus autoridades y algunos de sus proveedores fueron detenidos en marzo de 1978 por \u201csubversi\u00f3n econ\u00f3mica\u201d.<\/strong> Quedaron a disposici\u00f3n de la Subzona Militar 14 y juzgados por \u201cmalversaci\u00f3n de fondos\u201d, luego de sufrir una prolongada permanencia en prisi\u00f3n. Entre 1981 y 1982 desembarcaron los militares.<\/p>\n\n\n\n<p>El predio hoy est\u00e1 ocupado por unos 400 militares y soldados voluntarios de la Compa\u00f1\u00eda de Ingenieros Mecanizada 10 y la Compa\u00f1\u00eda de Comunicaciones Mecanizada 10.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Un reclamo que persiste<\/strong><\/p>\n\n\n\n<p>Desde hace unos veinte a\u00f1os, ha habido numerosos reclamos para que el lugar sea devuelto a la sociedad. Tanto de exalumnos, exdocentes, vecinos y dirigentes del oficialismo y de la oposici\u00f3n. Incluso hace unos a\u00f1os se conform\u00f3 una asamblea autoconvocada que reclam\u00f3 por el edificio.<\/p>\n\n\n\n<p>Una de las iniciativas m\u00e1s ambiciosas fue presentada por el rector de la UNLPam, Oscar Alpa, al intendente santarrose\u00f1o Luciano Di N\u00e1poli. Este, a su vez, se lo traslad\u00f3 en su momento al entonces ministro Rossi. Posteriormente, ya como funcionario nacional, Alpa sigui\u00f3 el tr\u00e1mite con atenci\u00f3n.<\/p>\n\n\n\n<p>El proyecto consist\u00eda en el traslado de algunas de las facultades de la UNLPam a ese lugar. Tambi\u00e9n del comedor universitario. Incluso Alpa plante\u00f3 que el predio podr\u00eda ser ocupado por talleres dictados por la municipalidad y hasta la Provincia podr\u00eda instalar el Instituto de Formaci\u00f3n Docente.<\/p>\n\n\n\n<p>\u201cHubo conversaciones avanzadas para que pudiera recuperarse la exescuela. A nivel local, con autoridades de la X Brigada y, en Naci\u00f3n, con el Ej\u00e9rcito\u201d, dijo Alpa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"532\" height=\"380\" src=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/escuelahogarstarosa.jpg\" alt=\"\" class=\"wp-image-7279\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/escuelahogarstarosa.jpg 532w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/05\/escuelahogarstarosa-300x214.jpg 300w\" sizes=\"(max-width: 532px) 100vw, 532px\" \/><\/figure>\n\n\n\n<p><strong>Las autoridades de la X Brigada le reconocieron, en su momento, que prefer\u00edan retirarse de la exescuela y asentarse en Toay. Entre otros puntos, para tener una mejor comunicaci\u00f3n y log\u00edstica.<\/strong><\/p>\n\n\n\n<p>\u201cDesde el Ministerio de Educaci\u00f3n de la Naci\u00f3n se hab\u00edan comprometido a financiar unos 4 mil metros cuadrados (el equivalente a la escuela hogar). Incluso se habl\u00f3 de la creaci\u00f3n de un fideicomiso para que el Ej\u00e9rcito pudiera administrar los fondos (de Educaci\u00f3n), hasta avanzar con la obra y no perder poder adquisitivo\u201d, dijo Alpa. Sin embargo, esas negociaciones se cayeron recientemente.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Patricia Matal\u00f3n, quien fuera dirigente del Partido Justicialista y luego se acercara al PRO y a la Libertad Avanza, celebr\u00f3 efusivamente que el Ej\u00e9rcito Argentino haya decidido no devolver el&hellip;<\/p>\n","protected":false},"author":3,"featured_media":64776,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,11,8],"tags":[],"class_list":["post-250335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-que-pasa","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Patricia Matal\u00f3n, quien fuera dirigente del Partido Justicialista y luego se acercara al PRO y a la Libertad Avanza, celebr\u00f3 efusivamente que el Ej\u00e9rcito Argentino haya decidido no devolver el&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-06T00:16:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-07T14:41:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/10\/escuelahogarstarosa2019-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar\",\"datePublished\":\"2024-01-06T00:16:06+00:00\",\"dateModified\":\"2024-01-07T14:41:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/\"},\"wordCount\":1004,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/escuelahogarstarosa2019-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"A - QUE PASA (al costado)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/\",\"name\":\"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/escuelahogarstarosa2019-1.jpg\",\"datePublished\":\"2024-01-06T00:16:06+00:00\",\"dateModified\":\"2024-01-07T14:41:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/escuelahogarstarosa2019-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/escuelahogarstarosa2019-1.jpg\",\"width\":1200,\"height\":728},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/01\\\/05\\\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/","og_locale":"es_ES","og_type":"article","og_title":"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar - Diario Textual","og_description":"Patricia Matal\u00f3n, quien fuera dirigente del Partido Justicialista y luego se acercara al PRO y a la Libertad Avanza, celebr\u00f3 efusivamente que el Ej\u00e9rcito Argentino haya decidido no devolver el&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2024-01-06T00:16:06+00:00","article_modified_time":"2024-01-07T14:41:04+00:00","og_image":[{"width":1200,"height":728,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/10\/escuelahogarstarosa2019-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar","datePublished":"2024-01-06T00:16:06+00:00","dateModified":"2024-01-07T14:41:04+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/"},"wordCount":1004,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/10\/escuelahogarstarosa2019-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","A - QUE PASA (al costado)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/","name":"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/10\/escuelahogarstarosa2019-1.jpg","datePublished":"2024-01-06T00:16:06+00:00","dateModified":"2024-01-07T14:41:04+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/10\/escuelahogarstarosa2019-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/10\/escuelahogarstarosa2019-1.jpg","width":1200,"height":728},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/01\/05\/patricia-matalon-ex-pj-y-actual-mileista-celebro-que-el-ejercito-no-devuelva-la-ex-escuela-hogar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Patricia Matal\u00f3n, ex PJ y actual mile\u00edsta, celebr\u00f3 que el Ej\u00e9rcito no devuelva la ex Escuela Hogar"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/250335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=250335"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/250335\/revisions"}],"predecessor-version":[{"id":250337,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/250335\/revisions\/250337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/64776"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=250335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=250335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=250335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}