{"id":254652,"date":"2024-02-21T08:30:32","date_gmt":"2024-02-21T11:30:32","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=254652"},"modified":"2024-02-22T08:33:22","modified_gmt":"2024-02-22T11:33:22","slug":"aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/","title":{"rendered":"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las municipalidades hacen n\u00fameros para definir si podr\u00e1n hacer frente al <strong><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/20\/paritarias-el-gobierno-oferto-un-20-de-aumento\/\" target=\"_blank\" rel=\"noreferrer noopener\">20% de aumento a estatales dispuesto por el Gobierno provincial<\/a><\/strong>. Diario Textual confirm\u00f3 que <strong><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/hay-desenganche-santa-rosa-avisa-que-no-puede-dar-el-aumento-del-20-a-los-municipales\/\" target=\"_blank\" rel=\"noreferrer noopener\">Santa Rosa no llega a ese porcentaje<\/a><\/strong>; que <strong>General Pico lo est\u00e1 analizando<\/strong>; y que <strong>Victorica y General Acha lo pagar\u00e1n<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0<strong>\u201cAl 20% que ofert\u00f3 la Provincia no llegamos\u201d<\/strong>, avis\u00f3 a\u00a0<strong>Diario Textual<\/strong>, en forma terminante,<strong>\u00a0<\/strong>una fuente municipal de la capital.\u00a0<strong>\u201cLa intenci\u00f3n siempre es acompa\u00f1ar (los aumentos que da la Provincia) pero, por supuesto, la sustentabilidad financiera de largo plazo es clave mantenerla<\/strong>\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Victorica, a su vez, dar\u00e1 luz verde. \u201cEn el caso de Victorica calculo que se va a pagar. El tema es que esa decisi\u00f3n implica redirigir fondos de alguna otra actividad como por ejemplo obra p\u00fablica o tener que recortar horas extras. Pero seguramente se va a dar\u201d, dijo a este diario digital el intendente <strong>Hugo Kenny.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Abel Sabarots<\/strong>, intendente de General Acha, tambi\u00e9n confirm\u00f3 el pago del aumento. \u201cS\u00ed, claro: lo vamos a pagar\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, desde el municipio de General Pico dijeron que no est\u00e1 definido. <strong>\u201cSe est\u00e1 analizando detalladamente, a\u00fan no hay definici\u00f3n\u201d<\/strong>, respondieron fuentes municipales a la consulta de Diario Textual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante estos dos primeros meses de 2024, Casa de Gobierno otorg\u00f3 un incremento salarial acumulado del 32%. Ayer, en la paritaria, el Ejecutivo puso sobre la mesa un 20% de aumento y, pese al rechazo de los sindicatos estatales provinciales por considerarlo insuficiente frente a la inflaci\u00f3n, avis\u00f3 que lo pagar\u00e1 con el salario de febrero (a fines de este mismo mes).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los municipios pueden adherir o no al incremento. Santa Rosa, Pico, Toay y el resto de las localidades dieron el primer aumento acordado del 10% en enero, con una ayuda de Provincia con 50 mil pesos por trabajador municipal. Pero ayer esos 50 mil pesos no se renovaron, por lo que el costo total deber\u00e1 ser afrontado por cada intendencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese marco, algunas municipalidades comenzaron a \u201cdesengancharse\u201d de los acuerdos salariales negociados por el Gobierno provincial y que, a rajatabla, ven\u00edan siendo replicados en los \u00faltimos a\u00f1os. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El panorama es cr\u00edtico. Las 80 localidades han sufrido en los \u00faltimos dos meses, a partir de la asunci\u00f3n de Javier Milei, un fort\u00edsimo impacto: ralentizaci\u00f3n o corte total de las obras p\u00fablicas nacionales, menores ingresos previstos por la ca\u00edda de la coparticipaci\u00f3n nacional, m\u00e1s dinero destinado a la ayuda social y hasta un corte casi total de la ayuda de Provincia por fuera de la coparticipaci\u00f3n (a excepci\u00f3n de los 50 mil pesos por municipal del mes de enero).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De todas maneras, todas las localidades -aunque con mayor incidencia en las ciudades- est\u00e1n recibiendo desde enero m\u00e1s ingresos a trav\u00e9s del flamante Fondo de Distribuci\u00f3n Poblacional, de car\u00e1cter permanente, actualizable y solventado por Rentas Generales de La Pampa. A fines del a\u00f1o pasado, estaba establecido en unos 3500 millones de pesos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las municipalidades hacen n\u00fameros para definir si podr\u00e1n hacer frente al 20% de aumento a estatales dispuesto por el Gobierno provincial. Diario Textual confirm\u00f3 que Santa Rosa no llega a&hellip;<\/p>\n","protected":false},"author":7,"featured_media":254655,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,11,8],"tags":[],"class_list":["post-254652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-que-pasa","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Las municipalidades hacen n\u00fameros para definir si podr\u00e1n hacer frente al 20% de aumento a estatales dispuesto por el Gobierno provincial. Diario Textual confirm\u00f3 que Santa Rosa no llega a&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-21T11:30:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-22T11:33:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/02\/billetescajero2024-111.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/\"},\"author\":{\"name\":\"diario5\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\"},\"headline\":\"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan\",\"datePublished\":\"2024-02-21T11:30:32+00:00\",\"dateModified\":\"2024-02-22T11:33:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/\"},\"wordCount\":514,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/billetescajero2024-111.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"A - QUE PASA (al costado)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/\",\"name\":\"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/billetescajero2024-111.jpg\",\"datePublished\":\"2024-02-21T11:30:32+00:00\",\"dateModified\":\"2024-02-22T11:33:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/billetescajero2024-111.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/billetescajero2024-111.jpg\",\"width\":1000,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2024\\\/02\\\/21\\\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\",\"name\":\"diario5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"caption\":\"diario5\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/","og_locale":"es_ES","og_type":"article","og_title":"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan - Diario Textual","og_description":"Las municipalidades hacen n\u00fameros para definir si podr\u00e1n hacer frente al 20% de aumento a estatales dispuesto por el Gobierno provincial. Diario Textual confirm\u00f3 que Santa Rosa no llega a&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2024-02-21T11:30:32+00:00","article_modified_time":"2024-02-22T11:33:22+00:00","og_image":[{"width":1000,"height":655,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/02\/billetescajero2024-111.jpg","type":"image\/jpeg"}],"author":"diario5","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario5","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/"},"author":{"name":"diario5","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067"},"headline":"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan","datePublished":"2024-02-21T11:30:32+00:00","dateModified":"2024-02-22T11:33:22+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/"},"wordCount":514,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/02\/billetescajero2024-111.jpg","articleSection":["A - ES NOTICIA (van abajo)","A - QUE PASA (al costado)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/","name":"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/02\/billetescajero2024-111.jpg","datePublished":"2024-02-21T11:30:32+00:00","dateModified":"2024-02-22T11:33:22+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/02\/billetescajero2024-111.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/02\/billetescajero2024-111.jpg","width":1000,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2024\/02\/21\/aumento-del-20-a-estatales-pico-en-veremos-victorica-y-acha-lo-pagan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Aumento del 20% a estatales: Santa Rosa no llega, Pico lo analiza y Victorica y Acha lo pagan"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067","name":"diario5","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","caption":"diario5"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario5\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/254652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=254652"}],"version-history":[{"count":6,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/254652\/revisions"}],"predecessor-version":[{"id":254663,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/254652\/revisions\/254663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/254655"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=254652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=254652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=254652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}