{"id":285602,"date":"2025-01-03T18:30:56","date_gmt":"2025-01-03T21:30:56","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=285602"},"modified":"2025-01-06T08:24:50","modified_gmt":"2025-01-06T11:24:50","slug":"poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/","title":{"rendered":"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d"},"content":{"rendered":"\n<p>El diputado provincial <strong>Hip\u00f3lito \u201cPoli\u201d Altolaguirre<\/strong> insisti\u00f3 en las \u00faltimas horas con que la UCR deber\u00eda aliarse con \u201ctodos\u201d los opositores para lograr arrebatarle la gobernaci\u00f3n al peronismo. Es decir, le abri\u00f3 la puerta a sumar incluso a La Libertad Avanza.<\/p>\n\n\n\n<p>\u201cCreo que en nuestra provincia debe ser ese el objetivo: un gran frente electoral con todos, inclusive sectores del justicialismo que no tengo dudas van a estar\u201d, dijo en declaraciones a LU 33.<\/p>\n\n\n\n<p>Adem\u00e1s, se refiri\u00f3 a la relaci\u00f3n cercana de intendentes del radicalismo -como Abel Sabarots, de General Acha, y Hugo Kenny, de Victorica, entre otros- con el Gobierno de Sergio Ziliotto. \u201cTenemos una relaci\u00f3n con todos los intendentes radicales, y hay que entender que a veces tienen que ir a mendigar a Casa de Gobierno porque deben gestionar sus localidades. Es complicada su situaci\u00f3n porque deben llevar soluciones a los vecinos\u201d, expres\u00f3.<\/p>\n\n\n\n<p>La posici\u00f3n de Altolaguirre, de todas maneras, no es la de toda la UCR. Precisamente hay jefes comunales que rechazan toda posibilidad de hacer un frente con La Libertad Avanza.<\/p>\n\n\n\n<p>Igual Altolaguirre volvi\u00f3 a decir que, si hubieran ampliado el frente a\u00fan m\u00e1s en 2023 (pretend\u00eda sumar a Comunidad Organizada, por ejemplo), podr\u00edan haber vencido a Ziliotto. \u201cLa \u00faltima (elecci\u00f3n de mayo de 2023) perdimos por dos o tres puntos la Provincia. Si hubi\u00e9ramos hecho un gran frente electoral provincial con la idiosincrasia de quienes creemos que la provincia va a salir adelante impulsando el empleo privado, que el Estado garantice lo que tiene que garantizar, que es educaci\u00f3n, salud, seguridad y justicia, pero que la parte de la producci\u00f3n y reactivaci\u00f3n la deje en quienes est\u00e1n dispuestos a arriesgarse, generar trabajo y saben hacerlo, el resultado hubiera sido otro\u201d, dijo.<\/p>\n\n\n\n<p>\u201cCreo que en nuestra provincia debe ser ese el objetivo, un gran frente electoral con todos, inclusive sectores del justicialismo que no tengo dudas van a estar\u201d, sostuvo.<\/p>\n\n\n\n<p><strong>&#8211; \u00bfIncluyendo a La Libertad Avanza?<\/strong><\/p>\n\n\n\n<p>&#8211; La pol\u00edtica cambi\u00f3 y hoy los frentes son as\u00ed, con gente que no piensan todos iguales. Sin duda hay vientos de cambio y en 2027 habr\u00e1 un cambio de signo pol\u00edtico en la provincia.<\/p>\n\n\n\n<p>El dirigente radical tambi\u00e9n dijo que el \u201cmodelo peronista\u201d de las \u00faltimas cuatro d\u00e9cadas en La Pampa est\u00e1 acabado. \u201cQued\u00f3 demostrado que la pol\u00edtica del oficialismo en estos 40 a\u00f1os ha sido perjudicial para la actividad econ\u00f3mica, que no se desarrolla\u201d, dijo. \u201cLa provincia no crece demogr\u00e1ficamente, ni en infraestructura, no hay oportunidades de trabajo y ese modelo ha quedado totalmente agotado\u201d, expres\u00f3-<\/p>\n\n\n\n<p>\u201cLa gente est\u00e1 cansada de ver c\u00f3mo se malgasta el dinero. Lo que tenemos que ajustar la cantidad de funcionarios, va a costar porque llevan a\u00f1os haci\u00e9ndolo, pero hay que ordenar el Estado, achicar los gastos y hacerlo m\u00e1s eficiente. No pod\u00e9s pedirle solidaridad a quien le cobras cada vez m\u00e1s impuestos\u201d, expres\u00f3.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diputado provincial Hip\u00f3lito \u201cPoli\u201d Altolaguirre insisti\u00f3 en las \u00faltimas horas con que la UCR deber\u00eda aliarse con \u201ctodos\u201d los opositores para lograr arrebatarle la gobernaci\u00f3n al peronismo. Es decir,&hellip;<\/p>\n","protected":false},"author":3,"featured_media":215609,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,11,8],"tags":[],"class_list":["post-285602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-que-pasa","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El diputado provincial Hip\u00f3lito \u201cPoli\u201d Altolaguirre insisti\u00f3 en las \u00faltimas horas con que la UCR deber\u00eda aliarse con \u201ctodos\u201d los opositores para lograr arrebatarle la gobernaci\u00f3n al peronismo. Es decir,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-03T21:30:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-06T11:24:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/02\/altolaguirrehipolitopoli2023-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1185\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d\",\"datePublished\":\"2025-01-03T21:30:56+00:00\",\"dateModified\":\"2025-01-06T11:24:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/\"},\"wordCount\":519,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/altolaguirrehipolitopoli2023-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"A - QUE PASA (al costado)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/\",\"name\":\"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/altolaguirrehipolitopoli2023-1.jpg\",\"datePublished\":\"2025-01-03T21:30:56+00:00\",\"dateModified\":\"2025-01-06T11:24:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/altolaguirrehipolitopoli2023-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/altolaguirrehipolitopoli2023-1.jpg\",\"width\":2000,\"height\":1185},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/03\\\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d - Diario Textual","og_description":"El diputado provincial Hip\u00f3lito \u201cPoli\u201d Altolaguirre insisti\u00f3 en las \u00faltimas horas con que la UCR deber\u00eda aliarse con \u201ctodos\u201d los opositores para lograr arrebatarle la gobernaci\u00f3n al peronismo. Es decir,&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-01-03T21:30:56+00:00","article_modified_time":"2025-01-06T11:24:50+00:00","og_image":[{"width":2000,"height":1185,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/02\/altolaguirrehipolitopoli2023-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d","datePublished":"2025-01-03T21:30:56+00:00","dateModified":"2025-01-06T11:24:50+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/"},"wordCount":519,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/02\/altolaguirrehipolitopoli2023-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","A - QUE PASA (al costado)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/","name":"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/02\/altolaguirrehipolitopoli2023-1.jpg","datePublished":"2025-01-03T21:30:56+00:00","dateModified":"2025-01-06T11:24:50+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/02\/altolaguirrehipolitopoli2023-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/02\/altolaguirrehipolitopoli2023-1.jpg","width":2000,"height":1185},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/03\/poli-altolaguirre-quiere-una-alianza-de-la-ucr-con-los-libertarios-un-gran-frente-electoral-con-todos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"\u201cPoli\u201d Altolaguirre abre la puerta a una alianza de la UCR con los libertarios: \u201cUn gran frente electoral con todos\u201d"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/285602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=285602"}],"version-history":[{"count":4,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/285602\/revisions"}],"predecessor-version":[{"id":285624,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/285602\/revisions\/285624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/215609"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=285602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=285602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=285602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}