{"id":286470,"date":"2025-01-16T08:35:06","date_gmt":"2025-01-16T11:35:06","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=286470"},"modified":"2025-01-16T19:51:39","modified_gmt":"2025-01-16T22:51:39","slug":"incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/","title":{"rendered":"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados"},"content":{"rendered":"\n<p><strong>Un incendio forestal de gran magnitud afecta a la localidad de Epuy\u00e9n, en el noroeste de Chubut, donde las llamas han destruido decenas de viviendas y han obligado a evacuar a cientos de vecinos.<\/strong><\/p>\n\n\n\n<p>Las altas temperaturas, sumadas a r\u00e1fagas de viento de hasta 70 km\/h, contribuyeron al avance descontrolado del fuego. Seg\u00fan reportes oficiales, por el momento, no se han registrado heridos.<\/p>\n\n\n\n<p>De acuerdo con las autoridades locales, el incendio se origin\u00f3 en un sector pr\u00f3ximo al lago Epuy\u00e9n, entre el cementerio local y la Escuela N\u00b0 9, el mi\u00e9rcoles por la tarde. Debido a la r\u00e1pida propagaci\u00f3n, las autoridades el intendente de la localidad, Jos\u00e9 Contreras, dispuso la evacuaci\u00f3n inmediata de los vecinos para protegerlos y facilitar las labores de los equipos de emergencia.<\/p>\n\n\n\n<p>\u201cHay varias casas quemadas y un principio de incendio en la Escuela 9, pero el clima no ayuda\u201d, declar\u00f3 Contreras en di\u00e1logo con FM 105.5 Radio de la Cordillera, calificando a la situaci\u00f3n como \u201csin precedentes\u201d. Es m\u00e1s, el mismo intendente tuvo que abandonar su vivienda junto a su familia por su bien.\u00a0<\/p>\n\n\n\n<p>Por su parte, Jorge Bonansea, titular del \u00e1rea de Protecci\u00f3n Civil de\u00a0<strong>Epuy\u00e9n<\/strong>, inform\u00f3 que el\u00a0<strong>incendio\u00a0<\/strong>tiene tres frentes activos: la cabecera, que cruz\u00f3 la Ruta 40 cerca de las canteras; el flanco izquierdo, ubicado frente al pueblo; y el flanco derecho, que afecta la zona de Puerto Bonito en el lago Epuy\u00e9n y avanza hacia el cerro Epuy\u00e9n.<\/p>\n\n\n\n<p>Por precauci\u00f3n, se decidi\u00f3 el corte de la Ruta Nacional N\u00b0 40 entre Epuy\u00e9n y el cruce con Cholila, ya que las llamas alcanzaron parte del camino. Los desv\u00edos hacia El Mait\u00e9n y otros puntos de la regi\u00f3n est\u00e1n habilitados a trav\u00e9s de la Ruta Provincial N\u00b070 y la Ruta Nacional 1S40 para evitar la Ruta 40.&nbsp;<\/p>\n\n\n\n<p>Para combatir las llamas, brigadistas del Servicio Provincial de Manejo del Fuego de diversas localidades como Las Golondrinas, Cholila, Lago Puelo, Puerto Patriada, y El Mait\u00e9n trabajan en conjunto con personal de bases nacionales, bomberos voluntarios y el Parque Nacional Lago Puelo. Adem\u00e1s, el Servicio Nacional de Manejo del Fuego envi\u00f3 tres aviones hidrantes, que operan desde el aer\u00f3dromo de El Bols\u00f3n.<\/p>\n\n\n\n<p>En tanto, el gobernador de Chubut, Ignacio Torres, conform\u00f3 un Comit\u00e9 de Emergencia para coordinar los esfuerzos y anunci\u00f3 que brindar\u00e1 una conferencia de prensa este jueves desde Epuy\u00e9n. \u201cLa prioridad en este momento es resguardar la vida de los habitantes de la zona, para lo cual hemos impulsado un amplio operativo y evacuado a aquellos vecinos que residen en zonas pr\u00f3ximas a las alcanzadas por el incendio\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Paralelamente, se activaron centros de recepci\u00f3n de donaciones en el Gimnasio Municipal de Epuy\u00e9n, la Comisar\u00eda de la Familia de El Bols\u00f3n y la Casa de la Cultura de El Hoyo, donde se reciben art\u00edculos como alimentos no perecederos, ropa de abrigo y medicamentos. Las autoridades recomiendan a quienes evac\u00faan llevar solo elementos esenciales y respetar las rutas habilitadas para garantizar la seguridad.<\/p>\n\n\n\n<p>A\u00fan no se han identificado las causas que dieron inicio al fuego, que sigue avanzando mientras contin\u00faan las tareas de contenci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un incendio forestal de gran magnitud afecta a la localidad de Epuy\u00e9n, en el noroeste de Chubut, donde las llamas han destruido decenas de viviendas y han obligado a evacuar&hellip;<\/p>\n","protected":false},"author":3,"featured_media":286473,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-286470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Un incendio forestal de gran magnitud afecta a la localidad de Epuy\u00e9n, en el noroeste de Chubut, donde las llamas han destruido decenas de viviendas y han obligado a evacuar&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-16T11:35:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T22:51:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/epuyenincendio2025-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados\",\"datePublished\":\"2025-01-16T11:35:06+00:00\",\"dateModified\":\"2025-01-16T22:51:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/\"},\"wordCount\":560,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/epuyenincendio2025-3.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/\",\"name\":\"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/epuyenincendio2025-3.jpg\",\"datePublished\":\"2025-01-16T11:35:06+00:00\",\"dateModified\":\"2025-01-16T22:51:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/epuyenincendio2025-3.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/epuyenincendio2025-3.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/16\\\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/","og_locale":"es_ES","og_type":"article","og_title":"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados - Diario Textual","og_description":"Un incendio forestal de gran magnitud afecta a la localidad de Epuy\u00e9n, en el noroeste de Chubut, donde las llamas han destruido decenas de viviendas y han obligado a evacuar&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-01-16T11:35:06+00:00","article_modified_time":"2025-01-16T22:51:39+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/epuyenincendio2025-3.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados","datePublished":"2025-01-16T11:35:06+00:00","dateModified":"2025-01-16T22:51:39+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/"},"wordCount":560,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/epuyenincendio2025-3.jpg","articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/","name":"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/epuyenincendio2025-3.jpg","datePublished":"2025-01-16T11:35:06+00:00","dateModified":"2025-01-16T22:51:39+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/epuyenincendio2025-3.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/epuyenincendio2025-3.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/16\/incendio-en-epuyen-casas-quemadas-miles-de-hectareas-afectadas-y-cientos-de-evacuados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Incendio en Epuy\u00e9n: casas quemadas, miles de hect\u00e1reas afectadas y cientos de evacuados"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/286470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=286470"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/286470\/revisions"}],"predecessor-version":[{"id":286471,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/286470\/revisions\/286471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/286473"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=286470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=286470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=286470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}