{"id":286963,"date":"2025-01-21T23:39:11","date_gmt":"2025-01-22T02:39:11","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=286963"},"modified":"2025-01-22T08:39:08","modified_gmt":"2025-01-22T11:39:08","slug":"milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/","title":{"rendered":"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d"},"content":{"rendered":"\n<p><strong>El multimillonario Elon Musk subi\u00f3 este 20 de enero, en la investidura de Donald Trump, al escenario del Capital One Arena, en Washington, entre grandes ovaciones, agitando los brazos y gritando. Realiz\u00f3 dos veces un gesto con la mano que muchos han se\u00f1alado que ha imitado el saludo nazi. Por la avalancha de cr\u00edticas, Musk reaccion\u00f3 con iron\u00eda y dijo que sus cr\u00edticos necesitan \u201cmejores trucos sucios\u201d para cuestionarlo.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Por lo pronto, el presidente <strong>Javier Milei <\/strong>sali\u00f3 a respaldarlo con un posteo en X titulado \u201cNazi las pelotas\u201d. Es el siguiente:<\/p>\n\n\n\n<p><em>\u201cElon Musk debe ser uno de los hombres m\u00e1s importantes de la Historia, que esta empujando el progreso humano a ritmos vertiginosos, y siempre ha defendido la libertad en su forma mas pura, para todos.<\/em><\/p>\n\n\n\n<p><em>Compr\u00f3 X en un acto que fue considerado una locura desde el punto de vista empresarial, pero que sin dudas ser\u00e1 considerado uno de sus grandes aportes a la humanidad, tomando control de una plataforma que se supon\u00eda era un foro de debate p\u00fablico, pero resulta que estaba programada para cancelar cualquier discurso que no fuera el discurso woke hegem\u00f3nico.<\/em><\/p>\n\n\n\n<p><em>Por eso hoy toda la progres\u00eda internacional se monta sobre el inocente gesto de @elonmusk para tildarlo de nazi. Porque su lucha por la libertad atenta contra el control hegem\u00f3nico del wokismo internacional.<\/em><\/p>\n\n\n\n<p><em>Pero el mundo cambi\u00f3. Elon no est\u00e1 solo. Los que luchamos por la libertad ya no estamos solos. Somos millones. Y ahora tambi\u00e9n recuperamos la \u00abtierra de la libertad\u00bb que estaba en sus manos, gracias a nuestro querido @realDonaldTrump.<\/em><\/p>\n\n\n\n<p><em>No s\u00f3lo no les tenemos miedo. Sino que los vamos a ir a buscar hasta el \u00faltimo rinc\u00f3n del planeta en defensa de la LIBERTAD.<\/em><\/p>\n\n\n\n<p><em>Zurdos hijos de putas tiemblen.<\/em><\/p>\n\n\n\n<p><em>La libertad avanza.<\/em><\/p>\n\n\n\n<p><em>VIVA LA LIBERTAD CARAJO\u201d.<\/em><\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">NAZI LAS PELOTAS<br>Elon Musk debe ser uno de los hombres m\u00e1s importantes de la Historia, que esta empujando el progreso humano a ritmos vertiginosos, y siempre ha defendido la libertad en su forma mas pura, para todos.<br><br>Compro X en un acto que fue considerado una locura desde el\u2026<\/p>&mdash; Javier Milei (@JMilei) <a href=\"https:\/\/twitter.com\/JMilei\/status\/1881887233516482610?ref_src=twsrc%5Etfw\">January 22, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n","protected":false},"excerpt":{"rendered":"<p>El multimillonario Elon Musk subi\u00f3 este 20 de enero, en la investidura de Donald Trump, al escenario del Capital One Arena, en Washington, entre grandes ovaciones, agitando los brazos y&hellip;<\/p>\n","protected":false},"author":3,"featured_media":286965,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,8],"tags":[],"class_list":["post-286963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El multimillonario Elon Musk subi\u00f3 este 20 de enero, en la investidura de Donald Trump, al escenario del Capital One Arena, en Washington, entre grandes ovaciones, agitando los brazos y&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-22T02:39:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T11:39:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/muskelonsaludo2025-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"351\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d\",\"datePublished\":\"2025-01-22T02:39:11+00:00\",\"dateModified\":\"2025-01-22T11:39:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/\"},\"wordCount\":377,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/muskelonsaludo2025-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/\",\"name\":\"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/muskelonsaludo2025-1.jpg\",\"datePublished\":\"2025-01-22T02:39:11+00:00\",\"dateModified\":\"2025-01-22T11:39:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/muskelonsaludo2025-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/muskelonsaludo2025-1.jpg\",\"width\":620,\"height\":351},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/21\\\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/","og_locale":"es_ES","og_type":"article","og_title":"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d - Diario Textual","og_description":"El multimillonario Elon Musk subi\u00f3 este 20 de enero, en la investidura de Donald Trump, al escenario del Capital One Arena, en Washington, entre grandes ovaciones, agitando los brazos y&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-01-22T02:39:11+00:00","article_modified_time":"2025-01-22T11:39:08+00:00","og_image":[{"width":620,"height":351,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/muskelonsaludo2025-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d","datePublished":"2025-01-22T02:39:11+00:00","dateModified":"2025-01-22T11:39:08+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/"},"wordCount":377,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/muskelonsaludo2025-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/","name":"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/muskelonsaludo2025-1.jpg","datePublished":"2025-01-22T02:39:11+00:00","dateModified":"2025-01-22T11:39:08+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/muskelonsaludo2025-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/muskelonsaludo2025-1.jpg","width":620,"height":351},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/21\/milei-banco-el-saludo-nazi-de-elon-musk-y-amenazo-zurdos-hijos-de-putas-tiemblen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Milei banc\u00f3 el saludo (\u00bfnazi?) de Elon Musk y amenaz\u00f3: \u201cZurdos hijos de putas tiemblen\u201d"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/286963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=286963"}],"version-history":[{"count":5,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/286963\/revisions"}],"predecessor-version":[{"id":286969,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/286963\/revisions\/286969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/286965"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=286963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=286963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=286963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}