{"id":287049,"date":"2025-01-23T09:30:50","date_gmt":"2025-01-23T12:30:50","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=287049"},"modified":"2025-01-23T20:27:21","modified_gmt":"2025-01-23T23:27:21","slug":"la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/","title":{"rendered":"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa"},"content":{"rendered":"\n<p>El Comit\u00e9 Provincia de la UCR contin\u00faa en su campa\u00f1a contra la Revisi\u00f3n T\u00e9cnica Obligatoria (RTO) que se comenz\u00f3 a exigir en Santa Rosa. Ahora anunci\u00f3 que har\u00e1 un instructivo para hacer el descargo y evitar pagar la multa.<\/p>\n\n\n\n<p>\u201cLa Municipalidad de Santa Rosa comenz\u00f3 a exigir la RTO. Con el pretexto de la seguridad vial, el Intendente encubre la desesperaci\u00f3n por recaudar y hacer caja con multas desde los 300.000 pesos\u201d, sostuvo en un parte de prensa.<\/p>\n\n\n\n<p>\u201cComo en una cacer\u00eda de veh\u00edculos, infunden temor con un objetivo: hacer repuntar el negocio, direccionando descaradamente a que las personas vayan a hacer la verificaci\u00f3n en el taller T\u00e9cnica Sur, el que montaron irregularmente y en tiempo r\u00e9cord\u201d, asegur\u00f3. La municipalidad, por lo pronto, considera que ese taller est\u00e1 totalmente habilitado para hacer la RTO y que tenga vigencia en todo el pa\u00eds.<\/p>\n\n\n\n<p>\u201cEl comit\u00e9 provincia de la UCR impulsar\u00e1 la posibilidad de realizar un descargo para personas que no vivan en Santa Rosa y\/o que no tengan el veh\u00edculo radicado en Santa Rosa. &nbsp;Creemos firmemente que es una medida innecesaria, con fines meramente recaudatorios y que la gesti\u00f3n municipal de la capital tiene las prioridades distorsionadas de lo que hoy el santarrose\u00f1o y el pampeano que visita la capital est\u00e1 demandando\u201d, finaliz\u00f3.<\/p>\n\n\n\n<p>La RTO es la revisi\u00f3n t\u00e9cnica obligatoria del veh\u00edculo que incluye el control peri\u00f3dico del estado mec\u00e1nico y de la emisi\u00f3n de gases contaminantes. En Santa Rosa fue establecida por ordenanza n\u00ba 6977\/2023.<\/p>\n\n\n\n<p>Hay dos talleres donde se puede hacer: T\u00e9cnica Sur (Santiago Marzo Sur 1310 esquina&nbsp;Wilde, de lunes a viernes de 8 a 17) y Patagonia Vertec (Corona Martinez 521).<\/p>\n\n\n\n<p>El costo var\u00eda de acuerdo a la categor\u00eda del veh\u00edculo. El valor para un auto hoy es de $45.000.<\/p>\n\n\n\n<p>Las multas van desde las 300 unidades fijas a 1000 unidades fijas, depende de los antecedentes del titular del veh\u00edculo. Cada unidad fija equivale a un litro de nafta s\u00faper.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Comit\u00e9 Provincia de la UCR contin\u00faa en su campa\u00f1a contra la Revisi\u00f3n T\u00e9cnica Obligatoria (RTO) que se comenz\u00f3 a exigir en Santa Rosa. Ahora anunci\u00f3 que har\u00e1 un instructivo&hellip;<\/p>\n","protected":false},"author":3,"featured_media":272918,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-287049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El Comit\u00e9 Provincia de la UCR contin\u00faa en su campa\u00f1a contra la Revisi\u00f3n T\u00e9cnica Obligatoria (RTO) que se comenz\u00f3 a exigir en Santa Rosa. Ahora anunci\u00f3 que har\u00e1 un instructivo&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-23T12:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T23:27:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/08\/rtotallertecnicasur2024-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa\",\"datePublished\":\"2025-01-23T12:30:50+00:00\",\"dateModified\":\"2025-01-23T23:27:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/\"},\"wordCount\":365,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/rtotallertecnicasur2024-2.jpg\",\"articleSection\":[\"A - QUE PASA (al costado)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/\",\"name\":\"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/rtotallertecnicasur2024-2.jpg\",\"datePublished\":\"2025-01-23T12:30:50+00:00\",\"dateModified\":\"2025-01-23T23:27:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/rtotallertecnicasur2024-2.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/rtotallertecnicasur2024-2.jpg\",\"width\":1500,\"height\":844},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/23\\\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/","og_locale":"es_ES","og_type":"article","og_title":"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa - Diario Textual","og_description":"El Comit\u00e9 Provincia de la UCR contin\u00faa en su campa\u00f1a contra la Revisi\u00f3n T\u00e9cnica Obligatoria (RTO) que se comenz\u00f3 a exigir en Santa Rosa. Ahora anunci\u00f3 que har\u00e1 un instructivo&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-01-23T12:30:50+00:00","article_modified_time":"2025-01-23T23:27:21+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/08\/rtotallertecnicasur2024-2.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa","datePublished":"2025-01-23T12:30:50+00:00","dateModified":"2025-01-23T23:27:21+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/"},"wordCount":365,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/08\/rtotallertecnicasur2024-2.jpg","articleSection":["A - QUE PASA (al costado)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/","name":"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/08\/rtotallertecnicasur2024-2.jpg","datePublished":"2025-01-23T12:30:50+00:00","dateModified":"2025-01-23T23:27:21+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/08\/rtotallertecnicasur2024-2.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/08\/rtotallertecnicasur2024-2.jpg","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/23\/la-ucr-anuncia-que-hara-un-instructivo-para-hacer-el-descargo-y-no-pagar-la-multa-de-la-rto-en-santa-rosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La UCR anuncia que har\u00e1 un instructivo para hacer el descargo y no pagar la multa de la RTO en Santa Rosa"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=287049"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287049\/revisions"}],"predecessor-version":[{"id":287051,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287049\/revisions\/287051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/272918"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=287049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=287049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=287049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}