{"id":287143,"date":"2025-01-24T11:44:18","date_gmt":"2025-01-24T14:44:18","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=287143"},"modified":"2025-01-24T22:08:28","modified_gmt":"2025-01-25T01:08:28","slug":"retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/","title":{"rendered":"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3"},"content":{"rendered":"\n<p><strong>El Gobierno anunci\u00f3 la reducci\u00f3n temporal de las retenciones al agro y la eliminaci\u00f3n definitiva de los derechos de exportaci\u00f3n para las econom\u00edas regionales. Esta decisi\u00f3n llega como respuesta a un sector que enfrenta desaf\u00edos cr\u00edticos, como la sequ\u00eda y la ca\u00edda de precios internacionales, pero es todav\u00eda m\u00e1s importante para la administraci\u00f3n libertaria, que est\u00e1 urgido de d\u00f3lares y apura al agro para que liquide. En el caso de La Pampa, si bien hay un alivio para sectores de la soja y otros granos, no implica ning\u00fan cambio con respecto a la principal exportaci\u00f3n: la carne, que tributa el 6,75%.<\/strong><\/p>\n\n\n\n<p>El impacto m\u00e1s inmediato ser\u00e1 la baja de las al\u00edcuotas de los principales cultivos. Desde el pr\u00f3ximo lunes, la soja reducir\u00e1 su retenci\u00f3n del 33% al 26%, mientras que derivados como el aceite y la harina pasar\u00e1n del 31% al 24,5%. Por otro lado, el trigo, la cebada, el sorgo y el ma\u00edz disminuir\u00e1n del 12% al 9,5%. Incluso el girasol, que ten\u00eda una carga del 7%, pasar\u00e1 a un 5,5%. Estas reducciones estar\u00e1n vigentes hasta el 30 de junio de 2025, brindando un alivio temporal al sector.<\/p>\n\n\n\n<p>Lo cierto es que<strong> la baja temporal de las retenciones es una medida para tapar el hueco en la liquidaci\u00f3n de divisas y mantener pisado el d\u00f3lar.<\/strong> Una medida que no resuelve el problema de fondo: el encarecimiento en d\u00f3lares de Argentina y la p\u00e9rdida de competitividad de las exportaciones.<\/p>\n\n\n\n<p><strong>El objetivo del Gobierno de Javier Milei es que se acelere la liquidaci\u00f3n de la cosecha para tener los d\u00f3lares que le empezaron a faltar producto del aumento de las importaciones y la ca\u00edda de las exportaciones.<\/strong><\/p>\n\n\n\n<p>En este punto, no son pocos los que se\u00f1alan que esta medida es similar a la del entonces ministro Mart\u00edn Guzm\u00e1n, en octubre de 2020, que ante la salida de la pandemia comenz\u00f3 a sufrir presiones cambiarias.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"tnCA8vRjeG\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/ministro-fernandez-la-baja-de-retenciones-es-bienvenida-aunque-financiada-por-provincias-y-municipios\/\">Ministro Fern\u00e1ndez: \u201cLa baja de retenciones es bienvenida, aunque financiada por provincias y municipios\u201d<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abMinistro Fern\u00e1ndez: \u201cLa baja de retenciones es bienvenida, aunque financiada por provincias y municipios\u201d\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/ministro-fernandez-la-baja-de-retenciones-es-bienvenida-aunque-financiada-por-provincias-y-municipios\/embed\/#?secret=d2U2e3k8yh#?secret=tnCA8vRjeG\" data-secret=\"tnCA8vRjeG\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno anunci\u00f3 la reducci\u00f3n temporal de las retenciones al agro y la eliminaci\u00f3n definitiva de los derechos de exportaci\u00f3n para las econom\u00edas regionales. Esta decisi\u00f3n llega como respuesta a&hellip;<\/p>\n","protected":false},"author":3,"featured_media":250808,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,20],"tags":[],"class_list":["post-287143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada-2","category-campo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3 - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3 - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El Gobierno anunci\u00f3 la reducci\u00f3n temporal de las retenciones al agro y la eliminaci\u00f3n definitiva de los derechos de exportaci\u00f3n para las econom\u00edas regionales. Esta decisi\u00f3n llega como respuesta a&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-24T14:44:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-25T01:08:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/carnedescargamediarestelam.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3\",\"datePublished\":\"2025-01-24T14:44:18+00:00\",\"dateModified\":\"2025-01-25T01:08:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/\"},\"wordCount\":356,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/carnedescargamediarestelam.jpg\",\"articleSection\":[\"A - PORTADA2\",\"CAMPO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/\",\"name\":\"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3 - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/carnedescargamediarestelam.jpg\",\"datePublished\":\"2025-01-24T14:44:18+00:00\",\"dateModified\":\"2025-01-25T01:08:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/carnedescargamediarestelam.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/carnedescargamediarestelam.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/24\\\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3 - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/","og_locale":"es_ES","og_type":"article","og_title":"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3 - Diario Textual","og_description":"El Gobierno anunci\u00f3 la reducci\u00f3n temporal de las retenciones al agro y la eliminaci\u00f3n definitiva de los derechos de exportaci\u00f3n para las econom\u00edas regionales. Esta decisi\u00f3n llega como respuesta a&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-01-24T14:44:18+00:00","article_modified_time":"2025-01-25T01:08:28+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/carnedescargamediarestelam.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3","datePublished":"2025-01-24T14:44:18+00:00","dateModified":"2025-01-25T01:08:28+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/"},"wordCount":356,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/carnedescargamediarestelam.jpg","articleSection":["A - PORTADA2","CAMPO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/","name":"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3 - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/carnedescargamediarestelam.jpg","datePublished":"2025-01-24T14:44:18+00:00","dateModified":"2025-01-25T01:08:28+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/carnedescargamediarestelam.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/01\/carnedescargamediarestelam.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/24\/retenciones-la-carne-vacuna-la-principal-exportacion-de-la-pampa-no-se-toco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Retenciones: la carne vacuna, la principal exportaci\u00f3n de La Pampa, no se toc\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=287143"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287143\/revisions"}],"predecessor-version":[{"id":287148,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287143\/revisions\/287148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/250808"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=287143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=287143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=287143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}