{"id":287568,"date":"2025-01-29T22:46:05","date_gmt":"2025-01-30T01:46:05","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=287568"},"modified":"2025-01-29T22:48:16","modified_gmt":"2025-01-30T01:48:16","slug":"boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/","title":{"rendered":"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final"},"content":{"rendered":"\n<p>Boca Juniors igual\u00f3 esta noche ante Uni\u00f3n de Santa Fe, por 1 a 1, en el encuentro correspondiente a&nbsp;la segunda fecha del Torneo Apertura de la Liga Profesional de F\u00fatbol.<\/p>\n\n\n\n<p>El Xeneize comenz\u00f3 ganando en el amanecer del partido, con gol del uruguayo Marcelo Saracchi, a los 5 minutos.<\/p>\n\n\n\n<p>Mientras que Franco Fragapane&nbsp;lo empat\u00f3 para los santafecinos a los 47 del complemento.<\/p>\n\n\n\n<p>El cotejo se disput\u00f3 en el Estadio 15 de Abril y fue arbitrado por\u00a0Pablo Echavarr\u00eda.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boca Juniors igual\u00f3 esta noche ante Uni\u00f3n de Santa Fe, por 1 a 1, en el encuentro correspondiente a&nbsp;la segunda fecha del Torneo Apertura de la Liga Profesional de F\u00fatbol.&hellip;<\/p>\n","protected":false},"author":3,"featured_media":287572,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,3],"tags":[],"class_list":["post-287568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-deportes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Boca Juniors igual\u00f3 esta noche ante Uni\u00f3n de Santa Fe, por 1 a 1, en el encuentro correspondiente a&nbsp;la segunda fecha del Torneo Apertura de la Liga Profesional de F\u00fatbol.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-30T01:46:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-30T01:48:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/bocaunion2025-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final\",\"datePublished\":\"2025-01-30T01:46:05+00:00\",\"dateModified\":\"2025-01-30T01:48:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/\"},\"wordCount\":95,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/bocaunion2025-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"DEPORTES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/\",\"name\":\"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/bocaunion2025-1.jpg\",\"datePublished\":\"2025-01-30T01:46:05+00:00\",\"dateModified\":\"2025-01-30T01:48:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/bocaunion2025-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/bocaunion2025-1.jpg\",\"width\":1000,\"height\":641},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/29\\\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/","og_locale":"es_ES","og_type":"article","og_title":"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final - Diario Textual","og_description":"Boca Juniors igual\u00f3 esta noche ante Uni\u00f3n de Santa Fe, por 1 a 1, en el encuentro correspondiente a&nbsp;la segunda fecha del Torneo Apertura de la Liga Profesional de F\u00fatbol.&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-01-30T01:46:05+00:00","article_modified_time":"2025-01-30T01:48:16+00:00","og_image":[{"width":1000,"height":641,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/bocaunion2025-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final","datePublished":"2025-01-30T01:46:05+00:00","dateModified":"2025-01-30T01:48:16+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/"},"wordCount":95,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/bocaunion2025-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","DEPORTES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/","name":"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/bocaunion2025-1.jpg","datePublished":"2025-01-30T01:46:05+00:00","dateModified":"2025-01-30T01:48:16+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/bocaunion2025-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/01\/bocaunion2025-1.jpg","width":1000,"height":641},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/29\/boca-se-durmio-en-santa-fe-y-union-se-lo-empato-en-el-final\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Boca se durmi\u00f3 en Santa Fe y Uni\u00f3n se lo empat\u00f3 en el final"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=287568"}],"version-history":[{"count":3,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287568\/revisions"}],"predecessor-version":[{"id":287573,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287568\/revisions\/287573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/287572"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=287568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=287568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=287568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}