{"id":287655,"date":"2025-01-31T07:57:31","date_gmt":"2025-01-31T10:57:31","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=287655"},"modified":"2025-01-31T11:18:55","modified_gmt":"2025-01-31T14:18:55","slug":"alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/","title":{"rendered":"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C"},"content":{"rendered":"\n<p>Sigue el calor agobiante en algunas zonas durante el inicio del 2025,&nbsp;y por eso el&nbsp;<strong>Servicio Meteorol\u00f3gico Nacional (SMN)<\/strong>&nbsp;manten\u00eda para este&nbsp;viernes&nbsp;nuevos&nbsp;<strong>alertas<\/strong>&nbsp;por&nbsp;<strong>altas temperaturas<\/strong>&nbsp;para diferentes distritos.<\/p>\n\n\n\n<p>De esta manera, se mantiene el\u00a0<strong>alerta amarillo en la Ciudad de Buenos Aires y en toda la provincia de Buenos Aires a excepci\u00f3n de la costa; y zonas de Entre R\u00edos, Santa Fe, C\u00f3rdoba, San Juan, San Luis, Mendoza, La Pampa, Neuqu\u00e9n y R\u00edo Negro.<\/strong> En el caso de La Pampa se esperan temperaturas de entre 37\u00b0 y 38\u00b0C.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Qu\u00e9 implica cada nivel de alerta por temperaturas extremas<\/h3>\n\n\n\n<p><strong>Alerta amarilla:<\/strong><\/p>\n\n\n\n<p>El alerta de&nbsp;<strong>nivel amarillo establece un efecto leve a moderado en la salud, de acuerdo al sistema del SMN.<\/strong><\/p>\n\n\n\n<p>Implica, en este caso, que&nbsp;<strong>las temperaturas pueden ser peligrosas<\/strong>,&nbsp;sobre todo para los grupos de riesgo, como ni\u00f1os y ni\u00f1as, personas mayores de 65 a\u00f1os, con enfermedades cr\u00f3nicas.<\/p>\n\n\n\n<p><strong>Alerta naranja:<\/strong><\/p>\n\n\n\n<p>Este aviso implica&nbsp;<strong>un efecto moderado a alto en la salud<\/strong>, por lo que&nbsp;<strong>las temperaturas pueden ser muy peligrosas<\/strong>,&nbsp;especialmente para los grupos de riesgo.<\/p>\n\n\n\n<p><strong>Alerta roja:<\/strong><\/p>\n\n\n\n<p>La advertencia de&nbsp;<strong>nivel rojo significa que el calor puede tener un efecto alto a extremo en la salud.<\/strong><strong>&nbsp;<\/strong>En este caso,&nbsp;<strong>las temperaturas son muy peligrosas,<\/strong><strong>&nbsp;<\/strong>y pueden afectar a todas las personas, incluso a las saludables.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Recomendaciones del SMN ante temperaturas extremas<\/h3>\n\n\n\n<p>Las recomendaciones para este tipo de eventos son indicadas por el Ministerio de Salud.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aumentar el consumo de agua sin esperar a tener sed para mantener una hidrataci\u00f3n adecuada.<\/li>\n\n\n\n<li>No exponerse al sol en exceso, ni en horas centrales del d\u00eda (entre las 10 y las 16 horas).<\/li>\n\n\n\n<li>Prestar atenci\u00f3n a los beb\u00e9s, ni\u00f1os y ni\u00f1as y a las personas mayores.<\/li>\n\n\n\n<li>Evitar las bebidas con cafe\u00edna, con alcohol o muy azucaradas.<\/li>\n\n\n\n<li>Evitar comidas muy abundantes.<\/li>\n\n\n\n<li>Ingerir verduras y frutas.<\/li>\n\n\n\n<li>Reducir la actividad f\u00edsica.<\/li>\n\n\n\n<li>Usar ropa ligera, holgada y de colores claros; sombrero, anteojos oscuros.<\/li>\n\n\n\n<li>Permanecer en espacios ventilados o acondicionados.<\/li>\n\n\n\n<li>Recordar que no existe un tratamiento farmacol\u00f3gico contra el golpe de calor y s\u00f3lo los m\u00e9todos cl\u00e1sicos, citados arriba, pueden prevenirlo y contrarrestarlo.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qu\u00e9 es un evento de temperaturas extremas<\/strong><\/h3>\n\n\n\n<p>Un evento de temperaturas extremas es un per\u00edodo en el que se espera que se registren&nbsp;<strong>valores de temperatura m\u00e1xima y m\u00ednima que pueden poner en peligro la salud de las personas.<\/strong>&nbsp;Luego de realizar una serie de estudios interdisciplinarios en Argentina, se encontr\u00f3 que hab\u00eda ciertos valores umbrales de temperaturas a partir de los cuales aumentaba la morbilidad y la mortalidad de las personas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sigue el calor agobiante en algunas zonas durante el inicio del 2025,&nbsp;y por eso el&nbsp;Servicio Meteorol\u00f3gico Nacional (SMN)&nbsp;manten\u00eda para este&nbsp;viernes&nbsp;nuevos&nbsp;alertas&nbsp;por&nbsp;altas temperaturas&nbsp;para diferentes distritos. De esta manera, se mantiene el\u00a0alerta amarillo&hellip;<\/p>\n","protected":false},"author":3,"featured_media":176014,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-287655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Sigue el calor agobiante en algunas zonas durante el inicio del 2025,&nbsp;y por eso el&nbsp;Servicio Meteorol\u00f3gico Nacional (SMN)&nbsp;manten\u00eda para este&nbsp;viernes&nbsp;nuevos&nbsp;alertas&nbsp;por&nbsp;altas temperaturas&nbsp;para diferentes distritos. De esta manera, se mantiene el\u00a0alerta amarillo&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-31T10:57:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-31T14:18:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/01\/calortelam2022-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"914\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C\",\"datePublished\":\"2025-01-31T10:57:31+00:00\",\"dateModified\":\"2025-01-31T14:18:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/\"},\"wordCount\":474,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/calortelam2022-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/\",\"name\":\"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/calortelam2022-1.jpg\",\"datePublished\":\"2025-01-31T10:57:31+00:00\",\"dateModified\":\"2025-01-31T14:18:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/calortelam2022-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/calortelam2022-1.jpg\",\"width\":914,\"height\":590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/01\\\/31\\\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/","og_locale":"es_ES","og_type":"article","og_title":"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C - Diario Textual","og_description":"Sigue el calor agobiante en algunas zonas durante el inicio del 2025,&nbsp;y por eso el&nbsp;Servicio Meteorol\u00f3gico Nacional (SMN)&nbsp;manten\u00eda para este&nbsp;viernes&nbsp;nuevos&nbsp;alertas&nbsp;por&nbsp;altas temperaturas&nbsp;para diferentes distritos. De esta manera, se mantiene el\u00a0alerta amarillo&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-01-31T10:57:31+00:00","article_modified_time":"2025-01-31T14:18:55+00:00","og_image":[{"width":914,"height":590,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/01\/calortelam2022-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C","datePublished":"2025-01-31T10:57:31+00:00","dateModified":"2025-01-31T14:18:55+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/"},"wordCount":474,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/01\/calortelam2022-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/","name":"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/01\/calortelam2022-1.jpg","datePublished":"2025-01-31T10:57:31+00:00","dateModified":"2025-01-31T14:18:55+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/01\/calortelam2022-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/01\/calortelam2022-1.jpg","width":914,"height":590},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/01\/31\/alerta-por-altas-temperaturas-en-la-pampa-se-esperan-38c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Alerta por altas temperaturas: en La Pampa se esperan 38\u00b0C"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=287655"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287655\/revisions"}],"predecessor-version":[{"id":287656,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/287655\/revisions\/287656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/176014"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=287655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=287655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=287655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}