{"id":294223,"date":"2025-04-16T20:21:00","date_gmt":"2025-04-16T23:21:00","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=294223"},"modified":"2025-04-16T20:29:17","modified_gmt":"2025-04-16T23:29:17","slug":"ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/","title":{"rendered":"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobernador de La Pampa,<strong> Sergio Ziliotto<\/strong>, volvi\u00f3 a c<strong>uestionar este mi\u00e9rcoles la vigencia de la barrera sanitaria que impide el ingreso de carne con hueso al sur del r\u00edo Colorado<\/strong> y sostuvo que <strong>la medida no tiene fundamentos sanitarios. <\/strong>En ese sentido, pidi\u00f3 la intervenci\u00f3n del Gobierno nacional para convocar a todas las provincias involucradas y abrir un espacio de di\u00e1logo que permita alcanzar un acuerdo. \u201cNo se trata de que haya un ganador y un perdedor. La salida est\u00e1 en encontrar un consenso\u201d, afirm\u00f3 Ziliotto, al tiempo que subray\u00f3 la necesidad de revisar la normativa vigente desde una mirada federal e integradora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"PdBrl0R0HX\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/frigorificos-pampeanos-en-crisis-una-situacion-muy-preocupante-dijo-la-ministra-de-la-produccion\/\">Frigor\u00edficos pampeanos en crisis: \u201cUna situaci\u00f3n muy preocupante\u201d, dijo la ministra de la Producci\u00f3n<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abFrigor\u00edficos pampeanos en crisis: \u201cUna situaci\u00f3n muy preocupante\u201d, dijo la ministra de la Producci\u00f3n\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/frigorificos-pampeanos-en-crisis-una-situacion-muy-preocupante-dijo-la-ministra-de-la-produccion\/embed\/#?secret=vGxxdsqfjs#?secret=PdBrl0R0HX\" data-secret=\"PdBrl0R0HX\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Desde hace 24 a\u00f1os, no se permite el ingreso de carne bovina con hueso al sur del r\u00edo Colorado. En su momento, esa barrera se hab\u00eda establecido con el fin de que no se transmitiera el virus de la fiebre aftosa a R\u00edo Negro y el resto de las provincias del sur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace casi un mes, el Servicio Nacional de Sanidad y Calidad Agroalimentaria (Senasa) admiti\u00f3 que era \u00ednfima la posibilidad de contagio de la aftosa a partir de la comercializaci\u00f3n de carne con hueso y levant\u00f3 la barrera. Unas horas despu\u00e9s, por presi\u00f3n del resto de los gobernadores, puso en stand by la medida por 90 d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, convoc\u00f3 a una mesa de trabajo para analizar una soluci\u00f3n. Este lunes 14 tuvieron la primera reuni\u00f3n, a la que no fue invitada La Pampa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo pronto, La Pampa est\u00e1 reclamando una reuni\u00f3n de todas las provincias. \u201cNosotros pedimos que se re\u00fana el Consejo Federal Agropecuario, no es un tema solo de la Patagonia\u201d, dijo Ziliotto. \u201cAl Gobierno nacional le cuesta definir pol\u00edticas federales. Hoy la Argentina est\u00e1 dividida por estatus sanitarios en dos regiones: al norte o al sur del r\u00edo Colorado. Lo que nosotros tenemos que definir es la cuesti\u00f3n sanitaria. Tenemos que defender el estatus sanitario de toda la Argentina, porque si nos suspenden, nos suspenden como pa\u00eds\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYa no est\u00e1 bajo ning\u00fan punto de vista de discusi\u00f3n que no es un tema sanitario, est\u00e1 zanjado. Lo dijo la propia Secretar\u00eda de Agricultura y Ganader\u00eda del gobierno nacional en el comunicado de ayer\u201d, sostuvo, en referencia a que no hay riesgo de contagio de aftosa con carne bovina con hueso. \u201cSeguramente hay cuestiones comerciales; mucho tiene que ver eso con la posibilidad de si ingresa o no ingresa carne con hueso plano o redondo, pero tambi\u00e9n tiene que ver si impacta eso en el precio de la carne. Pero tambi\u00e9n hay otra cuesti\u00f3n que te lo dicen permanentemente otros gobernadores y es entendible, ya que<strong> el costo de producci\u00f3n que tienen los productores al sur del r\u00edo Colorado no es el costo de producci\u00f3n que tienen los productores del resto del pa\u00eds. Ah\u00ed donde tiene que articular el Gobierno nacional y hacerse cargo que gobierna para toda la Argentina. Fijar reglas de incentivos fiscales, prerrogativas y beneficios de otro tipo para que ese productor tenga un costo de producci\u00f3n menor<\/strong>\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntonces as\u00ed se podr\u00e1 llegar a la g\u00f3ndola a un precio menor. No se puede analizar blanco o negro. Hay que analizarlo un contexto nacional, por eso nosotros pedimos que no solo est\u00e9 La Pampa, sino todo el resto de las provincias, y hay frigor\u00edfico en todas las provincias, en C\u00f3rdoba, en San Luis, en Entre R\u00edos, en Santa Fe, que tambi\u00e9n quisieran ingresar con carne con hueso a la Patagonia despu\u00e9s del r\u00edo Colorado. La salida est\u00e1 en qu\u00e9 no haya un ganador y un perdedor, somos todos argentinos, y en eso tiene que ver claramente la mano del gobierno nacional de hacer sustentable la producci\u00f3n. No habla de producci\u00f3n y trabajo\u201d, finaliz\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"OormlMeel5\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/15\/barrera-sanitaria-llaman-a-la-mesa-agropecuaria-de-la-pampa-para-establecer-la-hoja-de-ruta-del-reclamo\/\">Barrera sanitaria: llaman a la Mesa Agropecuaria de La Pampa para establecer la hoja de ruta del reclamo<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abBarrera sanitaria: llaman a la Mesa Agropecuaria de La Pampa para establecer la hoja de ruta del reclamo\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/15\/barrera-sanitaria-llaman-a-la-mesa-agropecuaria-de-la-pampa-para-establecer-la-hoja-de-ruta-del-reclamo\/embed\/#?secret=079lLDUbb5#?secret=OormlMeel5\" data-secret=\"OormlMeel5\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de La Pampa, Sergio Ziliotto, volvi\u00f3 a cuestionar este mi\u00e9rcoles la vigencia de la barrera sanitaria que impide el ingreso de carne con hueso al sur del r\u00edo&hellip;<\/p>\n","protected":false},"author":3,"featured_media":39911,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,11,20],"tags":[],"class_list":["post-294223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-que-pasa","category-campo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El gobernador de La Pampa, Sergio Ziliotto, volvi\u00f3 a cuestionar este mi\u00e9rcoles la vigencia de la barrera sanitaria que impide el ingreso de carne con hueso al sur del r\u00edo&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-16T23:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-16T23:29:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/02\/ziliottosergiofrigorificosantaisabel2019-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d\",\"datePublished\":\"2025-04-16T23:21:00+00:00\",\"dateModified\":\"2025-04-16T23:29:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/\"},\"wordCount\":682,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/ziliottosergiofrigorificosantaisabel2019-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"A - QUE PASA (al costado)\",\"CAMPO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/\",\"name\":\"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/ziliottosergiofrigorificosantaisabel2019-1.jpg\",\"datePublished\":\"2025-04-16T23:21:00+00:00\",\"dateModified\":\"2025-04-16T23:29:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/ziliottosergiofrigorificosantaisabel2019-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/ziliottosergiofrigorificosantaisabel2019-1.jpg\",\"width\":1280,\"height\":864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/16\\\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/","og_locale":"es_ES","og_type":"article","og_title":"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d - Diario Textual","og_description":"El gobernador de La Pampa, Sergio Ziliotto, volvi\u00f3 a cuestionar este mi\u00e9rcoles la vigencia de la barrera sanitaria que impide el ingreso de carne con hueso al sur del r\u00edo&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-04-16T23:21:00+00:00","article_modified_time":"2025-04-16T23:29:17+00:00","og_image":[{"width":1280,"height":864,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/02\/ziliottosergiofrigorificosantaisabel2019-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d","datePublished":"2025-04-16T23:21:00+00:00","dateModified":"2025-04-16T23:29:17+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/"},"wordCount":682,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/02\/ziliottosergiofrigorificosantaisabel2019-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","A - QUE PASA (al costado)","CAMPO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/","name":"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/02\/ziliottosergiofrigorificosantaisabel2019-1.jpg","datePublished":"2025-04-16T23:21:00+00:00","dateModified":"2025-04-16T23:29:17+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/02\/ziliottosergiofrigorificosantaisabel2019-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/02\/ziliottosergiofrigorificosantaisabel2019-1.jpg","width":1280,"height":864},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/16\/ziliotto-y-la-barrera-sanitaria-la-salida-esta-en-que-no-haya-un-ganador-y-un-perdedor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Ziliotto y la barrera sanitaria: \u201cLa salida est\u00e1 en que no haya un ganador y un perdedor\u201d"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/294223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=294223"}],"version-history":[{"count":4,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/294223\/revisions"}],"predecessor-version":[{"id":294227,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/294223\/revisions\/294227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/39911"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=294223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=294223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=294223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}