{"id":294323,"date":"2025-04-19T08:05:44","date_gmt":"2025-04-19T11:05:44","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=294323"},"modified":"2025-04-19T22:32:55","modified_gmt":"2025-04-20T01:32:55","slug":"hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/","title":{"rendered":"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1"},"content":{"rendered":"\n<p>En la madrugada de este s\u00e1bado, se confirm\u00f3 el hallazgo del cuerpo de Pablo Ovando, el gu\u00eda de pesca de 44 a\u00f1os que estaba desaparecido desde el martes junto a su hijo Agust\u00edn, de apenas cuatro a\u00f1os, en aguas del r\u00edo Paran\u00e1. La noticia fue comunicada por el fiscal Norberto R\u00edos a las 3:30 de la ma\u00f1ana.<\/p>\n\n\n\n<p>El cuerpo de Pablo fue encontrado en una zona cercana a donde el viernes por la tarde se hab\u00eda localizado a Agust\u00edn, ambos a varios kil\u00f3metros r\u00edo abajo del lugar donde apareci\u00f3 el yate familiar, que estaba anclado y con la llave puesta.<\/p>\n\n\n\n<p>Tras la aparici\u00f3n del ni\u00f1o, el operativo de b\u00fasqueda se concentr\u00f3 en ese sector del r\u00edo con la esperanza de dar tambi\u00e9n con el padre. Finalmente, los esfuerzos de rescatistas, gu\u00edas de pesca, familiares, amigos y fuerzas de seguridad dieron resultado, aunque con el desenlace m\u00e1s triste.<\/p>\n\n\n\n<p>Con ambos cuerpos localizados, se dio por concluido el rastrillaje. El fiscal R\u00edos indic\u00f3 que se realizar\u00e1n estudios m\u00e9dicos a los cuerpos para documentar cualquier dato relevante para la investigaci\u00f3n, aunque no se realizar\u00e1 autopsia, ya que no hay indicios de que se trate de un hecho delictivo.<\/p>\n\n\n\n<p>Pablo Ovando era una figura muy reconocida y querida en el \u00e1mbito del turismo de pesca en la regi\u00f3n. Fundador de Piray\u00fa Excursiones, dedic\u00f3 su vida a promover el sitio Jaaukanig\u00e1s como destino tur\u00edstico. Tambi\u00e9n era piloto de motos de agua y organizador de competencias deportivas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la madrugada de este s\u00e1bado, se confirm\u00f3 el hallazgo del cuerpo de Pablo Ovando, el gu\u00eda de pesca de 44 a\u00f1os que estaba desaparecido desde el martes junto a&hellip;<\/p>\n","protected":false},"author":2,"featured_media":294318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-294323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1 - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1 - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"En la madrugada de este s\u00e1bado, se confirm\u00f3 el hallazgo del cuerpo de Pablo Ovando, el gu\u00eda de pesca de 44 a\u00f1os que estaba desaparecido desde el martes junto a&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-19T11:05:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-20T01:32:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/04\/ovandoagustinpescadordesaparecido2025-7.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Sergio Romano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Romano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/\"},\"author\":{\"name\":\"Sergio Romano\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/523499e72392084bbaa07d9918058135\"},\"headline\":\"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1\",\"datePublished\":\"2025-04-19T11:05:44+00:00\",\"dateModified\":\"2025-04-20T01:32:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/\"},\"wordCount\":282,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/ovandoagustinpescadordesaparecido2025-7.webp\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/\",\"name\":\"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1 - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/ovandoagustinpescadordesaparecido2025-7.webp\",\"datePublished\":\"2025-04-19T11:05:44+00:00\",\"dateModified\":\"2025-04-20T01:32:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/ovandoagustinpescadordesaparecido2025-7.webp\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/ovandoagustinpescadordesaparecido2025-7.webp\",\"width\":1300,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/04\\\/19\\\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/523499e72392084bbaa07d9918058135\",\"name\":\"Sergio Romano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g\",\"caption\":\"Sergio Romano\"},\"sameAs\":[\"http:\\\/\\\/www.diariotextual.com\"],\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1 - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/","og_locale":"es_ES","og_type":"article","og_title":"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1 - Diario Textual","og_description":"En la madrugada de este s\u00e1bado, se confirm\u00f3 el hallazgo del cuerpo de Pablo Ovando, el gu\u00eda de pesca de 44 a\u00f1os que estaba desaparecido desde el martes junto a&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-04-19T11:05:44+00:00","article_modified_time":"2025-04-20T01:32:55+00:00","og_image":[{"width":1300,"height":655,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/04\/ovandoagustinpescadordesaparecido2025-7.webp","type":"image\/webp"}],"author":"Sergio Romano","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Sergio Romano","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/"},"author":{"name":"Sergio Romano","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/523499e72392084bbaa07d9918058135"},"headline":"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1","datePublished":"2025-04-19T11:05:44+00:00","dateModified":"2025-04-20T01:32:55+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/"},"wordCount":282,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/04\/ovandoagustinpescadordesaparecido2025-7.webp","articleSection":["A - ES NOTICIA (van abajo)","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/","name":"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1 - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/04\/ovandoagustinpescadordesaparecido2025-7.webp","datePublished":"2025-04-19T11:05:44+00:00","dateModified":"2025-04-20T01:32:55+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/04\/ovandoagustinpescadordesaparecido2025-7.webp","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/04\/ovandoagustinpescadordesaparecido2025-7.webp","width":1300,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/04\/19\/hallaron-los-cuerpos-del-pescador-y-de-su-hijo-que-habian-desaparecido-en-el-parana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Hallaron los cuerpos del pescador y de su hijo que hab\u00edan desaparecido en el Paran\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/523499e72392084bbaa07d9918058135","name":"Sergio Romano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g","caption":"Sergio Romano"},"sameAs":["http:\/\/www.diariotextual.com"],"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/294323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=294323"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/294323\/revisions"}],"predecessor-version":[{"id":294326,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/294323\/revisions\/294326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/294318"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=294323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=294323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=294323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}