{"id":300759,"date":"2025-07-07T18:53:00","date_gmt":"2025-07-07T21:53:00","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=300759"},"modified":"2025-07-07T19:51:12","modified_gmt":"2025-07-07T22:51:12","slug":"el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/","title":{"rendered":"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d"},"content":{"rendered":"\n<p>El flamante presidente de La Libertad Avanza en La Pampa, <strong>Adri\u00e1n Ravier<\/strong>, cruz\u00f3 duramente a la UCR y el Pro, en medio de las negociaciones para intentar sumarlos a un frente electoral de cara a las legislativas nacionales de octubre.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"YkQC1dFALa\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/atropellados-meados-y-tiempistas-la-oposicion-pampeana-negocia-pero-va-dividida\/\">Atropellados, \u201cmeados\u201d y tiempistas: la oposici\u00f3n pampeana negocia, pero va dividida<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abAtropellados, \u201cmeados\u201d y tiempistas: la oposici\u00f3n pampeana negocia, pero va dividida\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/atropellados-meados-y-tiempistas-la-oposicion-pampeana-negocia-pero-va-dividida\/embed\/#?secret=lJAYCPABm6#?secret=YkQC1dFALa\" data-secret=\"YkQC1dFALa\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Ravier, en un posteo en X, critic\u00f3 la supuesta falta de definiciones ideol\u00f3gicas de los principales partidos pol\u00edticos tradicionales y sostuvo que solo su espacio y algunos sectores de la izquierda mantienen una identidad clara. <strong>\u201cCon excepci\u00f3n de La Libertad Avanza y algunos partidos de izquierda, parece que el resto ya no saben qu\u00e9 ideas representan. No tienen identidad\u201d<\/strong>, expres\u00f3 Ravier en un mensaje difundido a trav\u00e9s de sus redes sociales.<\/p>\n\n\n\n<p>El economista y dirigente libertario puso como ejemplo las contradicciones internas de fuerzas como la Uni\u00f3n C\u00edvica Radical, el Partido Justicialista, el Movimiento de Integraci\u00f3n y Desarrollo, y el Pro.<strong> \u201cLa UCR, \u00bfes la de Alem o la de Ra\u00fal Alfons\u00edn? El PJ, \u00bfes el menemismo o el kirchnerismo? El MID de Frondizi, \u00bfes el de Alsogaray o el de Frigerio? El PRO, \u00bfes el de Macri o el de Larreta?\u201d<\/strong>, se pregunt\u00f3 Ravier.<\/p>\n\n\n\n<p>Si bien sus expresiones parecen hacer foco en la situaci\u00f3n general de los partidos a nivel nacional, indefectiblemente hay una lectura local: Ravier es quien est\u00e1 encabezando en la provincia las negociaciones con la UCR y el Pro para, eventualmente, hacer un frente electoral.<\/p>\n\n\n\n<p>Poco despu\u00e9s, <strong>Federico Guidugli<\/strong>, presidente del Comit\u00e9 Provincia de la UCR, sali\u00f3 con dureza a cuestionar al presidente de La Libertad Avanza.\u00a0\u201cCuando arranc\u00e1s en pol\u00edtica y no sabes que hacer para que te levanten haces esto, romper puentes con todos y agraviar a nuestros pr\u00f3ceres partidarios. La UCR representa a millones de argentinos hace m\u00e1s de 130 a\u00f1os. Equidad, producci\u00f3n, trabajo y libertad mucho antes que ustedes\u201d, sostuvo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"xxgdvCebiG\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/la-presidente-de-la-ucr-caliente-con-ravier-confirma-que-no-hay-frente-con-lla-rompe-puentes-con-todos\/\">La presidente de la UCR, caliente con Ravier, confirma que no hay frente con LLA: \u201cRompe puentes con todos\u201d<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abLa presidente de la UCR, caliente con Ravier, confirma que no hay frente con LLA: \u201cRompe puentes con todos\u201d\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/la-presidente-de-la-ucr-caliente-con-ravier-confirma-que-no-hay-frente-con-lla-rompe-puentes-con-todos\/embed\/#?secret=z3UmfV9vv6#?secret=xxgdvCebiG\" data-secret=\"xxgdvCebiG\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>En rigor, m\u00e1s que negociar, <strong>hasta el momento Ravier est\u00e1 imponiendo<\/strong>: como <strong><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/04\/ravier-mostro-los-dientes\/\" target=\"_blank\" rel=\"noreferrer noopener\">public\u00f3 la semana Diario Textual, exigi\u00f3 que el sello sea de LLA; una boleta de color violeta; y que un libertario -es decir, \u00e9l mismo- encabece la lista<\/a><\/strong>.<\/p>\n\n\n\n<p>En esas condiciones, la UCR ya le baj\u00f3 el pulgar. De todas maneras, a\u00fan hay sectores del radicalismo que mantienen contactos para, eventualmente, tratar de acercar posiciones. Lo mismo pasa con el Pro.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-diario-textual wp-block-embed-diario-textual\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"pYf4wOSZDt\"><a href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/04\/ravier-mostro-los-dientes\/\">Ravier mostr\u00f3 los dientes y present\u00f3 a la UCR y el Pro sus condiciones: sello de LLA, color violeta y encabezar la lista<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abRavier mostr\u00f3 los dientes y present\u00f3 a la UCR y el Pro sus condiciones: sello de LLA, color violeta y encabezar la lista\u00bb \u2014 Diario Textual\" src=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/04\/ravier-mostro-los-dientes\/embed\/#?secret=Ej6BNRDL3H#?secret=pYf4wOSZDt\" data-secret=\"pYf4wOSZDt\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El flamante presidente de La Libertad Avanza en La Pampa, Adri\u00e1n Ravier, cruz\u00f3 duramente a la UCR y el Pro, en medio de las negociaciones para intentar sumarlos a un&hellip;<\/p>\n","protected":false},"author":3,"featured_media":284656,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,8],"tags":[],"class_list":["post-300759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El flamante presidente de La Libertad Avanza en La Pampa, Adri\u00e1n Ravier, cruz\u00f3 duramente a la UCR y el Pro, en medio de las negociaciones para intentar sumarlos a un&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-07T21:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T22:51:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/12\/libertarioslalibertadavanzallaleones2024-777777.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"883\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d\",\"datePublished\":\"2025-07-07T21:53:00+00:00\",\"dateModified\":\"2025-07-07T22:51:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/\"},\"wordCount\":432,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/libertarioslalibertadavanzallaleones2024-777777.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/\",\"name\":\"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/libertarioslalibertadavanzallaleones2024-777777.jpg\",\"datePublished\":\"2025-07-07T21:53:00+00:00\",\"dateModified\":\"2025-07-07T22:51:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/libertarioslalibertadavanzallaleones2024-777777.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/libertarioslalibertadavanzallaleones2024-777777.jpg\",\"width\":883,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/07\\\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/","og_locale":"es_ES","og_type":"article","og_title":"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d - Diario Textual","og_description":"El flamante presidente de La Libertad Avanza en La Pampa, Adri\u00e1n Ravier, cruz\u00f3 duramente a la UCR y el Pro, en medio de las negociaciones para intentar sumarlos a un&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-07-07T21:53:00+00:00","article_modified_time":"2025-07-07T22:51:12+00:00","og_image":[{"width":883,"height":592,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/12\/libertarioslalibertadavanzallaleones2024-777777.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d","datePublished":"2025-07-07T21:53:00+00:00","dateModified":"2025-07-07T22:51:12+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/"},"wordCount":432,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/12\/libertarioslalibertadavanzallaleones2024-777777.jpg","articleSection":["A - ES NOTICIA (van abajo)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/","name":"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/12\/libertarioslalibertadavanzallaleones2024-777777.jpg","datePublished":"2025-07-07T21:53:00+00:00","dateModified":"2025-07-07T22:51:12+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/12\/libertarioslalibertadavanzallaleones2024-777777.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2024\/12\/libertarioslalibertadavanzallaleones2024-777777.jpg","width":883,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/07\/el-presidente-de-lla-la-pampa-y-una-definicion-sobre-la-ucr-y-el-pro-parece-que-no-tienen-identidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"El presidente de LLA La Pampa y una definici\u00f3n sobre la UCR y el Pro: \u201cParece que no tienen identidad\u201d"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/300759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=300759"}],"version-history":[{"count":3,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/300759\/revisions"}],"predecessor-version":[{"id":300920,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/300759\/revisions\/300920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/284656"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=300759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=300759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=300759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}