{"id":301154,"date":"2025-07-10T10:04:07","date_gmt":"2025-07-10T13:04:07","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=301154"},"modified":"2025-07-10T10:06:13","modified_gmt":"2025-07-10T13:06:13","slug":"chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/","title":{"rendered":"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor"},"content":{"rendered":"\n<p>Una tragedia enluta por estas horas a la Federaci\u00f3n Agraria Argentina (FAA) en Chaco luego de que este mi\u00e9rcoles la esposa del dirigente Javier Druzianich, a cargo de una filial local, falleciera aplastada por un tractor con arado. La v\u00edctima fue identificada como Vanina V\u00e1zquez y ten\u00eda 42 a\u00f1os. El episodio ocurri\u00f3 frente al marido y uno de los hijos de la mujer.<\/p>\n\n\n\n<p>Seg\u00fan inform\u00f3 el diario local Norte, de acuerdo a informaci\u00f3n suministrada por la comisar\u00eda quinta de la polic\u00eda local, el accidente tuvo lugar este feriado 9 de Julio cerca de las 14.30, en un campo ubicado en Bajo Hondo, a unos 15 kil\u00f3metros de la ciudad chaque\u00f1a de S\u00e1enz Pe\u00f1a.<\/p>\n\n\n\n<p><strong>La mujer iba de acompa\u00f1ante en un tractor de la familia que era conducido por su esposo de 44 a\u00f1os, sentada en uno de los laterales del veh\u00edculo<\/strong>, mientras realizaban tareas de\u00a0<strong>arado\u00a0<\/strong>en las cercan\u00edas del cruce conocido como \u201cGauchito Gil\u201d y tomaban mates.<\/p>\n\n\n\n<p>De acuerdo a los primeros relatos de los testigos, la tragedia se dio en el marco de una maniobra para intentar&nbsp;<strong>evitar pisar un pozo&nbsp;<\/strong>que hab\u00eda en el terreno. La v\u00edctima se desestabiliz\u00f3, perdi\u00f3 el equilibrio y&nbsp;<strong>cay\u00f3 por la rastra de discos de arados, que la pasaron por encima<\/strong>. La mujer falleci\u00f3 en el acto.<\/p>\n\n\n\n<p>Uno de los hijos del matrimonio, de 21 a\u00f1os e identificado como Javier, fue testigo del hecho y relat\u00f3 lo presenciado a las autoridades. En el lugar intervino la Polic\u00eda local, personal de la fiscal\u00eda de turno y la Divisi\u00f3n Bomberos.<\/p>\n\n\n\n<p>V\u00e1zquez y Druzianich resid\u00edan en la zona c\u00e9ntrica de la ciudad de S\u00e1enz Pe\u00f1a y eran conocidos en el \u00e1mbito agropecuario. D\u00edas atr\u00e1s, el productor se hab\u00eda manifestado en medios locales preocupado por la eliminaci\u00f3n del Fondo Algodonero. El hombre hab\u00eda advertido que la falta de asistencia podr\u00eda reducir la producci\u00f3n y afectar la calidad de vida de muchas familias rurales.<\/p>\n\n\n\n<p>\u201cEl Chaco se hizo productivo con el algod\u00f3n. Hoy, la miseria que tienen nuestros pueblos es justamente por la falta de pol\u00edticas algodoneras\u201d, se quej\u00f3. \u201cSe sojiz\u00f3 la provincia y estamos en un problema grave. Hacemos mucho cereal, pero no tienen buena rentabilidad. El algod\u00f3n sigue siendo una herramienta necesaria, pero necesita valor agregado y pol\u00edticas claras de comercializaci\u00f3n, no un gobierno que venga a eliminar leyes que son parte de nuestra historia. Eliminar la Ley Algodonera es ir en contra de todo eso\u201d, hab\u00eda marcado.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una tragedia enluta por estas horas a la Federaci\u00f3n Agraria Argentina (FAA) en Chaco luego de que este mi\u00e9rcoles la esposa del dirigente Javier Druzianich, a cargo de una filial&hellip;<\/p>\n","protected":false},"author":3,"featured_media":301158,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,20],"tags":[],"class_list":["post-301154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-campo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Una tragedia enluta por estas horas a la Federaci\u00f3n Agraria Argentina (FAA) en Chaco luego de que este mi\u00e9rcoles la esposa del dirigente Javier Druzianich, a cargo de una filial&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T13:04:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-10T13:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/07\/tragediaenchacomujeraplastadatractor2025-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"861\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor\",\"datePublished\":\"2025-07-10T13:04:07+00:00\",\"dateModified\":\"2025-07-10T13:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/\"},\"wordCount\":460,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/tragediaenchacomujeraplastadatractor2025-1.jpg\",\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"CAMPO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/\",\"name\":\"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/tragediaenchacomujeraplastadatractor2025-1.jpg\",\"datePublished\":\"2025-07-10T13:04:07+00:00\",\"dateModified\":\"2025-07-10T13:06:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/tragediaenchacomujeraplastadatractor2025-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/tragediaenchacomujeraplastadatractor2025-1.jpg\",\"width\":861,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2025\\\/07\\\/10\\\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/","og_locale":"es_ES","og_type":"article","og_title":"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor - Diario Textual","og_description":"Una tragedia enluta por estas horas a la Federaci\u00f3n Agraria Argentina (FAA) en Chaco luego de que este mi\u00e9rcoles la esposa del dirigente Javier Druzianich, a cargo de una filial&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2025-07-10T13:04:07+00:00","article_modified_time":"2025-07-10T13:06:13+00:00","og_image":[{"width":861,"height":549,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/07\/tragediaenchacomujeraplastadatractor2025-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor","datePublished":"2025-07-10T13:04:07+00:00","dateModified":"2025-07-10T13:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/"},"wordCount":460,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/07\/tragediaenchacomujeraplastadatractor2025-1.jpg","articleSection":["A - ES NOTICIA (van abajo)","CAMPO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/","name":"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/07\/tragediaenchacomujeraplastadatractor2025-1.jpg","datePublished":"2025-07-10T13:04:07+00:00","dateModified":"2025-07-10T13:06:13+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/07\/tragediaenchacomujeraplastadatractor2025-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2025\/07\/tragediaenchacomujeraplastadatractor2025-1.jpg","width":861,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2025\/07\/10\/chaco-la-esposa-de-un-referente-de-la-federacion-agraria-murio-al-ser-aplastada-por-un-tractor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Chaco: la esposa de un referente de la Federaci\u00f3n Agraria muri\u00f3 al ser aplastada por un tractor"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/301154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=301154"}],"version-history":[{"count":3,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/301154\/revisions"}],"predecessor-version":[{"id":301157,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/301154\/revisions\/301157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/301158"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=301154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=301154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=301154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}