{"id":31692,"date":"2018-12-20T11:52:02","date_gmt":"2018-12-20T14:52:02","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=31692"},"modified":"2018-12-20T13:26:13","modified_gmt":"2018-12-20T16:26:13","slug":"la-denunciante-marino-declara-camara-gesell","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/","title":{"rendered":"La denunciante de Marino declara en C\u00e1mara Gesell"},"content":{"rendered":"<p>Un d\u00eda despu\u00e9s de que el senador de la UCR, Juan Carlos Marino, rompiera el silencio, la Justicia le toma declaraci\u00f3n este jueves a la empleada legislativa Claudia Guebel, quien denunci\u00f3 al pampeano por acoso sexual. Lo hace en C\u00e1mara Gesell, un mecanismo utilizado para preservar a los menores de edad y a las v\u00edctimas de abusos.<\/p>\n<p>El juez federal Ariel Lijo orden\u00f3 medidas de prueba y pidi\u00f3 informes al Senado, en el marco de la causa en la que se investiga al senador radical por acoso sexual.<\/p>\n<p><strong>El magistrado, a cargo de la investigaci\u00f3n, orden\u00f3 las medidas de pruebas que hab\u00edan sido solicitadas por el fiscal Federico Delgado -que imput\u00f3 al legislador-, cit\u00f3 a nuevos testigos y pidi\u00f3 informes al Senado.<\/strong><\/p>\n<p>Adem\u00e1s de Marino, la trabajadora denunci\u00f3 a Pedro Fiorda, jefe de despacho del senador radical; y a Juan Carlos Amarilla, que se desempe\u00f1a como asesor en el despacho del diputado Alfredo Olmedo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00eda despu\u00e9s de que el senador de la UCR, Juan Carlos Marino, rompiera el silencio, la Justicia le toma declaraci\u00f3n este jueves a la empleada legislativa Claudia Guebel, quien&hellip;<\/p>\n","protected":false},"author":3,"featured_media":31694,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,319,8],"tags":[1078,140],"class_list":["post-31692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-a-temporales","category-politica","tag-guebel","tag-marino"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La denunciante de Marino declara en C\u00e1mara Gesell - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La denunciante de Marino declara en C\u00e1mara Gesell - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Un d\u00eda despu\u00e9s de que el senador de la UCR, Juan Carlos Marino, rompiera el silencio, la Justicia le toma declaraci\u00f3n este jueves a la empleada legislativa Claudia Guebel, quien&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-20T14:52:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-20T16:26:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/12\/guebelclaudia11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"593\" \/>\n\t<meta property=\"og:image:height\" content=\"389\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"La denunciante de Marino declara en C\u00e1mara Gesell\",\"datePublished\":\"2018-12-20T14:52:02+00:00\",\"dateModified\":\"2018-12-20T16:26:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/\"},\"wordCount\":172,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/guebelclaudia11.jpg\",\"keywords\":[\"Guebel\",\"marino\"],\"articleSection\":[\"A - QUE PASA (al costado)\",\"A - TEMPORALES\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/\",\"name\":\"La denunciante de Marino declara en C\u00e1mara Gesell - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/guebelclaudia11.jpg\",\"datePublished\":\"2018-12-20T14:52:02+00:00\",\"dateModified\":\"2018-12-20T16:26:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/guebelclaudia11.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/guebelclaudia11.jpg\",\"width\":593,\"height\":389},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/20\\\/la-denunciante-marino-declara-camara-gesell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La denunciante de Marino declara en C\u00e1mara Gesell\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La denunciante de Marino declara en C\u00e1mara Gesell - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/","og_locale":"es_ES","og_type":"article","og_title":"La denunciante de Marino declara en C\u00e1mara Gesell - Diario Textual","og_description":"Un d\u00eda despu\u00e9s de que el senador de la UCR, Juan Carlos Marino, rompiera el silencio, la Justicia le toma declaraci\u00f3n este jueves a la empleada legislativa Claudia Guebel, quien&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2018-12-20T14:52:02+00:00","article_modified_time":"2018-12-20T16:26:13+00:00","og_image":[{"width":593,"height":389,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/12\/guebelclaudia11.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"La denunciante de Marino declara en C\u00e1mara Gesell","datePublished":"2018-12-20T14:52:02+00:00","dateModified":"2018-12-20T16:26:13+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/"},"wordCount":172,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/12\/guebelclaudia11.jpg","keywords":["Guebel","marino"],"articleSection":["A - QUE PASA (al costado)","A - TEMPORALES","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/","name":"La denunciante de Marino declara en C\u00e1mara Gesell - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/12\/guebelclaudia11.jpg","datePublished":"2018-12-20T14:52:02+00:00","dateModified":"2018-12-20T16:26:13+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/12\/guebelclaudia11.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/12\/guebelclaudia11.jpg","width":593,"height":389},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/20\/la-denunciante-marino-declara-camara-gesell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La denunciante de Marino declara en C\u00e1mara Gesell"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/31692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=31692"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/31692\/revisions"}],"predecessor-version":[{"id":31695,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/31692\/revisions\/31695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/31694"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=31692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=31692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=31692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}