{"id":31967,"date":"2018-12-21T18:29:17","date_gmt":"2018-12-21T21:29:17","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=31967"},"modified":"2018-12-22T20:37:15","modified_gmt":"2018-12-22T23:37:15","slug":"aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/","title":{"rendered":"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023"},"content":{"rendered":"<p>En<strong> dos localidades del oeste pampeano ya se sabe qui\u00e9nes ser\u00e1n los jefes comunales desde 2019 a 2023<\/strong>. Es que, pese a que a\u00fan no se hicieron las elecciones, anoche se venci\u00f3 el plazo y solo se presentaron, en cada pueblo, <strong>una lista del Frente Pampeano Justicialista<\/strong> (la coalici\u00f3n comandada por el PJ, con el acompa\u00f1amiento del Frente Renovador, Nuevo Encuentro, PH, PC y Patria Grande).<\/p>\n<p>Esas localidades son <strong>Loventuel<\/strong>, donde<strong>\u00a0Hugo Mart\u00edne<\/strong>z va camino a los 16 a\u00f1os al frente de la comisi\u00f3n de fomento, y Luan Toro, con <strong>M\u00f3nica Valor<\/strong>\u00a0que ya se asegur\u00f3 la reelecci\u00f3n.<\/p>\n<p>En los dos casos, no tendr\u00e1n internas el 17 de febrero. Tampoco tendr\u00e1n que competir con otros partidos o frentes, como Cambiemos, el 19 de mayo. Solo Cambiemos present\u00f3, en ambos pueblos, una lista de concejales para Luan Toro y de vocales para Loventuel.<\/p>\n<p>\u00abTan malo no debo ser\u00bb, dijo Mart\u00ednez a Infohuella. En su pueblo hay, aproximadamente, 120 empadronados. Su lista se votar\u00e1 en las generales del 19 de mayo.\u00a0<strong>All\u00ed, con un solo voto, ser\u00e1 nuevamente intendente. Cabe destacar que el voto en blanco, por m\u00e1s que sea mayor\u00eda, no es considerado v\u00e1lido.<\/strong><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"I8lgAuq3fR\"><p><a href=\"http:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/la-foto-ziliotto-fernandez-la-lista-diputados\/\">La foto de Ziliotto y Fern\u00e1ndez con la lista de diputados<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"http:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/la-foto-ziliotto-fernandez-la-lista-diputados\/embed\/#?secret=I8lgAuq3fR\" data-secret=\"I8lgAuq3fR\" width=\"600\" height=\"338\" title=\"&#8220;La foto de Ziliotto y Fern\u00e1ndez con la lista de diputados&#8221; &#8212; Diario Textual\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En dos localidades del oeste pampeano ya se sabe qui\u00e9nes ser\u00e1n los jefes comunales desde 2019 a 2023. Es que, pese a que a\u00fan no se hicieron las elecciones, anoche&hellip;<\/p>\n","protected":false},"author":3,"featured_media":24470,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[319,8],"tags":[125],"class_list":["post-31967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-temporales","category-politica","tag-elecciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023 - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023 - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"En dos localidades del oeste pampeano ya se sabe qui\u00e9nes ser\u00e1n los jefes comunales desde 2019 a 2023. Es que, pese a que a\u00fan no se hicieron las elecciones, anoche&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-21T21:29:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-22T23:37:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/10\/eleccionestelam2015-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023\",\"datePublished\":\"2018-12-21T21:29:17+00:00\",\"dateModified\":\"2018-12-22T23:37:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/\"},\"wordCount\":222,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/eleccionestelam2015-1.jpg\",\"keywords\":[\"elecciones\"],\"articleSection\":[\"A - TEMPORALES\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/\",\"name\":\"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023 - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/eleccionestelam2015-1.jpg\",\"datePublished\":\"2018-12-21T21:29:17+00:00\",\"dateModified\":\"2018-12-22T23:37:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/eleccionestelam2015-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/eleccionestelam2015-1.jpg\",\"width\":510,\"height\":339},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/12\\\/21\\\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023 - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/","og_locale":"es_ES","og_type":"article","og_title":"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023 - Diario Textual","og_description":"En dos localidades del oeste pampeano ya se sabe qui\u00e9nes ser\u00e1n los jefes comunales desde 2019 a 2023. Es que, pese a que a\u00fan no se hicieron las elecciones, anoche&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2018-12-21T21:29:17+00:00","article_modified_time":"2018-12-22T23:37:15+00:00","og_image":[{"width":510,"height":339,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/10\/eleccionestelam2015-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023","datePublished":"2018-12-21T21:29:17+00:00","dateModified":"2018-12-22T23:37:15+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/"},"wordCount":222,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/10\/eleccionestelam2015-1.jpg","keywords":["elecciones"],"articleSection":["A - TEMPORALES","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/","name":"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023 - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/10\/eleccionestelam2015-1.jpg","datePublished":"2018-12-21T21:29:17+00:00","dateModified":"2018-12-22T23:37:15+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/10\/eleccionestelam2015-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/10\/eleccionestelam2015-1.jpg","width":510,"height":339},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/12\/21\/aun-sin-elecciones-pj-pampeano-ya-metio-dos-intendentes-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"A\u00fan sin elecciones, el PJ pampeano ya meti\u00f3 dos intendentes hasta 2023"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/31967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=31967"}],"version-history":[{"count":5,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/31967\/revisions"}],"predecessor-version":[{"id":31972,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/31967\/revisions\/31972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/24470"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=31967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=31967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=31967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}