{"id":323283,"date":"2026-03-26T10:39:03","date_gmt":"2026-03-26T13:39:03","guid":{"rendered":"https:\/\/diariotextual.com\/inicio\/?p=323283"},"modified":"2026-03-27T06:58:53","modified_gmt":"2026-03-27T09:58:53","slug":"viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/","title":{"rendered":"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez"},"content":{"rendered":"\n<p>El presidente del bloque de diputados nacionales del peronismo, Germ\u00e1n Mart\u00ednez, llegar\u00e1 este jueves a Santa Rosa invitado a participar del 95\u00ba plenario de Rectoras y Rectores del Consejo Interuniversitario Nacional (CIN).<\/p>\n\n\n\n<p>El dirigente tiene previsto brindar una conferencia de prensa a las 19.30 en la sede del PJ, en calle Irigoyen.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del bloque de diputados nacionales del peronismo, Germ\u00e1n Mart\u00ednez, llegar\u00e1 este jueves a Santa Rosa invitado a participar del 95\u00ba plenario de Rectoras y Rectores del Consejo Interuniversitario&hellip;<\/p>\n","protected":false},"author":7,"featured_media":178112,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-323283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El presidente del bloque de diputados nacionales del peronismo, Germ\u00e1n Mart\u00ednez, llegar\u00e1 este jueves a Santa Rosa invitado a participar del 95\u00ba plenario de Rectoras y Rectores del Consejo Interuniversitario&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T13:39:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T09:58:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/02\/martinezgermandiputado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"966\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/\"},\"author\":{\"name\":\"diario5\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\"},\"headline\":\"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez\",\"datePublished\":\"2026-03-26T13:39:03+00:00\",\"dateModified\":\"2026-03-27T09:58:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/\"},\"wordCount\":67,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/martinezgermandiputado.jpg\",\"articleSection\":[\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/\",\"name\":\"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/martinezgermandiputado.jpg\",\"datePublished\":\"2026-03-26T13:39:03+00:00\",\"dateModified\":\"2026-03-27T09:58:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/martinezgermandiputado.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/martinezgermandiputado.jpg\",\"width\":966,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2026\\\/03\\\/26\\\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/c7834961ad8b29b1d9cdbf4571299067\",\"name\":\"diario5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g\",\"caption\":\"diario5\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/","og_locale":"es_ES","og_type":"article","og_title":"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez - Diario Textual","og_description":"El presidente del bloque de diputados nacionales del peronismo, Germ\u00e1n Mart\u00ednez, llegar\u00e1 este jueves a Santa Rosa invitado a participar del 95\u00ba plenario de Rectoras y Rectores del Consejo Interuniversitario&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2026-03-26T13:39:03+00:00","article_modified_time":"2026-03-27T09:58:53+00:00","og_image":[{"width":966,"height":607,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/02\/martinezgermandiputado.jpg","type":"image\/jpeg"}],"author":"diario5","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario5","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/"},"author":{"name":"diario5","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067"},"headline":"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez","datePublished":"2026-03-26T13:39:03+00:00","dateModified":"2026-03-27T09:58:53+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/"},"wordCount":67,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/02\/martinezgermandiputado.jpg","articleSection":["POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/","name":"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/02\/martinezgermandiputado.jpg","datePublished":"2026-03-26T13:39:03+00:00","dateModified":"2026-03-27T09:58:53+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/02\/martinezgermandiputado.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2022\/02\/martinezgermandiputado.jpg","width":966,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2026\/03\/26\/viene-a-santa-rosa-el-jefe-de-bloque-de-diputados-peronistas-german-martinez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Viene a Santa Rosa el jefe de bloque de diputados peronistas Germ\u00e1n Mart\u00ednez"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/c7834961ad8b29b1d9cdbf4571299067","name":"diario5","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948c893b847ca6df68216ead81b63f363408ec9b0f600fefc0641ce78613b111?s=96&d=mm&r=g","caption":"diario5"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario5\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/323283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=323283"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/323283\/revisions"}],"predecessor-version":[{"id":323286,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/323283\/revisions\/323286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/178112"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=323283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=323283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=323283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}