{"id":34154,"date":"2019-01-13T09:50:15","date_gmt":"2019-01-13T12:50:15","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=34154"},"modified":"2019-01-14T07:39:29","modified_gmt":"2019-01-14T10:39:29","slug":"se-vence-plazo-verifica-estas-los-padrones-electorales","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/","title":{"rendered":"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales"},"content":{"rendered":"<p>Hasta este lunes 14 est\u00e1n exhibidos, en la<a href=\"http:\/\/electoral.juslapampa.gob.ar\/provisorio\/consulta.aspx\" target=\"_blank\" rel=\"noopener\"><strong>\u00a0p\u00e1gina web del Tribunal Electoral de la Provincia de La Pampa<\/strong><\/a>, los padrones provisorios, tanto para las elecciones internas abiertas, obligatorias y simult\u00e1neas del 17 de febrero; como para los comicios generales provinciales del 19 de mayo.<\/p>\n<p>Hasta este lunes los ciudadanos pueden efectuar sus reclamos si no figurasen en ellos o estuvieran inscriptos err\u00f3neamente. Para constatarlo deben ingresar al \u00edcono \u201cConsulta de padrones\u201d. All\u00ed pueden observar si est\u00e1n o no registrados y, eventualmente, realizar cualquier consulta.<\/p>\n<p>Cuatro d\u00edas m\u00e1s tarde del vencimiento de ese plazo, o sea el viernes 18, se publicar\u00e1n los padrones definitivos solo para las internas abiertas. A partir de ese momento tambi\u00e9n se conocer\u00e1n los lugares de votaci\u00f3n de cada uno de los electores.<\/p>\n<p>El Tribunal Electoral est\u00e1 ubicado en avenida San Mart\u00edn Oeste 152, Santa Rosa, y el horario de atenci\u00f3n es de 7 a 13. Sus tel\u00e9fonos son 02954-429567\/429341.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta este lunes 14 est\u00e1n exhibidos, en la\u00a0p\u00e1gina web del Tribunal Electoral de la Provincia de La Pampa, los padrones provisorios, tanto para las elecciones internas abiertas, obligatorias y simult\u00e1neas&hellip;<\/p>\n","protected":false},"author":3,"featured_media":16748,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[319,8],"tags":[1329],"class_list":["post-34154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-temporales","category-politica","tag-padrones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Hasta este lunes 14 est\u00e1n exhibidos, en la\u00a0p\u00e1gina web del Tribunal Electoral de la Provincia de La Pampa, los padrones provisorios, tanto para las elecciones internas abiertas, obligatorias y simult\u00e1neas&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-13T12:50:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-14T10:39:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/08\/eleccionestelam00121212.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"645\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales\",\"datePublished\":\"2019-01-13T12:50:15+00:00\",\"dateModified\":\"2019-01-14T10:39:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/eleccionestelam00121212.jpg\",\"keywords\":[\"padrones\"],\"articleSection\":[\"A - TEMPORALES\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/\",\"name\":\"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/eleccionestelam00121212.jpg\",\"datePublished\":\"2019-01-13T12:50:15+00:00\",\"dateModified\":\"2019-01-14T10:39:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/eleccionestelam00121212.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/eleccionestelam00121212.jpg\",\"width\":645,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/13\\\/se-vence-plazo-verifica-estas-los-padrones-electorales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/","og_locale":"es_ES","og_type":"article","og_title":"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales - Diario Textual","og_description":"Hasta este lunes 14 est\u00e1n exhibidos, en la\u00a0p\u00e1gina web del Tribunal Electoral de la Provincia de La Pampa, los padrones provisorios, tanto para las elecciones internas abiertas, obligatorias y simult\u00e1neas&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2019-01-13T12:50:15+00:00","article_modified_time":"2019-01-14T10:39:29+00:00","og_image":[{"width":645,"height":430,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/08\/eleccionestelam00121212.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales","datePublished":"2019-01-13T12:50:15+00:00","dateModified":"2019-01-14T10:39:29+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/"},"wordCount":173,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/08\/eleccionestelam00121212.jpg","keywords":["padrones"],"articleSection":["A - TEMPORALES","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/","name":"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/08\/eleccionestelam00121212.jpg","datePublished":"2019-01-13T12:50:15+00:00","dateModified":"2019-01-14T10:39:29+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/08\/eleccionestelam00121212.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/08\/eleccionestelam00121212.jpg","width":645,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/13\/se-vence-plazo-verifica-estas-los-padrones-electorales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Se vence el plazo: verific\u00e1 si est\u00e1s en los padrones electorales"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/34154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=34154"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/34154\/revisions"}],"predecessor-version":[{"id":34155,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/34154\/revisions\/34155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/16748"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=34154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=34154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=34154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}