{"id":34619,"date":"2019-01-17T18:08:04","date_gmt":"2019-01-17T21:08:04","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=34619"},"modified":"2019-01-18T07:58:25","modified_gmt":"2019-01-18T10:58:25","slug":"lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/","title":{"rendered":"Lezcano: \u00abNuestra lista est\u00e1 compuesta por gente de todos los sectores\u00bb"},"content":{"rendered":"<p>\u201cNuestro lista est\u00e1 compuesta por gente que representa a todos los sectores y comprometida con el proyecto pol\u00edtico para resolver los problemas de la ciudad y construir una Santa Rosa de cara al futuro, con obras y desarrollo\u201d. Lo dijo <strong>Jorge Lezcano<\/strong> al hablar de la lista de la que forma parte de cara a las internas del 17 de febrero en las que se definir\u00e1 la postulaci\u00f3n a la candidatura a la intendencia de Santa Rosa en el marco del Frejupa. \u201cNombrarlos es un encanto \u2013remarc\u00f3- porque cuando los presento siempre es con cara de satisfacci\u00f3n. Es un equipo que va a trabajar desde donde lo necesitemos y es importante que la gente lo conozca\u201d, defini\u00f3 antes de pasar a nombrar a cada uno.<\/p>\n<p>En ese sentido, comenz\u00f3 resaltando la figura de su compa\u00f1era de f\u00f3rmula y candidata a concejala Anal\u00eda Torres. \u201cPara construir nuestro proyecto va a haber que modificar ordenanzas y, para ello, Anal\u00eda Torres me parece que tiene que ser la presidenta del Concejo, es una contadora p\u00fablica nacional que tiene una vasta trayectoria en las instituciones intermedias, nunca ha ocupado cargos p\u00fablicos y tiene sobrada capacidad\u201d, dijo.<\/p>\n<p>El segundo candidato es Jos\u00e9 Minetto. \u00abTambi\u00e9n siempre estuvo en instituciones intermedias, ha sido candidato a parlamentario italiano y es un profesor y miembro de la comunidad acad\u00e9mica. Se acerc\u00f3 desinteresadamente a la C\u00e1mara cuando asumimos en el 2015 y hemos trabajado juntos. Cuando lleg\u00f3 el momento de hacer la lista decidimos que nos acompa\u00f1e\u201d, dijo.<\/p>\n<p>El tercer lugar es ocupado por Jorge Rodr\u00edguez. \u00abYa es concejal en este momento, es un reconocido docente y representante del sector de la Educaci\u00f3n T\u00e9cnica\u201d, dijo.<\/p>\n<p>\u00abLorena Guaiquian -continu\u00f3- es una compa\u00f1era para destacar que viene de otra de las l\u00edneas, Convergencia, que nos acompa\u00f1a y que tiene una militancia importante. Buscamos tambi\u00e9n la representaci\u00f3n no solo barrial sectorial y en ello Lorena tiene un trabajo con los pueblos originarios que se suma a su militancia de base\u201d.<\/p>\n<p>La lista contin\u00faa con H\u00e9ctor Julio Colombato. \u00abEs una persona conocida; proviene de la 25, que es otra de las l\u00edneas que nos acompa\u00f1a. Es un hombre de mucha militancia, muy reconocido y con a\u00f1os en el peronismo\u201d, dijo.<\/p>\n<p>\u00abGast\u00f3n Rodr\u00edguez -prosigui\u00f3- es un dirigente barrial que ha militado y ha tenido la decisi\u00f3n de decir \u00b4yo tambi\u00e9n quiero ser\u00b4 participando desde su espacio en la interna y eso tiene un valor porque en vez de criticar y denostar se present\u00f3 y tuvo su caudal de votos. As\u00ed que merec\u00eda un lugar\u201d.<\/p>\n<p>\u201cNatalia Aristoy, en tanto, se fue acercando por lo social, empez\u00f3 a acercarse porque cre\u00eda que ten\u00eda que aportarle a la sociedad desde alg\u00fan lugar\u00bb, dijo. \u00abNo hab\u00eda hecho nunca pol\u00edtica partidaria y se acerc\u00f3 con cuidado desde su participaci\u00f3n en los medios y cuando armamos la lista nos pareci\u00f3 que ten\u00eda que transformar ese compromiso social en pol\u00edticas p\u00fablicas\u201d.<\/p>\n<p>\u00abRita Ballesteros es una militante joven que siempre ha trabajado desde los roperitos comunitarios y siempre con sus ganas de ser que es importante\u201d, agreg\u00f3.<\/p>\n<p>Edgardo Villamil es un comerciante y tambi\u00e9n un militante de a\u00f1os que nunca tuvo un cargo. Siempre colabor\u00f3 ofreci\u00e9ndose para darles clases a los chicos, apoyando en lo que pudiera siempre desde lo social y con compromiso. En tanto, Patricia Berghin ya sabemos de su trabajo y su compromiso social ya que conoce la realidad de los barrios como pocos en la ciudad. Y\u00a0Mat\u00edas Mina viene de otra de las l\u00edneas (NEP), es un joven con muchas intenciones de hacer cosas por la comunidad\u00bb, dijo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNuestro lista est\u00e1 compuesta por gente que representa a todos los sectores y comprometida con el proyecto pol\u00edtico para resolver los problemas de la ciudad y construir una Santa Rosa&hellip;<\/p>\n","protected":false},"author":3,"featured_media":34629,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,319,8],"tags":[817],"class_list":["post-34619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-a-temporales","category-politica","tag-lezcano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lezcano: &quot;Nuestra lista est\u00e1 compuesta por gente de todos los sectores&quot; - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lezcano: &quot;Nuestra lista est\u00e1 compuesta por gente de todos los sectores&quot; - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"\u201cNuestro lista est\u00e1 compuesta por gente que representa a todos los sectores y comprometida con el proyecto pol\u00edtico para resolver los problemas de la ciudad y construir una Santa Rosa&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-17T21:08:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-18T10:58:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/01\/lezcanojorgelista2019-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"874\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Lezcano: \u00abNuestra lista est\u00e1 compuesta por gente de todos los sectores\u00bb\",\"datePublished\":\"2019-01-17T21:08:04+00:00\",\"dateModified\":\"2019-01-18T10:58:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/\"},\"wordCount\":648,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/lezcanojorgelista2019-1.jpeg\",\"keywords\":[\"lezcano\"],\"articleSection\":[\"A - QUE PASA (al costado)\",\"A - TEMPORALES\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/\",\"name\":\"Lezcano: \\\"Nuestra lista est\u00e1 compuesta por gente de todos los sectores\\\" - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/lezcanojorgelista2019-1.jpeg\",\"datePublished\":\"2019-01-17T21:08:04+00:00\",\"dateModified\":\"2019-01-18T10:58:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/lezcanojorgelista2019-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/lezcanojorgelista2019-1.jpeg\",\"width\":874,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/01\\\/17\\\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lezcano: \u00abNuestra lista est\u00e1 compuesta por gente de todos los sectores\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lezcano: \"Nuestra lista est\u00e1 compuesta por gente de todos los sectores\" - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/","og_locale":"es_ES","og_type":"article","og_title":"Lezcano: \"Nuestra lista est\u00e1 compuesta por gente de todos los sectores\" - Diario Textual","og_description":"\u201cNuestro lista est\u00e1 compuesta por gente que representa a todos los sectores y comprometida con el proyecto pol\u00edtico para resolver los problemas de la ciudad y construir una Santa Rosa&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2019-01-17T21:08:04+00:00","article_modified_time":"2019-01-18T10:58:25+00:00","og_image":[{"width":874,"height":555,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/01\/lezcanojorgelista2019-1.jpeg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Lezcano: \u00abNuestra lista est\u00e1 compuesta por gente de todos los sectores\u00bb","datePublished":"2019-01-17T21:08:04+00:00","dateModified":"2019-01-18T10:58:25+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/"},"wordCount":648,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/01\/lezcanojorgelista2019-1.jpeg","keywords":["lezcano"],"articleSection":["A - QUE PASA (al costado)","A - TEMPORALES","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/","name":"Lezcano: \"Nuestra lista est\u00e1 compuesta por gente de todos los sectores\" - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/01\/lezcanojorgelista2019-1.jpeg","datePublished":"2019-01-17T21:08:04+00:00","dateModified":"2019-01-18T10:58:25+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/01\/lezcanojorgelista2019-1.jpeg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/01\/lezcanojorgelista2019-1.jpeg","width":874,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/01\/17\/lezcano-nuestra-lista-esta-compuesta-gente-todos-los-sectores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Lezcano: \u00abNuestra lista est\u00e1 compuesta por gente de todos los sectores\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/34619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=34619"}],"version-history":[{"count":3,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/34619\/revisions"}],"predecessor-version":[{"id":34628,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/34619\/revisions\/34628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/34629"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=34619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=34619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=34619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}