{"id":3720,"date":"2018-04-04T10:39:10","date_gmt":"2018-04-04T10:39:10","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=3720"},"modified":"2018-04-04T16:46:15","modified_gmt":"2018-04-04T16:46:15","slug":"la-justicia-brasilena-define-encarcela-lula-da-silva","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/","title":{"rendered":"La Justicia brasile\u00f1a define si encarcela a Lula da Silva"},"content":{"rendered":"<p>El Supremo Tribunal Federal de Brasil debe decidir hoy sobre un recurso extraordinario del expresidente <strong>Luiz In\u00e1cio Lula da Silva,<\/strong> que fue condenado en enero a 12 a\u00f1os de prisi\u00f3n en segunda instancia en el marco la mecausa sobre corrupci\u00f3n pol\u00edtica \u00abLava Jato\u00bb. La defensa de Lula interpuso ante la m\u00e1xima corte del pa\u00eds un recurso de \u00abhabeas corpus\u00bb pa<strong>ra solicitar que la pena de c\u00e1rcel sea suspendido hasta que el caso sea cerrado en todas las instancias<\/strong>.<!--more--><\/p>\n<p>En caso de que el Supremo rechace el pedido, Lula, que <strong>aspira a ser candidato en las elecciones presidenciales de octubre<\/strong>, podr\u00eda ser encarcelado en los pr\u00f3ximos d\u00edas. Pero el expresidente tiene a\u00fan la posibilidad de llevar su caso a dos instancias m\u00e1s tras la segunda instancia: ante el Superior Tribunal de Justicia, la m\u00e1xima corte del pa\u00eds para asuntos no constitucionales, y finalmente ante el propio Tribunal Supremo.<\/p>\n<p><strong>El caso de Lula amenaza con generar un terremoto pol\u00edtico en Brasil<\/strong>, agitado desde hace a\u00f1os por esc\u00e1ndalos de corrupci\u00f3n. El expresidente es el favorito para ganar un tercer mandato en las elecciones del 7 de octubre, con hasta el 36% de intenci\u00f3n de voto.<\/p>\n<p>El exl\u00edder obrero es muy popular entre las clases m\u00e1s pobres debido a los programas sociales impulsados por sus Gobiernos. Miles de personas salieron a las calles de las principales ciudades brasile\u00f1as este martes para manifestarse tanto en contra como a favor del encarcelamiento.<\/p>\n<p>La Justicia, sin embargo, considera que Lula estuvo implicado en una enorme trama corrupta en torno a la petrolera estatal Petrobras mientras era presidente. Un tribunal de apelaci\u00f3n confirm\u00f3 en enero una condena de 2017 que dictamin\u00f3 que Lula acept\u00f3 la reforma de un apartamento a cambio de favorecer a la constructora OAS en sus negocios con Petrobras.<\/p>\n<p>De cara a las elecciones, la posible candidatura de Lula ser\u00e1 juzgada aparte por el Tribunal Superior Electoral (TSE). La llamada ley de \u00abFicha Limpa\u00bb (\u00abExpediente Limpio\u00bb) impide formalmente al expresidente ser candidato debido a su condena. El tribunal electoral, sin embargo, debe emitir un fallo formal si el PT intenta inscribir oficialmente la candidatura de su l\u00edder, lo que no ocurrir\u00eda hasta agosto.<\/p>\n<p>La fiscal general de Brasil, Raquel Dodge, abog\u00f3 hoy por que la Corte Suprema rechace el recurso de Lula y que permita con ello que el expresidente sea encarcelado. \u00abS\u00f3lo en Brasil la Justicia entiende que s\u00f3lo se puede ejecutar una sentencia despu\u00e9s de que cuatro instancias judiciales confirmen una condena. Esta exageraci\u00f3n destruye el sistema judicial porque una Justicia que tarda es una Justicia que falla\u00bb, lament\u00f3 Dodge en una sesi\u00f3n p\u00fablica de la fiscal\u00eda en Brasilia, un d\u00eda antes de una trascendental fallo judicial para el destino de Lula.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Supremo Tribunal Federal de Brasil debe decidir hoy sobre un recurso extraordinario del expresidente Luiz In\u00e1cio Lula da Silva, que fue condenado en enero a 12 a\u00f1os de prisi\u00f3n&hellip;<\/p>\n","protected":false},"author":3,"featured_media":3722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,7],"tags":[],"class_list":["post-3720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-mundo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Justicia brasile\u00f1a define si encarcela a Lula da Silva - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Justicia brasile\u00f1a define si encarcela a Lula da Silva - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"El Supremo Tribunal Federal de Brasil debe decidir hoy sobre un recurso extraordinario del expresidente Luiz In\u00e1cio Lula da Silva, que fue condenado en enero a 12 a\u00f1os de prisi\u00f3n&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-04T10:39:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-04T16:46:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/04\/luladasilva2121212.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"812\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"La Justicia brasile\u00f1a define si encarcela a Lula da Silva\",\"datePublished\":\"2018-04-04T10:39:10+00:00\",\"dateModified\":\"2018-04-04T16:46:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/\"},\"wordCount\":490,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/luladasilva2121212.jpg\",\"articleSection\":[\"A - QUE PASA (al costado)\",\"MUNDO\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/\",\"name\":\"La Justicia brasile\u00f1a define si encarcela a Lula da Silva - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/luladasilva2121212.jpg\",\"datePublished\":\"2018-04-04T10:39:10+00:00\",\"dateModified\":\"2018-04-04T16:46:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/luladasilva2121212.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/luladasilva2121212.jpg\",\"width\":812,\"height\":500,\"caption\":\"(FILES) In this file photo taken on February 22, 2018 Former Brazilian president Luiz Inacio Lula da Silva gestures during the commemoration of the 38th anniversary of the Workers Party (PT) in Sao Paulo, Brazil. Brazil's top court decided Thursday to defer until April 4 a decision on whether ex-president Luiz Inacio Lula da Silva should face jail if he loses an appeal next week. The Federal Supreme Court, sitting in the capital Brasilia, decided to adjourn its session for two weeks, meaning the leftist former president cannot be jailed before then. \\\/ AFP PHOTO \\\/ Miguel SCHINCARIOL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/04\\\/04\\\/la-justicia-brasilena-define-encarcela-lula-da-silva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Justicia brasile\u00f1a define si encarcela a Lula da Silva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Justicia brasile\u00f1a define si encarcela a Lula da Silva - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/","og_locale":"es_ES","og_type":"article","og_title":"La Justicia brasile\u00f1a define si encarcela a Lula da Silva - Diario Textual","og_description":"El Supremo Tribunal Federal de Brasil debe decidir hoy sobre un recurso extraordinario del expresidente Luiz In\u00e1cio Lula da Silva, que fue condenado en enero a 12 a\u00f1os de prisi\u00f3n&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2018-04-04T10:39:10+00:00","article_modified_time":"2018-04-04T16:46:15+00:00","og_image":[{"width":812,"height":500,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/04\/luladasilva2121212.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"La Justicia brasile\u00f1a define si encarcela a Lula da Silva","datePublished":"2018-04-04T10:39:10+00:00","dateModified":"2018-04-04T16:46:15+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/"},"wordCount":490,"commentCount":0,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/04\/luladasilva2121212.jpg","articleSection":["A - QUE PASA (al costado)","MUNDO"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/","name":"La Justicia brasile\u00f1a define si encarcela a Lula da Silva - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/04\/luladasilva2121212.jpg","datePublished":"2018-04-04T10:39:10+00:00","dateModified":"2018-04-04T16:46:15+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/04\/luladasilva2121212.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/04\/luladasilva2121212.jpg","width":812,"height":500,"caption":"(FILES) In this file photo taken on February 22, 2018 Former Brazilian president Luiz Inacio Lula da Silva gestures during the commemoration of the 38th anniversary of the Workers Party (PT) in Sao Paulo, Brazil. Brazil's top court decided Thursday to defer until April 4 a decision on whether ex-president Luiz Inacio Lula da Silva should face jail if he loses an appeal next week. The Federal Supreme Court, sitting in the capital Brasilia, decided to adjourn its session for two weeks, meaning the leftist former president cannot be jailed before then. \/ AFP PHOTO \/ Miguel SCHINCARIOL"},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/04\/04\/la-justicia-brasilena-define-encarcela-lula-da-silva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La Justicia brasile\u00f1a define si encarcela a Lula da Silva"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/3720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=3720"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/3720\/revisions"}],"predecessor-version":[{"id":3723,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/3720\/revisions\/3723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/3722"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=3720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=3720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=3720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}