{"id":41345,"date":"2019-03-12T09:27:04","date_gmt":"2019-03-12T12:27:04","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=41345"},"modified":"2019-03-12T16:38:08","modified_gmt":"2019-03-12T19:38:08","slug":"1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/","title":{"rendered":"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad"},"content":{"rendered":"<p>La\u00a0<strong>Cooperativa Popular de Electricidad<\/strong> (CPE) decidi\u00f3 tomar una destacable medida: <strong>sin que los adjudicatarios tengan que hacer un tr\u00e1mite<\/strong> previo<strong>, decidi\u00f3 colocar los medidores y dejar conectada la electricidad a las 1009 casas<\/strong> sociales que se inaugurar\u00e1n en los pr\u00f3ximos d\u00edas en la ciudad de Santa Rosa.<\/p>\n<p><strong>\u00abLas casas tendr\u00e1n conectado el servicio de energ\u00eda el\u00e9ctrica, por lo que las familias adjudicatarias solo deber\u00e1n subir la llave de corte al momento de ingresar\u00bb<\/strong>, inform\u00f3 la CPE en un comunicado de prensa.<\/p>\n<p>Desde la fecha de entrega de las llaves, <strong>quedar\u00e1 abierto un plazo de 30 d\u00edas corridos para realizar el tr\u00e1mite administrativo de solicitud de conexi\u00f3n<\/strong>. Vencido ese plazo, las viviendas que no registren titular quedar\u00e1n sin servicio el\u00e9ctrico.<\/p>\n<p>La medida, dijeron desde la CPE, tiende a facilitar el ingreso de las familias a sus viviendas y evitar las aglomeraciones de usuarios en las oficinas de la entidad cooperativa.<\/p>\n<p><strong>Los medidores instalados en las flamantes viviendas tienen estado inicial \u00abcero\u00bb por lo que, independientemente de la fecha de solicitud de conexi\u00f3n, la facturaci\u00f3n considerar\u00e1 el consumo registrado desde ese momento.<\/strong><\/p>\n<p>Los tr\u00e1mites correspondientes se pueden realizar en las oficinas centrales de la CPE, en Ra\u00fal B. D\u00edaz 218, y en el Centro Carlos Lorenzo, en Jos\u00e9 Luro y Per\u00fa, de lunes a viernes, de 7,15 a 14 horas.<\/p>\n<p>Ser\u00e1 titular del servicio el\u00e9ctrico, el adjudicatario o c\u00f3nyuge declarado en el acta de adjudicaci\u00f3n. Para el tr\u00e1mite hay que presentar DNI y acta de adjudicaci\u00f3n, y no se debe registrar deuda. En caso contrario, al momento de la solicitud de conexi\u00f3n, la misma se regularizar\u00e1 mediante un plan de pagos.<\/p>\n<p>Estas viviendas<strong> podr\u00edan entregarse en el mes de abril.<\/strong> Paralelamente, desde el Instituto Provincial Aut\u00e1rquico de Viviendas (Ipav),<strong> se rectific\u00f3<\/strong> una informaci\u00f3n ofrecida por fuentes oficiales ayer: <strong>no se estableci\u00f3 a\u00fan la fecha del sorteo de la ubicaci\u00f3n de las casas de cada familia<\/strong> adjudicataria.\u00a0 La fecha y lugar del sorteo se establecer\u00e1 en los pr\u00f3ximos d\u00edas. Tampoco se determin\u00f3 el d\u00eda del acto de las entregas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0Cooperativa Popular de Electricidad (CPE) decidi\u00f3 tomar una destacable medida: sin que los adjudicatarios tengan que hacer un tr\u00e1mite previo, decidi\u00f3 colocar los medidores y dejar conectada la electricidad a&hellip;<\/p>\n","protected":false},"author":3,"featured_media":9206,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,319,12],"tags":[617,564],"class_list":["post-41345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada-2","category-a-temporales","category-sociedad","tag-casas","tag-ipav"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"La\u00a0Cooperativa Popular de Electricidad (CPE) decidi\u00f3 tomar una destacable medida: sin que los adjudicatarios tengan que hacer un tr\u00e1mite previo, decidi\u00f3 colocar los medidores y dejar conectada la electricidad a&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-12T12:27:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-12T19:38:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/06\/barrionkcontrolpolicial32.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"619\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad\",\"datePublished\":\"2019-03-12T12:27:04+00:00\",\"dateModified\":\"2019-03-12T19:38:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/\"},\"wordCount\":384,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/barrionkcontrolpolicial32.jpg\",\"keywords\":[\"casas\",\"ipav\"],\"articleSection\":[\"A - PORTADA2\",\"A - TEMPORALES\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/\",\"name\":\"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/barrionkcontrolpolicial32.jpg\",\"datePublished\":\"2019-03-12T12:27:04+00:00\",\"dateModified\":\"2019-03-12T19:38:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/barrionkcontrolpolicial32.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/barrionkcontrolpolicial32.jpg\",\"width\":996,\"height\":619},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/12\\\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/","og_locale":"es_ES","og_type":"article","og_title":"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad - Diario Textual","og_description":"La\u00a0Cooperativa Popular de Electricidad (CPE) decidi\u00f3 tomar una destacable medida: sin que los adjudicatarios tengan que hacer un tr\u00e1mite previo, decidi\u00f3 colocar los medidores y dejar conectada la electricidad a&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2019-03-12T12:27:04+00:00","article_modified_time":"2019-03-12T19:38:08+00:00","og_image":[{"width":996,"height":619,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/06\/barrionkcontrolpolicial32.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad","datePublished":"2019-03-12T12:27:04+00:00","dateModified":"2019-03-12T19:38:08+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/"},"wordCount":384,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/06\/barrionkcontrolpolicial32.jpg","keywords":["casas","ipav"],"articleSection":["A - PORTADA2","A - TEMPORALES","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/","name":"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/06\/barrionkcontrolpolicial32.jpg","datePublished":"2019-03-12T12:27:04+00:00","dateModified":"2019-03-12T19:38:08+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/06\/barrionkcontrolpolicial32.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/06\/barrionkcontrolpolicial32.jpg","width":996,"height":619},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/12\/1009-casas-la-cpe-sin-tramite-previo-coloca-los-medidores-conecta-la-electricidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"1009 casas: la CPE, sin tr\u00e1mite previo, coloca los medidores y conecta la electricidad"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/41345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=41345"}],"version-history":[{"count":5,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/41345\/revisions"}],"predecessor-version":[{"id":41364,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/41345\/revisions\/41364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/9206"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=41345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=41345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=41345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}