{"id":42578,"date":"2019-03-21T11:28:21","date_gmt":"2019-03-21T14:28:21","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=42578"},"modified":"2019-03-23T13:56:19","modified_gmt":"2019-03-23T16:56:19","slug":"135-anos-la-rendicion-manuel-namuncura","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/","title":{"rendered":"La rendici\u00f3n de Manuel Namuncur\u00e1"},"content":{"rendered":"<p>El 21 de marzo de 1884, hace exactamente<strong> 135 a\u00f1os<\/strong>, el legendario lonko <strong>Manuel Namuncur\u00e1<\/strong>, quien entre 1873 y 1878 fue jefe de la <strong>Confederaci\u00f3n de las Salinas Grandes<\/strong> en el actual territorio pampeano y del oeste bonaerense, se<strong> rindi\u00f3<\/strong> ante las tropas del Ej\u00e9rcito Argentino. Lo hizo en el <strong>Fort\u00edn \u00d1orqu\u00edn<\/strong>, actual provincia de Neuqu\u00e9n, junto a 240 de sus hombres. <strong>Estaban hambrientos y desarmados.<\/strong> El cacique estaba acompa\u00f1ado adem\u00e1s de cinco capitanejos, dos de sus hermanos y algunas de sus esposas, entre ella la cautiva chilena Rosario Burgos.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/ELKpYt6RK9s\" width=\"720\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Namuncur\u00e1 -cuyo nombre proviene del mapudungun Namunkura, <strong>\u201cGarr\u00f3n de piedra\u201d<\/strong>, de namun, pie o garr\u00f3n, y kura, piedra- hab\u00eda nacido en 1811 en el actual Chile, en la regi\u00f3n del r\u00edo Llaima.<\/p>\n<p>En 1834, con unos 23 a\u00f1os, lleg\u00f3 a tierra argentina a las \u00f3rdenes de su padre, el gran toki Calfucur\u00e1. En el invierno de ese a\u00f1o, Calfucur\u00e1 perge\u00f1\u00f3 una traici\u00f3n a los boroganos -otros boroganos, procedentes de Boroa, Chile- en el paraje Masall\u00e9, en cercan\u00edas de la laguna de Epecu\u00e9n: bajo la excusa de querer comercializar, logr\u00f3 reunir a los boroganos y asesin\u00f3 a unos mil indios y a los caciques Rondeao, Mel\u00edn, Alun y Callvuquirque. Se la conoce como la <strong>\u201cMasacre de Masall\u00e9\u201d<\/strong>.<\/p>\n<p>Calfucur\u00e1 tom\u00f3 poco despu\u00e9s el control de las Salinas Grandes. Namuncur\u00e1, uno de los hijos del llamado \u201cNapole\u00f3n de las pampas\u201d, vivi\u00f3 durante unos 40 a\u00f1os en las tolder\u00edas de Chilihu\u00e9. Fue una de las dos grandes capitales, junto a Leuvuc\u00f3, que se asentaron en la actual provincia. Estaban ubicadas en una zona de m\u00e9danos, a unos 15 kil\u00f3metros al este del actual paraje de Padre Buodo, es decir, al sur de la actual Doblas y al sudoeste de Macach\u00edn.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-42589 \" src=\"http:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/calfucuramapatolderiaschilihuesalinasgrandes1.jpg\" alt=\"\" width=\"638\" height=\"590\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/calfucuramapatolderiaschilihuesalinasgrandes1.jpg 696w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/calfucuramapatolderiaschilihuesalinasgrandes1-300x278.jpg 300w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/calfucuramapatolderiaschilihuesalinasgrandes1-585x541.jpg 585w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/p>\n<p>Namuncur\u00e1 ofici\u00f3 de embajador de su pueblo ante Juan Manuel de Rosas, con el que firm\u00f3 tratados de paz.<\/p>\n<p>En 1854, luego de la batalla de Caseros, fue bautizado en la ciudad de Paran\u00e1, Entre R\u00edos, con el nombre cristiano de Manuel. Se dice que su padrino fue Justo Jos\u00e9 de Urquiza. En esta misma ocasi\u00f3n jur\u00f3 lealtad y cumplimiento a la Constituci\u00f3n Argentina de 1853.<\/p>\n<p>Las cuatro d\u00e9cadas en la zona de las Salinas Grandes de la dinast\u00eda de los Piedra fueron tiempos de negociaciones de paz y de guerra, bajo la presi\u00f3n por el corrimiento de la frontera con los winca. Los incumplimientos de los tratados de paz con el indio por parte del Gobierno de Buenos Aires fueron moneda corriente, lleg\u00f3 a protestar en algunas cartas el propio Namuncur\u00e1.<\/p>\n<p>Particip\u00f3, junto a su padre, de numerosos malones que arrasaron con poblaciones enteras y tomaron, de bot\u00edn, a cientos de colonos y miles y miles de cabeza de ganado.<\/p>\n<p>En 1872, luego de un brutal mal\u00f3n, muri\u00f3 Calfucur\u00e1 en los toldos de Chilihu\u00e9. En la ceremonia del entierro, concurrieron unos 200 caciques de toda la regi\u00f3n.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/iP79co9NLM0\" width=\"753\" height=\"390\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p>La sucesi\u00f3n del gran toki estuvo a punto de generar una guerra civil dentro de su tribu. Manuel tuvo que enfrentar a su hermano primog\u00e9nito, considerado el leg\u00edtimo heredero, Jos\u00e9 Millaquecur\u00e1 -calificado como un \u201cpobre diablo\u201d por Estanislao Zeballos- y a otro hermano, Bernardo Namuncur\u00e1.<\/p>\n<p>Manuel era apoyado por su hermano menor, \u00c1lvaro Reumaycur\u00e1, tambi\u00e9n llamado Albarito o Alvarito Rumay, que durante el gran parlamento realizado para decidir qui\u00e9n ser\u00eda el nuevo jefe se mantuvo cerca con centenares de lanzas. Los ancianos decidieron declarar inv\u00e1lido a Millaquecur\u00e1 y conformaron un triunvirato formado por Manuel, Bernardo y \u00c1lvaro. Para 1875, Manuel ya hab\u00eda desplazado a los otros dos y era el l\u00edder \u00fanico de la tribu.<\/p>\n<p>En 1875, junto a lanzas trasandinas y ranqueles, organiz\u00f3 lo que se conoce el \u00abMal\u00f3n Grande\u00bb. Fue una conjunci\u00f3n de guerreros de Namuncur\u00e1, lanzas trasandinas, ranqueles, indios de Pinc\u00e9n y de Catriel que se sublevaron contra el Gobierno nacional. Un total de 3500 lanzas asolaron los partidos de Azul, Tandil, Olavarr\u00eda, Ju\u00e1rez, Tapalqu\u00e9, Tres Arroyos y Alvear, una extensi\u00f3n de casi 7000 kil\u00f3metros cuadrados. Solamente en Azul dejaron 400 muertos, seg\u00fan cr\u00f3nicas de esa \u00e9poca. Se llevaron 500 cautivos y un total de 300 000 reses. Los indios fueron vencidos el 18 de marzo de 1876 en la batalla de Parag\u00fcil.<\/p>\n<p>El coronel <strong>Nicol\u00e1s Levalle lo desaloj\u00f3 de Chilihu\u00e9 en enero de 1878.<\/strong> En el mes de noviembre del mismo a\u00f1o, avanz\u00f3 en su b\u00fasqueda hasta <strong>Lihuel Calel<\/strong>, donde Namuncur\u00e1 se hab\u00eda asentado, y<strong> forz\u00f3 su fuga hacia la cordillera<\/strong>.<\/p>\n<p>Durante un tiempo pudo escapar de las cacer\u00edas realizadas por el Ej\u00e9rcito nacional y se refugi\u00f3 en la Cordillera de los Andes.<\/p>\n<p>El 21 de marzo de 1884, cuando parte de su familia hab\u00eda sido capturada, finalmente se rindi\u00f3. El comandante Pablo Belisle fue el que lo recibi\u00f3 en el fort\u00edn. <strong>\u201cEs un hombre que tendr\u00e1 cincuenta a\u00f1os m\u00e1s o menos, bien conservado, de cara abierta y despejada que inspira mucha simpat\u00eda\u201d, escribi\u00f3 luego el militar. \u201cTodos los indios lo adoran y se puede considerar entre ellos como un verdadero monarca\u201d.<\/strong><\/p>\n<div id=\"attachment_42583\" style=\"width: 810px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-42583\" class=\"wp-image-42583 size-full\" src=\"http:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura1884.jpg\" alt=\"\" width=\"800\" height=\"577\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura1884.jpg 800w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura1884-300x216.jpg 300w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura1884-768x554.jpg 768w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura1884-585x422.jpg 585w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-42583\" class=\"wp-caption-text\">Namuncur\u00e1 en Buenos Aires, con parte de la comitiva con la que visit\u00f3 a Julio Argentino Roca.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Por su alta investidura, el presidente Julio Argentino Roca hab\u00eda dado expresas instrucciones de respetar su vida, nombrarlo <strong>\u201cCoronel de la Naci\u00f3n\u201d<\/strong> y asignarle <strong>un sueldo mensual<\/strong> con cargo al erario p\u00fablico. Consciente de su importancia, Namuncur\u00e1 pidi\u00f3 de inmediato parlamentar con el mandatario en Buenos Aires. De jefe a jefe.<\/p>\n<p>Luego de un breve paso por Fuerte Roca y Carmen de Patagones, Namuncur\u00e1 fue llevado al puerto de Bah\u00eda Blanca por el padre salesiano Domingo Melanesio. Desde all\u00ed se embarc\u00f3 en el vapor Pomona con destino a Buenos Aires, acompa\u00f1ado de una numerosa comitiva, con la intenci\u00f3n de reunirse con las autoridades, ratificar su rendici\u00f3n y gestionar tierras para su tribu.<\/p>\n<p>El profesor y periodista franc\u00e9s Juan Mariano Larsen escribi\u00f3 para la Revista de la Sociedad Geogr\u00e1fica Argentina los pormenores de su estad\u00eda en la capital. \u201cA bordo del vapor franc\u00e9s Pomona lleg\u00f3 el domingo a Buenos Aires el famoso cacique Namuncur\u00e1, hoy sometido, acompa\u00f1ado de quince indios de su tribu y cuatro mujeres. Vest\u00eda pantal\u00f3n punz\u00f3 con franja dorada, un sobretodo negro bastante largo y usado con presillas doradas y kep\u00ed negro con cinco galones. Casi todos sus acompa\u00f1antes son j\u00f3venes y robustos. Ayer temprano fueron conducidos todos hasta la Casa de Gobierno por el mayor Linares, que los acompa\u00f1\u00f3 desde Patagones\u201d, escribi\u00f3.<\/p>\n<p>La tarde del 26 de junio de 1884 se reuni\u00f3 con Roca. El cacique, relataron los cronistas, lleg\u00f3 muy puntual a la cita. Acompa\u00f1ado de sus hermanos y luego de reunirse primero con el ministro de Guerra, Benjam\u00edn Victorica, fue conducido al despacho del presidente Roca. Si bien uno de sus hermanos hizo de int\u00e9rprete, aquello no era en verdad necesario: Namuncur\u00e1 hablaba espa\u00f1ol.<\/p>\n<div id=\"attachment_42587\" style=\"width: 660px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-42587\" class=\"wp-image-42587 size-full\" src=\"http:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura4.jpg\" alt=\"\" width=\"650\" height=\"734\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura4.jpg 650w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura4-266x300.jpg 266w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura4-585x661.jpg 585w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><p id=\"caption-attachment-42587\" class=\"wp-caption-text\">Namuncur\u00e1, con uniforme militar, flanqueado por dos de sus hijos, Juli\u00e1n (izquierda) y Ceferino (derecha), en 1905.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Se estableci\u00f3 posteriormente en Chimpay, provincia de R\u00edo Negro, donde le dieron a toda la tribu unas pocas hect\u00e1reas. En 1886, fruto de su relaci\u00f3n con la cautiva Rosario Burgos, naci\u00f3 Ceferino Namuncur\u00e1. Es el hijo que fue llevado al Vaticano, donde muri\u00f3 y posteriormente la Iglesia Cat\u00f3lica decidi\u00f3 beatificarlo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-42585 size-full\" src=\"http:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura3.jpg\" alt=\"\" width=\"414\" height=\"470\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura3.jpg 414w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura3-264x300.jpg 264w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/><\/p>\n<p>Namuncur\u00e1 repiti\u00f3 visitas a Buenos Aires en 1886, 1894 y 1897. Alcanz\u00f3 finalmente del Gobierno el otorgamiento de los campos en San Ignacio, en la confluencia del arroyo San Ignacio con el r\u00edo Alumin\u00e9. Falleci\u00f3 en San Ignacio el 31 de Julio de 1908, a los 97 a\u00f1os de edad. Fue enterrado en el cementerio de la colonia. Hoy se desconoce la ubicaci\u00f3n del cuerpo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 21 de marzo de 1884, hace exactamente 135 a\u00f1os, el legendario lonko Manuel Namuncur\u00e1, quien entre 1873 y 1878 fue jefe de la Confederaci\u00f3n de las Salinas Grandes en&hellip;<\/p>\n","protected":false},"author":3,"featured_media":42582,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,2],"tags":[1855],"class_list":["post-42578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada-2","category-cultura","tag-namuncura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La rendici\u00f3n de Manuel Namuncur\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La rendici\u00f3n de Manuel Namuncur\u00e1\" \/>\n<meta property=\"og:description\" content=\"El 21 de marzo de 1884, hace exactamente 135 a\u00f1os, el legendario lonko Manuel Namuncur\u00e1, quien entre 1873 y 1878 fue jefe de la Confederaci\u00f3n de las Salinas Grandes en&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-21T14:28:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-23T16:56:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"770\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"La rendici\u00f3n de Manuel Namuncur\u00e1\",\"datePublished\":\"2019-03-21T14:28:21+00:00\",\"dateModified\":\"2019-03-23T16:56:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/\"},\"wordCount\":1327,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/namuncura2.jpg\",\"keywords\":[\"namuncura\"],\"articleSection\":[\"A - PORTADA2\",\"CULTURA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/\",\"name\":\"La rendici\u00f3n de Manuel Namuncur\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/namuncura2.jpg\",\"datePublished\":\"2019-03-21T14:28:21+00:00\",\"dateModified\":\"2019-03-23T16:56:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/namuncura2.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/namuncura2.jpg\",\"width\":1400,\"height\":770},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/03\\\/21\\\/135-anos-la-rendicion-manuel-namuncura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La rendici\u00f3n de Manuel Namuncur\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La rendici\u00f3n de Manuel Namuncur\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/","og_locale":"es_ES","og_type":"article","og_title":"La rendici\u00f3n de Manuel Namuncur\u00e1","og_description":"El 21 de marzo de 1884, hace exactamente 135 a\u00f1os, el legendario lonko Manuel Namuncur\u00e1, quien entre 1873 y 1878 fue jefe de la Confederaci\u00f3n de las Salinas Grandes en&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2019-03-21T14:28:21+00:00","article_modified_time":"2019-03-23T16:56:19+00:00","og_image":[{"width":1400,"height":770,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura2.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"La rendici\u00f3n de Manuel Namuncur\u00e1","datePublished":"2019-03-21T14:28:21+00:00","dateModified":"2019-03-23T16:56:19+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/"},"wordCount":1327,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura2.jpg","keywords":["namuncura"],"articleSection":["A - PORTADA2","CULTURA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/","name":"La rendici\u00f3n de Manuel Namuncur\u00e1","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura2.jpg","datePublished":"2019-03-21T14:28:21+00:00","dateModified":"2019-03-23T16:56:19+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura2.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/namuncura2.jpg","width":1400,"height":770},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/03\/21\/135-anos-la-rendicion-manuel-namuncura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La rendici\u00f3n de Manuel Namuncur\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/42578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=42578"}],"version-history":[{"count":9,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/42578\/revisions"}],"predecessor-version":[{"id":42892,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/42578\/revisions\/42892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/42582"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=42578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=42578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=42578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}