{"id":448,"date":"2018-03-02T02:54:31","date_gmt":"2018-03-02T02:54:31","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=448"},"modified":"2018-03-02T20:04:48","modified_gmt":"2018-03-02T20:04:48","slug":"448","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/","title":{"rendered":"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela"},"content":{"rendered":"<div class=\"itemIntroText\">Boca Juniors igual\u00f3 0 a 0 en su visita a Alianza Lima, de Per\u00fa, en el arranque del Grupo 8 de la Copa Libertadores.<\/div>\n<div><\/div>\n<p><!--more--><\/p>\n<div class=\"itemIntroText\">\n<p>El encuentro se disput\u00f3 en el estadio Nacional de Lima, con el arbitraje del uruguayo Daniel Fedorczuk.<\/p>\n<p>Por el mismo grupo del xeneize, Palmeiras, de Brasil gole\u00f3 3 a 0 a Junior de Barranquilla con goles de Bruno Corsini (2) y Miguel Borja.<\/p>\n<p><strong>Perdi\u00f3 el Rojo<\/strong><br \/>\nIndependiente no pudo superar su debut en la Copa Libertadores, a la que volvi\u00f3 luego de seis a\u00f1os, y perdi\u00f3 como visitante por 1 a 0 frente a Deportivo Lara de Venezuela, en el estadio Metropolitano de la ciudad de Barqu\u00edsimeto, por la primera fecha del Grupo 7 de la Copa Libertadores.<\/p>\n<p>Carlos Sierra, a los 11 minutos, marc\u00f3 el gol del elenco anfitri\u00f3n.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Boca Juniors igual\u00f3 0 a 0 en su visita a Alianza Lima, de Per\u00fa, en el arranque del Grupo 8 de la Copa Libertadores.<\/p>\n","protected":false},"author":2,"featured_media":449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,3],"tags":[22,21],"class_list":["post-448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-noticia","category-deportes","tag-alianza","tag-tevez"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Boca Juniors igual\u00f3 0 a 0 en su visita a Alianza Lima, de Per\u00fa, en el arranque del Grupo 8 de la Copa Libertadores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-02T02:54:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-02T20:04:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/bocaalianzalimatevez43434.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio Romano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Romano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/\"},\"author\":{\"name\":\"Sergio Romano\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/523499e72392084bbaa07d9918058135\"},\"headline\":\"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela\",\"datePublished\":\"2018-03-02T02:54:31+00:00\",\"dateModified\":\"2018-03-02T20:04:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/\"},\"wordCount\":135,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/bocaalianzalimatevez43434.jpg\",\"keywords\":[\"alianza\",\"tevez\"],\"articleSection\":[\"A - ES NOTICIA (van abajo)\",\"DEPORTES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/\",\"name\":\"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/bocaalianzalimatevez43434.jpg\",\"datePublished\":\"2018-03-02T02:54:31+00:00\",\"dateModified\":\"2018-03-02T20:04:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/bocaalianzalimatevez43434.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/bocaalianzalimatevez43434.jpg\",\"width\":1200,\"height\":833},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2018\\\/03\\\/02\\\/448\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/523499e72392084bbaa07d9918058135\",\"name\":\"Sergio Romano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g\",\"caption\":\"Sergio Romano\"},\"sameAs\":[\"http:\\\/\\\/www.diariotextual.com\"],\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/","og_locale":"es_ES","og_type":"article","og_title":"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela - Diario Textual","og_description":"Boca Juniors igual\u00f3 0 a 0 en su visita a Alianza Lima, de Per\u00fa, en el arranque del Grupo 8 de la Copa Libertadores.","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2018-03-02T02:54:31+00:00","article_modified_time":"2018-03-02T20:04:48+00:00","og_image":[{"width":1200,"height":833,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/bocaalianzalimatevez43434.jpg","type":"image\/jpeg"}],"author":"Sergio Romano","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Sergio Romano","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/"},"author":{"name":"Sergio Romano","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/523499e72392084bbaa07d9918058135"},"headline":"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela","datePublished":"2018-03-02T02:54:31+00:00","dateModified":"2018-03-02T20:04:48+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/"},"wordCount":135,"commentCount":0,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/bocaalianzalimatevez43434.jpg","keywords":["alianza","tevez"],"articleSection":["A - ES NOTICIA (van abajo)","DEPORTES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/","name":"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/bocaalianzalimatevez43434.jpg","datePublished":"2018-03-02T02:54:31+00:00","dateModified":"2018-03-02T20:04:48+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/bocaalianzalimatevez43434.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2018\/03\/bocaalianzalimatevez43434.jpg","width":1200,"height":833},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2018\/03\/02\/448\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Boca empat\u00f3 en Per\u00fa; Independiente cay\u00f3 en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/523499e72392084bbaa07d9918058135","name":"Sergio Romano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/558f03f407fa3accd9dabd3c363c971a21b2b44ce0fe39bb24a92ac5472808b8?s=96&d=mm&r=g","caption":"Sergio Romano"},"sameAs":["http:\/\/www.diariotextual.com"],"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=448"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/448\/revisions"}],"predecessor-version":[{"id":451,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/448\/revisions\/451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/449"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}