{"id":54141,"date":"2019-06-29T19:16:55","date_gmt":"2019-06-29T22:16:55","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=54141"},"modified":"2019-06-30T10:02:43","modified_gmt":"2019-06-30T13:02:43","slug":"alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/","title":{"rendered":"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas"},"content":{"rendered":"<p>Alberto Fern\u00e1ndez se comprometi\u00f3, en caso de llegar a Casa Rosada, a volver a financiar la construcci\u00f3n de unas mil viviendas sociales por a\u00f1o a La Pampa. Lo dijo el gobernador Carlos Verna este s\u00e1bado, a trav\u00e9s de un tuit.<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p dir=\"ltr\" lang=\"es\">Con <a href=\"https:\/\/twitter.com\/alferdez?ref_src=twsrc%5Etfw\">@alferdez<\/a> y <a href=\"https:\/\/twitter.com\/CFKArgentina?ref_src=twsrc%5Etfw\">@CFKArgentina<\/a> tambi\u00e9n hablamos de la recuperaci\u00f3n del sistema de fondos nacionales para viviendas sociales. Las familias pampeanas van a poder seguir cumpliendo el sue\u00f1o de su casa propia. Hoy, solo contamos con recursos provinciales para esta operatoria. <a href=\"https:\/\/t.co\/BMCGcRfh68\">pic.twitter.com\/BMCGcRfh68<\/a><\/p>\n<p>\u2014 Carlos Verna (@VernaGobernador) <a href=\"https:\/\/twitter.com\/VernaGobernador\/status\/1145089897100992512?ref_src=twsrc%5Etfw\">29 de junio de 2019<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>\u00abHablamos de la recuperaci\u00f3n del sistema de fondos nacionales para viviendas sociales. Las familias pampeanas van a poder seguir cumpliendo el sue\u00f1o de su casa propia. Hoy, solo contamos con recursos provinciales para esta operatoria\u00bb, expres\u00f3.<\/p>\n<p>Hasta 2015, en La Pampa se constru\u00edan unas mil casas sociales con fondos nacionales. Pero con la llegada de Mauricio Macri, esa financiaci\u00f3n se cort\u00f3 abruptamente. Las \u00faltimas casas entregadas en Santa Rosa hab\u00edan sido licitadas en el Gobierno de Cristina Fern\u00e1ndez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alberto Fern\u00e1ndez se comprometi\u00f3, en caso de llegar a Casa Rosada, a volver a financiar la construcci\u00f3n de unas mil viviendas sociales por a\u00f1o a La Pampa. Lo dijo el&hellip;<\/p>\n","protected":false},"author":3,"featured_media":42752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,12],"tags":[],"class_list":["post-54141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada-2","category-sociedad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"Alberto Fern\u00e1ndez se comprometi\u00f3, en caso de llegar a Casa Rosada, a volver a financiar la construcci\u00f3n de unas mil viviendas sociales por a\u00f1o a La Pampa. Lo dijo el&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-29T22:16:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-30T13:02:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/casas1009mudanza2019-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"657\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas\",\"datePublished\":\"2019-06-29T22:16:55+00:00\",\"dateModified\":\"2019-06-30T13:02:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/\"},\"wordCount\":196,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/casas1009mudanza2019-1.jpg\",\"articleSection\":[\"A - PORTADA2\",\"SOCIEDAD\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/\",\"name\":\"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/casas1009mudanza2019-1.jpg\",\"datePublished\":\"2019-06-29T22:16:55+00:00\",\"dateModified\":\"2019-06-30T13:02:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/casas1009mudanza2019-1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/casas1009mudanza2019-1.jpg\",\"width\":1000,\"height\":657},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/06\\\/29\\\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/","og_locale":"es_ES","og_type":"article","og_title":"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas - Diario Textual","og_description":"Alberto Fern\u00e1ndez se comprometi\u00f3, en caso de llegar a Casa Rosada, a volver a financiar la construcci\u00f3n de unas mil viviendas sociales por a\u00f1o a La Pampa. Lo dijo el&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2019-06-29T22:16:55+00:00","article_modified_time":"2019-06-30T13:02:43+00:00","og_image":[{"width":1000,"height":657,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/casas1009mudanza2019-1.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas","datePublished":"2019-06-29T22:16:55+00:00","dateModified":"2019-06-30T13:02:43+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/"},"wordCount":196,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/casas1009mudanza2019-1.jpg","articleSection":["A - PORTADA2","SOCIEDAD"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/","name":"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/casas1009mudanza2019-1.jpg","datePublished":"2019-06-29T22:16:55+00:00","dateModified":"2019-06-30T13:02:43+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/casas1009mudanza2019-1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/03\/casas1009mudanza2019-1.jpg","width":1000,"height":657},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/06\/29\/alberto-fernandez-prometio-la-pampa-devolver-los-fondos-las-viviendas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Alberto Fern\u00e1ndez prometi\u00f3 a La Pampa devolver los fondos para las viviendas"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/54141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=54141"}],"version-history":[{"count":2,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/54141\/revisions"}],"predecessor-version":[{"id":54143,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/54141\/revisions\/54143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/42752"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=54141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=54141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=54141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}